{"id":8094,"date":"2015-05-15T23:59:27","date_gmt":"2015-05-15T21:59:27","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=8094"},"modified":"2018-02-06T14:54:55","modified_gmt":"2018-02-06T13:54:55","slug":"in-den-ring-steigen-the-outbreaks","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/","title":{"rendered":"In den Ring steigen (The Outbreaks)"},"content":{"rendered":"<div id=\"attachment_8116\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" aria-describedby=\"caption-attachment-8116\" class=\"wp-image-8116 size-medium\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight.jpg?resize=300%2C247&#038;ssl=1\" alt=\"In den Ring steigen (The Outbreaks)\" width=\"300\" height=\"247\" \/><\/a><p id=\"caption-attachment-8116\" class=\"wp-caption-text\">The big arena fight<\/p><\/div>\n<p style=\"text-align: justify;\">In den Ring steigen (The Outbreaks)<\/p>\n<p style=\"text-align: justify;\">In dem Keller der Taverne, zum einbeinigen Basilisken, schien das eigentliche Leben der Taverne, abseits im Schatten der Stadt stattzufinden. Der Geruch von Schwei\u00df, Blut und anderen Ger\u00fcchen stiegen hier, w\u00e4hrend des Abstiegs in die Nase. Neugierig erkundeten die &#8222;Neuen&#8220; die Umgebung der Arena, die sich mit ca 10 Metern H\u00f6he von den anderen R\u00e4umen abhob. Der Keller schien gut geplant worden zu sein, um etlichen Zuschauern Platz bieten zu k\u00f6nnen. Allein der blutbeschmierte Ring zeugte von dem was sie heute abend erwarten w\u00fcrde, noch war aber noch Zeit bis dahin, die der ein oder andere in der Gruppe unterschiedlich nutzte. W\u00e4hrend Thoringal und auch Totes Pferd sich nach einer Arbeit, in einer nahen gelegenen Schmiede umsahen und leider entt\u00e4uscht wurden, da die Auftragslage in der hiesigen Schmiede, Aufgrund des Ausbleibens\u00a0 der Eisenerzlieferung vom Festland, zwar gegeben war, aber der Mangel des Rohstoffes keine Alternativen bot, die Esse unter Feuer zu nehmen und die Auftr\u00e4ge abzuarbeiten. Dabei fiel bei Thoringal ein Name, den er sp\u00e4ter wieder h\u00f6ren w\u00fcrde, Grim Elder Jorgend, ein H\u00e4ndler der anscheinend alles besorgen konnte was das Herz beliebte, nat\u00fcrlich nur zu moderaten Preisen. Die Interessen der am Abend in das sp\u00e4rliche Licht abtauchenden Charaktere waren unterschiedlicher Natur, w\u00e4hrend die Einen einen Vertrag zu einem Kampf unterschrieben, bei einen gewissen goblinoidischen Buchmacher, mit dem Namen: Hickskrix, wollten die anderen wetten, oder mehr Informationen \u00fcber Mintarn bekommen. Die Gesellschaft die sich dort aufhielt war alles andere als allt\u00e4glich, unter anderem ein Dunkelelf, ein komisch aussehender buckliger, ein\u00e4ugiger, alter Goblin, ein kristallines Wesen, ein Steingolem, diverse Robentr\u00e4ger die, obwohl die Magie beim Kampf verboten war, hier Anwesend waren, aber auch viele alte und gebrechlich aussehende Leute. Wer in der Arena k\u00e4mpfen w\u00fcrde, war schwer einzusch\u00e4tzen.<\/p>\n<div id=\"attachment_8506\" style=\"width: 254px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/fight.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" aria-describedby=\"caption-attachment-8506\" class=\"size-medium wp-image-8506\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/fight.jpg?resize=244%2C300&#038;ssl=1\" alt=\"Grumpfs fight\" width=\"244\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/fight.jpg?resize=244%2C300&amp;ssl=1 244w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/fight.jpg?w=640&amp;ssl=1 640w\" sizes=\"(max-width: 244px) 100vw, 244px\" \/><\/a><p id=\"caption-attachment-8506\" class=\"wp-caption-text\">Grumpfs fight<\/p><\/div>\n<p style=\"text-align: justify;\">Grumpf betrachtete seine\u00a0 zu F\u00e4usten geballten H\u00e4nde Die Krusten getrockneten Blutes f\u00e4rbtenseine Bandagen dunkel. Bis jetzt war ja alles wie geplant gelaufen. Die einzige Herausforderung in der ersten Runde war seine Niederlage im zweiten Kampf echt aussehen zu lassen. Sein Gegner hatte ihm kaum etwas entzgegenzusetzten. Auch die Neulinge schlugen sich gut. Sandrose, wie die Halb-Riesin sich vorgestellt hatte, traff in der ersten Runde auf einen anderen riesen Typen, konnte ihn aber in zwei K\u00e4mpfen niederringen und sich damit f\u00fcr die n\u00e4chste Runde qualifizieren. Thoringal stand in seinen ersten K\u00e4mpfen einem Lanzmann gegen\u00fcber. Die zwei Zwerge lieferten sich eine Pr\u00fcgelei der Sonderklasse, die Thoringal nach einem 0:1 R\u00fcckstand aber doch noch mit 2:1 f\u00fcr sich entscheiden konnte. W\u00e4hrend Teranja in beeindruckender Art und Weise eine junge Dunkelelfe zurechtwies, war Cains Performance nahezu lausig. Doch er war ein alter Hase in dem Gesch\u00e4ft und auch derjenige der im Finalkampf auf Grumpf warten w\u00fcrde&#8230;\u00a0 Grumpf lauschte den Ger\u00e4uschen die von der Arena herein in das dunke Hinterzimmer der K\u00e4mpfer drangen. Er kannte die kontrollierten Kampfschreie des alten Mannes. Und so wie es sich anh\u00f6rte war er nun richtig in Fahrt gekommen. Der dumpfe Hall der Schl\u00e4ge wurde nur vom Teranjas St\u00f6hnen unterbrochen. Und das nachdem er Sie so zugerichtet hatte. Sie war schnell, das musste man ihr lassen.\u00a0 Aber er war fast dreimal so schwer wie sie und er war ein Ork. Bei den Menschen gab es ja gewisse Regeln f\u00fcr den Umgang mit seinen Mitmenschen. Da ist zum einen auch die, das Mann Frauen nicht schlagen soll. Ein Grinsen machte sich auf Grumpfs Gesicht breit. Wie gut das er kein Mensch war! Denn als der Gong f\u00fcr die erste Runde ert\u00f6nt schlug er ihr einfach so hart er konnte mitten ins Gesicht. Das Ergebinss waren drei ausgschlagene Schneidez\u00e4hne und eine verdutzte Teranja. Ein eintscheidender Vorteil gegen die flinke K\u00e4mpferin. Einen den er auszunutzen wusste und gleich hart nachsetzte. Am Ende des Kampfes hatte er Teranjas h\u00fcbsches Gesicht zu Brei geschlagen. Da w\u00fcrden die Heiler alle H\u00e4nde voll zu tun haben. Und so wie es sich jetzt anh\u00f6rte, sprang Cain auch nicht ziemperlich mit ihr um. Teranjas Schmerzensschreie verritten das Cain einen Hebel angesetzt hatte und den Kampf ein f\u00fcr alle mal beenden wollte. Das dumpfe Knacken und das Raunen der Menge lies vermuten, das wohl nicht Teranja selbst, aber daf\u00fcr ihr Ellbogengelenk nachgegeben hatte. Ihre Schreie \u00fcbert\u00f6hnten sogar den Beifall der Menge&#8230;armes kleines Ding. Aber jetzt war es wieder an ihm. Nun hie\u00df es wie erwartet Grumpf gegen Cain. Die Wiederholung von gestern Nacht. Einem Kampf den er noch sehr schmerzhaft in Erinnerung hatte. Und so erhob er sich und tratt langsam und konzentriert in den Schein der Fackeln.<\/p>\n<div id=\"attachment_8126\" style=\"width: 232px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/d3-cain.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" aria-describedby=\"caption-attachment-8126\" class=\"size-medium wp-image-8126\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/d3-cain.jpg?resize=222%2C300&#038;ssl=1\" alt=\"Cain\" width=\"222\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/d3-cain.jpg?resize=222%2C300&amp;ssl=1 222w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/d3-cain.jpg?resize=757%2C1024&amp;ssl=1 757w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/d3-cain.jpg?w=850&amp;ssl=1 850w\" sizes=\"(max-width: 222px) 100vw, 222px\" \/><\/a><p id=\"caption-attachment-8126\" class=\"wp-caption-text\">Cain<\/p><\/div>\n<p style=\"text-align: justify;\">Teranja wurde mit schmerzverzerrtem Gesicht aus dem Ring geschleift in dem Cain schon grinsend wartete&#8230; Nun ist es also wieder so weit alter Freund. 150 kg Muskeln treffen auf \u00fcber 50 Jahre Erfahrung.<\/p>\n<p style=\"text-align: justify;\">Als die zwei sich in voller Konzentration gegen\u00fcberstanden und nur darauf warteten bis der Gong die erste Runde einl\u00e4utete, fetzte pl\u00f6tzlich Blinker, diese kleine, h\u00e4ssliche Nervens\u00e4ge dicht gefolgt von Totes Pferd quer durch den Ring. Was machte dieser Kobold, Goblin, was auch immer hier, wunderte sich Grumpf, hatte er ihn doch zuvor in eine der Kisten gesperrt. Er hatte sich sogar extra eine mit nem Haufen unbequemem Zeugs drin ausgesucht. Wie sich Herausstellte handelte es sich bei dem Zeug um das gesammelte Waffenarsenal und Werkzeug von Totes Pferd und Blinker der Rotzl\u00f6ffel hatte dieses verwendet um sich aus der Kiste zu befreien. Der riesige Elf, der sich bis jetzt um Grumpfs Wetteins\u00e4tze gek\u00fcmmert und ihn\u00a0 heute Nacht schon zu einem reichen Ork gemacht hatte, hatte nun aber anscheinend nur mehr sein Werkzeug im Kopf, das Blinker triumphierend in H\u00e4nden hielt. Das war der Entscheidende Kampf und die Wetten mussten vor dem Gong gesetzt sein&#8230; Das alles war nicht gut f\u00fcr seine Nerven, und so lies er Cain kurzerhand mit\u00a0dessen Verwunderung allein\u00a0im Ring zur\u00fcck und st\u00fcrzte Blinker und dem Elfen nach in das kleine Hinterzimmer, das den Durchgang ins Unterreich beherbergte. Blinker der flinke kleine Rattenjunge, flog schon die Stiegen hinab, wo er das erbeutete Werkezeug in einer auf halbem Weg, direkt am Abgang stehenden Kiste ablud und seinen Weg nach unten fortsetzte. Als Totes Pferd allerdings\u00a0sichtlich genervt sein Hab und Gut wieder aus der Kiste holen wollte schnappte diese pl\u00f6tzlich nach ihm und sein Bein schien an einer gallertartigen Sicht festzukleben. Grumpf der hielt es f\u00fcr eine gute Idee mit einem m\u00e4chtigen Satz auf die Kiste zu springen, was aber nur zur folge hatte das nun nicht nur ein Elf an der Kiste, sondern nun auch ein Ork auf deren Deckel klebte. Auch als Sandrose und Thoringal, die den Tumult bemerkt haben d\u00fcrften,\u00a0zu Hilfe geeilt kamen schien eine Befreiung von der kleberigen Kiste unm\u00f6glich. Erst als Kandogan, Tazlogg und Darren, der anscheinend etwas von dem Hexenwerk verstand, auftauchten konnten die zwei Recken aus ihrer misslichen Lage befreit werde und die Kiste zerfiel samt der Gallerte zu staub.<\/p>\n<div id=\"attachment_8148\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/gelatinous_cube.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" aria-describedby=\"caption-attachment-8148\" class=\"size-medium wp-image-8148\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/gelatinous_cube.png?resize=300%2C200&#038;ssl=1\" alt=\"gelatinous cube\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/gelatinous_cube.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/gelatinous_cube.png?w=482&amp;ssl=1 482w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-8148\" class=\"wp-caption-text\">gelatinous cube<\/p><\/div>\n<p style=\"text-align: justify;\">Als Grumpf zur\u00fcck in die Arena kam sa\u00df Cain im Schneidersitz in der Mitte des Rings. In nahezu meditativer Pose schien der alte Mann auf seinen Gegner zu warten. Er war die Ruhe selbst. Grumpf z\u00f6gerte keine Sekunde und st\u00fcrzte sich zur Freude der ungeduldigen Menge mit ohrenbet\u00e4ubendem Gebr\u00fcll auf seinen Gegner. Er f\u00fchlte die Wellen der Wut, die wie Wogen aus Feuer in seinen Muskeln brannten. Er setzte alle Kraft in seinen ersten Schlag. Erst jetzt \u00f6ffnete der noch immer regungslos dasitzende Cain sein Augen. Und auf seinem Gesicht zeichnete sich ein L\u00e4cheln ab&#8230;<\/p>\n<p style=\"text-align: justify;\">Er hatte wieder ordentlich Pr\u00fcgel eingesteckt, und sein zugeschwollenes Auge und die blutende Nase w\u00fcrden ihn noch eine Zeit lang daran erinnern. Doch diesmal hatte auch Cain sein Fett abbekommen. Nach einem pr\u00e4zisen Schlaghagel des Meisters bekam Grumpf den erfahren K\u00e4mpfer endlich zu fassen. Das war seine Chance und er setzte alles ein was er hatte und rang den alten Mann zu Boden. Und die Regeln war hierbei sehr klar, wer seinen Gegner zu Boden zwingt, gewinnt und damit hat Grumpf das Turnier f\u00fcr sich entschieden. Wenig sp\u00e4ter sa\u00df er schon mit Darren im Zimmer des dunkelelfischen Buchmachers und stritt mit dem Veranstalter ums Preisgeld. Wollten sie ihm doch glatt,\u00a0Stiefel und ein paar Handschuhe andrehen. Ihm, der sein Leben lang noch keine Schuhe getragen hatte. Und was sollte er mit Handschuhen? Genervt verstaute der Drow die Gegenst\u00e4nde wieder in einer Kiste an der Wand und holte einen alten, schweren Lederg\u00fcrtel heraus. &#8222;G\u00fcrtel wirst du doch wohl tragen Ork?&#8220; Er war zwar nicht sch\u00f6n, aber er passte. Au\u00dferdem f\u00fchlte er eine komische St\u00e4rke durch seine Glieder str\u00f6men als er sich den schweren G\u00fcrtel anlegte. Ja, damit konnte er arbeiten. Grinsend h\u00f6rte er sich an, was da noch so kam, was allerdings nur dazu f\u00fchrte das er zum erstaunen der anderen Anwesenden in schallendes Gel\u00e4chter ausbrach. &#8222;Was??? Hauptmann der Wache? Ich? Aber sicher nicht!!!!&#8220; Jetzt wollten sie ihm doch tats\u00e4chlich einen Posten als Hauptmann der Festungswachen anbieten? Da h\u00e4tte er ja mit den zu kleinen Stiefeln mehr anfangen k\u00f6nnen. Er war in einer Autorit\u00e4ren Struktur wie die der Wache eine war\u00a0ungef\u00e4hr genauso fehl am Platz wie Totes Pferd im Kloster oder der Zwerg auf nem Magierkonzil. Polternd fiel die\u00a0beschlagene T\u00fcr des Wettb\u00fcros ins Schloss. Grumpf konnte bei dem Gedanken daran die Wache anzuf\u00fchren wirklich nur den Kopf sch\u00fctteln.\u00a0Obwohl, wenn er sich vorstellte was die\u00a0S\u00e4cke von der Wache f\u00fcr Augen machen w\u00fcrden wenn er da pl\u00f6tzlich als ihr Chef auftauchen w\u00fcrde&#8230; Der Spa\u00df w\u00e4r die Sache schon fast wieder wert, zumindest f\u00fcr ein paar St\u00fcndchen, k\u00f6nnte er seinen Schabernack mit diesen Affen treiben. Nachdenklich blickte er hinter sich auf die schwere T\u00fcr. &#8222;Ach, was solls. Jetzt brauch ich erstmal was zu trinken&#8220; dachte er bei sich und machte sich auf den Weg in die Taverne.<\/p>\n<p style=\"text-align: justify;\">In einem Raum, abgeschirmt vom Schankraum, trafen sich Totes Pferd, Thoringal und der von seinem &#8222;Ausflug zum Turm&#8220; zur\u00fcckgekehrte Strave. Strave erz\u00e4hlte ihnen von dem Erlebnis in dem Turm und von der Herausforderung mit dem Berater von Tarnheel Embuirhan,\u00a0Bharandas Zhan der nach laut Auskunft von der Erscheinung von Szentarr Ravin, ein Nekromant sei der seine Finger tief im Spiel mit h\u00e4tte. Kein Wunder das keine ausgesandte Gruppe je widergekehrt war. Dazu kam noch die Information, das Mintarn in den Wirtschaftkrieg zwischen Tiefwasser \/ Baldurs Gate und Luskan heineingezogen w\u00fcrde. Die Zeiten sahen also nicht gut aus in Mintarn. Strave erkundigte sich, da er wusste welche Belohnung es bei dem &#8222;Wettbewerb&#8220; gab, nach dem Gewinner. Dabei fiel der Name Grumpf.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den Ring steigen (The Outbreaks) In dem Keller der Taverne, zum einbeinigen Basilisken, schien das eigentliche Leben der Taverne, abseits im Schatten der Stadt stattzufinden. Der Geruch von Schwei\u00df, Blut und anderen Ger\u00fcchen stiegen hier, w\u00e4hrend des Abstiegs in die Nase. Neugierig erkundeten die &#8222;Neuen&#8220; die Umgebung der Arena, die sich mit ca 10 [&hellip;]<\/p>\n","protected":false},"author":74,"featured_media":8116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[338],"tags":[378],"class_list":["post-8094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe8","tag-1-mirtul-1382-2-mirtul-1382"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In den Ring steigen (The Outbreaks) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In den Ring steigen (The Outbreaks) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"In den Ring steigen (The Outbreaks) In dem Keller der Taverne, zum einbeinigen Basilisken, schien das eigentliche Leben der Taverne, abseits im Schatten der Stadt stattzufinden. Der Geruch von Schwei\u00df, Blut und anderen Ger\u00fcchen stiegen hier, w\u00e4hrend des Abstiegs in die Nase. Neugierig erkundeten die &#8222;Neuen&#8220; die Umgebung der Arena, die sich mit ca 10 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-15T21:59:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-06T13:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"412\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Grumpf (Hemi)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Grumpf (Hemi)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/\"},\"author\":{\"name\":\"Grumpf (Hemi)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/f1286e226d927ae2cff20b60385f352b\"},\"headline\":\"In den Ring steigen (The Outbreaks)\",\"datePublished\":\"2015-05-15T21:59:27+00:00\",\"dateModified\":\"2018-02-06T13:54:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/\"},\"wordCount\":1872,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1\",\"keywords\":[\"1.Mirtul 1382 - 2.Mirtul 1382\"],\"articleSection\":[\"The Outbreaks (old)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/\",\"name\":\"In den Ring steigen (The Outbreaks) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1\",\"datePublished\":\"2015-05-15T21:59:27+00:00\",\"dateModified\":\"2018-02-06T13:54:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1\",\"width\":500,\"height\":412,\"caption\":\"The big arena fight\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe8\\\/in-den-ring-steigen-the-outbreaks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In den Ring steigen (The Outbreaks)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/f1286e226d927ae2cff20b60385f352b\",\"name\":\"Grumpf (Hemi)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8cf00ed6085ab014a9c75054ec8530a00b179364a62c369da93e70c2a4a36fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8cf00ed6085ab014a9c75054ec8530a00b179364a62c369da93e70c2a4a36fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8cf00ed6085ab014a9c75054ec8530a00b179364a62c369da93e70c2a4a36fe?s=96&d=mm&r=g\",\"caption\":\"Grumpf (Hemi)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/hemi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In den Ring steigen (The Outbreaks) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/","og_locale":"de_DE","og_type":"article","og_title":"In den Ring steigen (The Outbreaks) - RPG-Berlin.de","og_description":"In den Ring steigen (The Outbreaks) In dem Keller der Taverne, zum einbeinigen Basilisken, schien das eigentliche Leben der Taverne, abseits im Schatten der Stadt stattzufinden. Der Geruch von Schwei\u00df, Blut und anderen Ger\u00fcchen stiegen hier, w\u00e4hrend des Abstiegs in die Nase. Neugierig erkundeten die &#8222;Neuen&#8220; die Umgebung der Arena, die sich mit ca 10 [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2015-05-15T21:59:27+00:00","article_modified_time":"2018-02-06T13:54:55+00:00","og_image":[{"width":500,"height":412,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1","type":"image\/jpeg"}],"author":"Grumpf (Hemi)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Grumpf (Hemi)","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/"},"author":{"name":"Grumpf (Hemi)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/f1286e226d927ae2cff20b60385f352b"},"headline":"In den Ring steigen (The Outbreaks)","datePublished":"2015-05-15T21:59:27+00:00","dateModified":"2018-02-06T13:54:55+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/"},"wordCount":1872,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1","keywords":["1.Mirtul 1382 - 2.Mirtul 1382"],"articleSection":["The Outbreaks (old)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/","name":"In den Ring steigen (The Outbreaks) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1","datePublished":"2015-05-15T21:59:27+00:00","dateModified":"2018-02-06T13:54:55+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1","width":500,"height":412,"caption":"The big arena fight"},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe8\/in-den-ring-steigen-the-outbreaks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"In den Ring steigen (The Outbreaks)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/f1286e226d927ae2cff20b60385f352b","name":"Grumpf (Hemi)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d8cf00ed6085ab014a9c75054ec8530a00b179364a62c369da93e70c2a4a36fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8cf00ed6085ab014a9c75054ec8530a00b179364a62c369da93e70c2a4a36fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8cf00ed6085ab014a9c75054ec8530a00b179364a62c369da93e70c2a4a36fe?s=96&d=mm&r=g","caption":"Grumpf (Hemi)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/hemi\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/05\/the_big_arena_fight-e1431840082899.jpg?fit=500%2C412&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-26y","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/8094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=8094"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/8094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/8116"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=8094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=8094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=8094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}