{"id":6967,"date":"2015-03-07T21:49:45","date_gmt":"2015-03-07T20:49:45","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=6967"},"modified":"2018-02-06T16:24:44","modified_gmt":"2018-02-06T15:24:44","slug":"raetzel-ueber-raetzel","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/","title":{"rendered":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft wp-image-6976 size-medium\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?resize=194%2C300&#038;ssl=1\" alt=\"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)\" width=\"194\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?resize=194%2C300&amp;ssl=1 194w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?w=540&amp;ssl=1 540w\" sizes=\"(max-width: 194px) 100vw, 194px\" \/><\/a>R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)<\/p>\n<p>In der Nacht vom 16.Tarsakh zum 17. Tarsakh 1382 wurde die Gruppe im Gutshaus des B\u00fcrgermeisters von 2 Geistern angegriffen. Das etwas Gr\u00f6\u00dfere riss einen kleinen Teil von Brotors Lederg\u00fcrtel ab und entkam der Gruppe bei der kleinen Verfolgung. Das kleinere wurde an der Hauseingangst\u00fcr gestellt und bezog reichlich Pr\u00fcgel, na ja die h\u00e4lfe der Schl\u00e4ge, Pfeile &amp; Bolzen flogen ja auch ohne Schaden anzurichten hindurch.<\/p>\n<p>Am 17.Tarsakh wurde ordentlich Gefr\u00fchst\u00fcckt und danach wurde durch die Gruppe dem gutem Hr. Ismark Kolyana ( Sohn des B\u00fcrgermeisters, der in der Dorfsch\u00e4nke von der Gruppe 1 Tage zuvor entdecket wurde, kann auch sein das er deswegen als Papagei betitelt wird weil er so bunt angezogen ist ) noch einmal ordentlich ins Gewissen geredet ohne das K\u00f6rperliche Attribute zur Anwendung kam. Er wurde mehr oder weniger \u00dcberzeugt, dass er sich schon auf Grund seiner Stellung, als Sohn des B\u00fcrgermeisters, etwas mehr um seine Dorfbewohner k\u00fcmmern sollte. Da seine Schwester jetzt das Amt der Dorfb\u00fcrgermeisterin inne hatte wurde Sie gefragt ob Sie Einw\u00e4nde hatte, nat\u00fcrlich hatte Sie keine, sie begr\u00fc\u00dfte es schon eher und war vielleicht auch etwas erfreut.<\/p>\n<p>Da die Verdammten es jetzt schon zweimal mit Geistern in engeren Kontakt gekommen sind, wurden 10 Flaschen mit geweihtem Wasser gef\u00fcllt und auf die Gruppenmitglieder aufgeteilt. Danach ging es denn in das Dorf um f\u00fcr unseren Papagei eine etwas Sinnvollere Ausr\u00fcstung zu besorgen. Es f\u00fchrte der Weg der Gruppe zum wei\u00df gestrichenen Haus das nicht sehr besch\u00e4digt war und auch nicht verbarrikadiert war. Im Erdgeschoss fand man nichts von Bedeutung oder was als Waffe f\u00fcr den Papagei dienen konnte. Aller ding fand die Gruppe einen Geheimgang. Als der Mechanismus der verborgenen T\u00fcr entdeckt und ausgel\u00f6st wurde, h\u00f6rte die Gruppe von oben\u00a0 die Stimme einer etwas \u00e4lteren Menschen Frau.<\/p>\n<p>Also teilte sich die Gruppe auf.<\/p>\n<p>Jorax, Amara, DBW gingen in den Gang, Knartsch sorgte f\u00fcr R\u00fcckendeckung in einem Versteck im EG (hoff ich zumindest, weil gesehen hab ich ihn nicht mehr. Drisinil, Cyrilla und der Papagei gingen nach oben.<\/p>\n<p>Jorax, Amara und der braune Wanderer mussten durch einen engen niedrigen Gang krabbeln der ca. 1,5 &#8211; 2 m lang war. Es war stockfinster und Amara musste eine Kerze entz\u00fcnden um etwas Licht f\u00fcr sich ins dunkele zu bringen (Elfen und ihre D\u00e4mmersicht). Danach wurde dieser Gang etwas breiter und h\u00f6her, so dass alle halbwegs aufrecht gegen konnten. Am Ende dieses Ganges stand die kleine Gruppe vor einer Holzt\u00fcr mit Vorh\u00e4ngeschloss. Der Geruch im Gang erinnerte die 3 etwas an getrocknetes Blut, und einen leicht modrigem Geruch stieg ihnen in die Nase. Egal, Amara versuchte sich als Schlossknackerin , bescheiden , zwei Dietriche hatten nicht die erhoffte Wirkung. Also beschoss Jorax es auf die etwas andere Schlosskackertour. Er lie\u00df sich vom brauen Wanderer das 2 Tage zuvor gefundene Nageleisen geben und hebelte das mickrige Vorh\u00e4ngeschloss auf. Die Gruppe trat durch die T\u00fcr. Der Raum der sich der Gruppe erschloss war ca. 5 x 5 m gro\u00df und hatte einen kleinen Teich auf der linken H\u00e4lfte des Raumes. Es fand sich eine junge Frau die am Ufer des kleinen Teiches lag.\u00a0 Ihr linker Arm war an der Schulter abgetrennt worden. Aber die Wunden waren aller mehr oder weniger fachm\u00e4nnisch versorgt wurden. Die meisten Ihrer Knochen waren auch mehr als einmal gebrochen worden. Sie ist also gefoltert worden. Die Gruppe untersuchte denn Raum weiter und fand in der einen Ecke einen Lagerraum. Der Lagerraum hatte auf der einen Seite allerlei Ger\u00e4te um Glieder abzutrennen und Wunden zu versorgen und auf der gegen\u00fcberliegenden Seite waren Gleicherma\u00dfen von unterschiedlichen Personen und evtl. auch Rassen in Glass Beh\u00e4lter eingelegt \/ konserviert. Nach dieser Entdeckung untersuchten die Gruppe noch einmal die Frau am Ufer und fanden an den F\u00fc\u00dfen Abdr\u00fccke von Eisenfesseln mit der Gefangene angekettet wurden und im Wasser einen Wappenrock mit einem gr\u00fcnen Knochensch\u00e4del. Stellen f\u00fcr solche Vorrichtung f\u00fcr Ankettung fand die Gruppe anschlie\u00dfend auch an den W\u00e4nden, sie waren aber schon etwas von Moosen \u00fcberwachsen. Danach ging die Gruppe zur\u00fcck in den Raum im EG.<\/p>\n<p>Drisinil, Cyrilla und der Papagei gingen nach oben und hielten mit der alten Dame einen Caf\u00e9 Klatsch ab. (Falls das einer etwas n\u00e4her ausf\u00fchren m\u00f6chte kann er das gerne machen)<\/p>\n<p>Als Jorax, Amara, DBW zur\u00fcck in den Raum im EG kam gesellte sich Cyrilla zu Ihnen und erz\u00e4hlte der Gruppe was sich abgespielt hatte, Caf\u00e9 Pl\u00e4uschchen halt. also marschierte die gesamte Gruppe nach oben zur alten Dame und gesellte sich zu Drisinil und dem Papagei. Jorax z\u00fcckte sein F\u00e4sschen und erkl\u00e4rte der alten Dame das er Tee nur trinkt wenn da etwas Schuss in der Tasche Tee ist, und gab einen Portion Rum aus seinem F\u00e4sschen dazu. Der alten Dame schmeckte es sehr und so ging es denn mit den n\u00e4chsten 4-5 Tassen weiter. Nach einigen sehr zweideutigen S\u00e4tzen der guten alten Dame faste Jorax den Entschluss, dass die alte Dame mit hoher Wahrscheinlichkeit eine M\u00f6rderin war, die sich mit abgetrennten Gliedma\u00dfen die Gunst der Werw\u00f6lfe erkaufen wollte. Warum auch wohl das Haus nicht beim Angriff der Werw\u00f6lfe angegriffen wurde. Darauf trat er mit voller Wucht gegen die Tischkante und lies den Tisch auf die alte Dame zuschie\u00dfen. Dar\u00fcber war die alte Dame wohl sehr verdutzt, denn im n\u00e4chsten Zug sprang Jorax auf den Teetisch ging mit einer 360\u00b0 Drehung in die Hocke und lies seine Fu\u00df mit vollem Schwung gegen die linke Seite des Kopfes prallen. Das traf die Dame mit voller Wucht und lies sie zu Boden fallen, Jorax kommt in einer flie\u00dfenden Bewegung auf die Beine, springt sofort ab und trifft die Dame mit einem Ellenbogen Drop auf dem oberem R\u00fccken \/ Schulterbl\u00e4tter der alten Dame was ihr Ende bedeutete. Der anschlie\u00dfende Genickbruch durch drehen der Kopfes um mehr als 180 \u00b0 ist nicht mehr von Bedeutung. Danach ist Jorax etwas entt\u00e4uscht , hatte er doch Felsen fest angenommen die gute alte , jetzt tote , Dame ist nur Fassade und es verwandelt sich in ein fieses stinkendes 2,50 m gro\u00dfes Monster. &#8220; hab ich evtl. jemanden unschuldiges get\u00f6tet &#8220; ging den Zwerg durch den Kopf und verwirrte Ihn sehr. Das blieb der Gruppe nicht verborgen und der Zwerg bekam Zuspruch und wurde von Amara getr\u00f6stet. Danach durch suchte die Gruppe sehr sorgf\u00e4ltig das gesamte Haus, schlie\u00dflich wurden sie im Erdgescho\u00df, genauer gesagt in der K\u00fcche, f\u00fcndig. Sie fanden im einer kleinen Holzschatulle einen Zettel der mit folgenden Worten beschrieben war: Diene uns gut, so wird dir kein Leid geschehen, Unterzeichnet mit Valicya. Das machte dem Zwerg wieder Mut, also hatte er wohl doch den richtigen Richter bei der alten Dame gehabt. Nach dem die Gruppe die Leiche der jungen Frau dem Papagei gezeigt hatte best\u00e4tigte er das die Leiche der jungen Frau die Tochter der alten Dame war. Noch eine Best\u00e4tigung mehr f\u00fcr den Zwerg, dass richtige getan zu haben.<\/p>\n<p>Anschlie\u00dfend ging die Gruppe zur\u00fcck und bereiteten sich darauf vor den Friedhof und die dazu geh\u00f6renden Kapelle \/ Kirche zu untersuchen.<\/p>\n<p>Zur Erinnerung der Zeitliche Ablauf der vergangenen Tage bevor die Gruppe im die Ortschaft kam:<\/p>\n<p>14 Tage vor\u00a0Eintreffen der Gruppe im Ort: Gespr\u00e4ch zwischen dem B\u00fcrgermeister und dem Graf Strahd von Zarovich, der Graf wurde durch das sehr glei\u00dfend helle Aufleuchten des Amulettes der Rabenkinder in die Flucht geschlagen<\/p>\n<p>7-8 Tage vor\u00a0Eintreffen der Gruppe im Ort : tot des B\u00fcrgermeisters<\/p>\n<p>5-6 Tage vor\u00a0Eintreffen der Gruppe im Ort : Angriff der Werw\u00f6lfe auf das Dorf<\/p>\n<p>3 Tagen vor\u00a0Eintreffen der Gruppe im Ort : Angriff des Zombies auf das Dorf<\/p>\n<p>Tag 0 Eintreffen der Gruppe im Ort<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) In der Nacht vom 16.Tarsakh zum 17. Tarsakh 1382 wurde die Gruppe im Gutshaus des B\u00fcrgermeisters von 2 Geistern angegriffen. Das etwas Gr\u00f6\u00dfere riss einen kleinen Teil von Brotors Lederg\u00fcrtel ab und entkam der Gruppe bei der kleinen Verfolgung. Das kleinere wurde an der Hauseingangst\u00fcr gestellt und bezog [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":6976,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[128],"tags":[344],"class_list":["post-6967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe2","tag-14-tarsakh-1382-17-tarsakh-1382"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) In der Nacht vom 16.Tarsakh zum 17. Tarsakh 1382 wurde die Gruppe im Gutshaus des B\u00fcrgermeisters von 2 Geistern angegriffen. Das etwas Gr\u00f6\u00dfere riss einen kleinen Teil von Brotors Lederg\u00fcrtel ab und entkam der Gruppe bei der kleinen Verfolgung. Das kleinere wurde an der Hauseingangst\u00fcr gestellt und bezog [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-07T20:49:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-06T15:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"833\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorax Mc Dougal (Christian)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorax Mc Dougal (Christian)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/\"},\"author\":{\"name\":\"Jorax Mc Dougal (Christian)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/f061588295f75787e430a121167ce3b9\"},\"headline\":\"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)\",\"datePublished\":\"2015-03-07T20:49:45+00:00\",\"dateModified\":\"2018-02-06T15:24:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/\"},\"wordCount\":1328,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/ravenloft3.jpg?fit=540%2C833&ssl=1\",\"keywords\":[\"14.Tarsakh 1382 - 17.Tarsakh 1382\"],\"articleSection\":[\"Cult of the Damned (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/\",\"name\":\"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/ravenloft3.jpg?fit=540%2C833&ssl=1\",\"datePublished\":\"2015-03-07T20:49:45+00:00\",\"dateModified\":\"2018-02-06T15:24:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/ravenloft3.jpg?fit=540%2C833&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/ravenloft3.jpg?fit=540%2C833&ssl=1\",\"width\":540,\"height\":833},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/raetzel-ueber-raetzel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/f061588295f75787e430a121167ce3b9\",\"name\":\"Jorax Mc Dougal (Christian)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1895bd7ebd04666151adcfaa3bac0046efb4e81938b8619db9362cbd62b45d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1895bd7ebd04666151adcfaa3bac0046efb4e81938b8619db9362cbd62b45d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1895bd7ebd04666151adcfaa3bac0046efb4e81938b8619db9362cbd62b45d4?s=96&d=mm&r=g\",\"caption\":\"Jorax Mc Dougal (Christian)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/kendrick\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) - RPG-Berlin.de","og_description":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) In der Nacht vom 16.Tarsakh zum 17. Tarsakh 1382 wurde die Gruppe im Gutshaus des B\u00fcrgermeisters von 2 Geistern angegriffen. Das etwas Gr\u00f6\u00dfere riss einen kleinen Teil von Brotors Lederg\u00fcrtel ab und entkam der Gruppe bei der kleinen Verfolgung. Das kleinere wurde an der Hauseingangst\u00fcr gestellt und bezog [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2015-03-07T20:49:45+00:00","article_modified_time":"2018-02-06T15:24:44+00:00","og_image":[{"width":540,"height":833,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1","type":"image\/jpeg"}],"author":"Jorax Mc Dougal (Christian)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Jorax Mc Dougal (Christian)","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/"},"author":{"name":"Jorax Mc Dougal (Christian)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/f061588295f75787e430a121167ce3b9"},"headline":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)","datePublished":"2015-03-07T20:49:45+00:00","dateModified":"2018-02-06T15:24:44+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/"},"wordCount":1328,"commentCount":4,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1","keywords":["14.Tarsakh 1382 - 17.Tarsakh 1382"],"articleSection":["Cult of the Damned (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/","name":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1","datePublished":"2015-03-07T20:49:45+00:00","dateModified":"2018-02-06T15:24:44+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1","width":540,"height":833},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/raetzel-ueber-raetzel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"R\u00e4tsel \u00fcber R\u00e4tsel (Cult of the Damned)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/f061588295f75787e430a121167ce3b9","name":"Jorax Mc Dougal (Christian)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d1895bd7ebd04666151adcfaa3bac0046efb4e81938b8619db9362cbd62b45d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1895bd7ebd04666151adcfaa3bac0046efb4e81938b8619db9362cbd62b45d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1895bd7ebd04666151adcfaa3bac0046efb4e81938b8619db9362cbd62b45d4?s=96&d=mm&r=g","caption":"Jorax Mc Dougal (Christian)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/kendrick\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/03\/ravenloft3.jpg?fit=540%2C833&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-1On","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/6967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=6967"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/6967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/6976"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=6967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=6967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=6967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}