{"id":6789,"date":"2015-02-28T18:12:34","date_gmt":"2015-02-28T17:12:34","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=6789"},"modified":"2018-04-15T20:42:11","modified_gmt":"2018-04-15T18:42:11","slug":"totes-pferd","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/","title":{"rendered":"Totes Pferd"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft wp-image-15496 size-medium\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?resize=300%2C300&#038;ssl=1\" alt=\"Totes Pferd\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?resize=270%2C270&amp;ssl=1 270w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?resize=230%2C230&amp;ssl=1 230w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?w=420&amp;ssl=1 420w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Totes Pferd<\/p>\n<p>Du hast ihn sicher\u00a0schon irgendwo gesehen, wenn du\u00a0in letzter Zeit in Baldurs Tor warst. Ein dunkelhaariger Elf, abartig gro\u00df und schlacksig mit Armen wie \u00c4sten und mehr T\u00e4towierungen auf seiner Haut als Kleidung. Wenn die spitzen Ohren nicht w\u00e4ren k\u00f6nnte man ihn fast f\u00fcr einen Nordl\u00e4nder halten&#8230; naja,einen rasierten Nordl\u00e4nder vielleicht.<\/p>\n<p>Nein, ich hab nicht die leiseste Ahnung wo er herkommt. Er spricht nicht viel Gemeinsprache, glaube ich, eigentlich komisch f\u00fcr einen der so weit gereist ist wie er. Oh, das Ding, das er \u00fcberall mit sich rumtr\u00e4gt? Das hat er bei mir anfertigen lassen, war richtig komisch. Ich hab zuerst versucht, eine ordentliche Waffe zu verkaufen, ein Langschwert oder zumindest einen Krumms\u00e4bel, aber nein er besteht drauf, gibt mir sogar Anweisungen wie ich das Ding schmieden soll. Mir! Lausiger Barbar. &#8222;Nicht mehr als zw\u00f6lf\u00a0Zoll\u00a0lang, die Spitze eineinhalb Zoll\u00a0breiter als der Rest der Klinge\u00a0und nach vorne gebogen ausgerichtet, keine Parierstange, nur ein runder Griffschutz aus Holz.&#8220; Nennt sich &#8218;Ma-che-te&#8216; das Ding, hab meinen Kumpel\u00a0Nisus gefragt, der ist selber Mondelf und der hat das Wort noch nie in seinem Leben geh\u00f6rt&#8230; Appropos, willst du was richtig gruseliges h\u00f6ren? Wie Nisus sich mit ihm auf Elfisch unterhalten hat &#8211; genau, an dem Abend am Hafen wie ich beim W\u00fcrfeln den ganzen Topf abger\u00e4umt hab!\u00a0&#8211; wei\u00dft du noch, wie sich bei Nisus die Nackenhaare aufgestellt haben, je l\u00e4nger er mit ihm gesprochen hat? Ich hab ihn nachher gefragt, was denn los war und stell dir vor, Nisus meint der Barbar spricht zwar Elfisch aber mit einem\u00a0<em>Drow<\/em>-Akzent.<\/p>\n<p>Nein, man spricht es &#8218;Droh&#8216; aus und nicht &#8218;Drau&#8216;.<\/p>\n<p>Also haben wir hier einen Elf, der\u00a0aussieht wie ein nordischer Berserker, unter den Sternen schl\u00e4ft und rohes Fleisch isst wie ein Gnoll im Wald und spricht wie ein verfluchter Drow. Und aus irgendeinem Grund will er unbedingt nach Korrin, er fragt schon eine ganze Woche lang deswegen rum. Ich meine was soll man davon halten? Ich w\u00fcrd ihn ja gerne den Wachen melden, aber du hast ja sicher schon geh\u00f6rt, wie er k\u00e4mpft, wenn er in die Ecke getrieben ist, der hat dem Dicken Rolf ein\u00a0Ohr abgerissen, mit den Z\u00e4hnen!<\/p>\n<p>Seinen Namen? Naja, wir haben\u00a0ihn einfach Totes Pferd genannt, weil\u00a0sobald er angekommen ist ist der Gaul, auf dem er eingeritten ist einfach zusammengebrochen und verreckt, mitten auf der Hauptstra\u00dfe. Schrecklicher Anblick, das arme Vieh hatte lauter Pfeilwunden. Ich glaube ihm gef\u00e4llt der Name, seit er hier ist stellt er sich auch immer als Totes Pferd vor. Er hat ein oder zwei Mal versucht uns seinen echten Namen zu sagen, aber keiner au\u00dfer Nisus hat ihn richtig aussprechen k\u00f6nnen, also haben wir&#8217;s gelassen, bevor er sauer wird. Warte, ich glaube er hat ihn sogar aufgeschrieben, f\u00fcr seine Rechnung bei mir&#8230;<\/p>\n<p>Tamrosekincaiwellyn.<\/p>\n<p>Kein Wunder, dass ihm Totes Pferd besser gef\u00e4llt, was?<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Zitate von Tamrosekincaiwellyn, AKA Totes Pferd<\/strong><\/p>\n<p>\u00dcber Gut und B\u00f6se:<\/p>\n<p>&#8222;Ein Mann muss tun, was ein Mann tun muss um sich und die, die er liebt zu sch\u00fctzen. Aber manchmal tun M\u00e4nner auch mehr, als sie m\u00fcssen, grausame Dinge, unverantwortliche Dinge, einfach nur weil sie&#8217;s k\u00f6nnen. Grausamkeit ist ein Zeichen von Schw\u00e4che und Schw\u00e4che wird fr\u00fcher oder sp\u00e4ter immer bestraft.&#8220;<\/p>\n<p>\u00dcber Rechtschaffenheit und Chaos:<\/p>\n<p>&#8222;Regeln sind\u00a0wie&#8230; Kleidung. Es ist gut, welche zu haben, aber ein Mann der immer die selbe tr\u00e4gt, egal zu welcher Jahreszeit, an welchem Ort und zu welchem Wetter wird fr\u00fcher oder sp\u00e4ter ins Schwitzen kommen. Oder erfrieren.&#8220;<\/p>\n<p>\u00dcber die G\u00f6tter:<\/p>\n<p>&#8222;Ein Mann der nur auf seine G\u00f6tter vertraut, zieht unbewaffnet in die Schlacht. Ein Mann der auf seine Muskeln, seine Erfahrung und auf den Stahl in seiner Hand vertrauen kann, der braucht keine G\u00f6tter, die ihn sch\u00fctzen.&#8220;<\/p>\n<p>\u00dcber Elfen:<\/p>\n<p>&#8222;Die Menschen glauben, dass Alter gleichbedeutend mit Weisheit ist. Ich bin \u00e4lter als ein Mensch je ohne Magie werden k\u00f6nnte und meine Weisheit habe ich selbst\u00a0gefunden oder von anderen gestohlen, man hat sie mir nicht einfach geschenkt, nur weil ich alt bin.&#8220;<\/p>\n<p>\u00dcber Menschen:<\/p>\n<p>&#8222;Das beste, was die Menschen je geleistet haben? Die Hellebarde. Eine Waffe, die gleicherma\u00dfen als Axt oder als Spie\u00df verwendet werden kann, das ist die kl\u00fcgste Erfindung, die ich je gesehen habe. Wenn wir Elfen die Hellebarde vor den Menschen erfunden h\u00e4tten, w\u00fcrden wir an eurer Stelle \u00fcber Faerun herrschen, da bin ich mir sicher.&#8220;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Eindr\u00fccke meiner ersten Seereise von Tamrosekincaiwellyn AKA Totes Pferd<\/strong><\/p>\n<p>Bin eindeutig nicht f\u00fcr die Seefahrt geschaffen, so viel Geschaukle und Gewackle. Habe mich die ersten Tage st\u00e4ndig \u00fcbergeben. Keiner hat gelacht, der Genasi (ich habe erfahren, dass er Jenotus hei\u00dft) hat mir sogar gezeigt, wie ich richtig mit den Wogen mitatme um dem Schwindel entgegenzuwirken und der Kapit\u00e4n hat mir etwas Rum gegeben. Die Atem\u00fcbungen haben ein bisschen geholfen, der Rum aber mehr.<\/p>\n<p>Fast die ganze \u00dcberfahrt lang Schlechtwetter. Hab den Kapit\u00e4n gefragt, ob der Schiffspriester vor der \u00dcberfahrt noch allen Himmels- und Sturmg\u00f6ttern angemessen geopfert hat, bevor wir losgefahren sind aber er ist der Frage ausgewichen. Ich habe dies richtigerweise als ein schlechtes Omen gedeutet.<\/p>\n<p>Die Schiffsmannschaft erscheint mir ganz in Ordnung, aber dieser Expeditionsgesellschaft traue ich nicht ganz. Jenotus unterh\u00e4lt sich st\u00e4ndig mit ihrem Zauberer, ich sollte ihn wenn wir an Land sind bei Gelegenheit deswegen ausfragen.<br \/>\nDiese Madam Fley ist auch verd\u00e4chtig. Was f\u00fcr ein hoher Beamter fordert im Fall seines Todes einen Nachfolger an, der erst um die halbe Welt reisen muss um das Amt \u00fcberhaupt anzutreten? Jenotus sagt er traut ihr nicht, h\u00e4lt sie f\u00fcr eine Diebin. Ich glaube ihr ebenfalls nicht, denke aber da ist mehr im Gange.<\/p>\n<p>Wir wurden angegriffen. Keine Piraten wie ich erwartet hatte, sondern Seekreaturen mit neun Fu\u00df langen Fangarmen, wie der Kraken aus den alten Geschichten. Die beiden Zauberer nennen die Bestien Scyllae und behaupten, sie seien hier nicht beheimatet, sondern von einer andersweltlichen Macht beschworen worden.<br \/>\nDirekt vor dem Angriff hat der Barde (Halbling oder Gnom?) angefangen der Mannschaft eines seiner Zauberlieder vorzusingen und auch die ganze Zeit weitergesungen, w\u00e4hrend der Rest von uns gegen sie gek\u00e4mpft hat. Ich wollte ihn nach dem Kampf der Sicherheit halber \u00fcber Bord werfen, aber Jenotus und der oben genannte nutzlose Priester sind dazwischen gegangen. Ich werde es bei einer sp\u00e4teren Gelegenheit nachholen.<\/p>\n<p>Nachdem wir die Kreaturen vertrieben haben, hat uns nichts mehr behelligt. Ich habe dem Stegmeister in Mintarn erz\u00e4hlt, unser Schiff stehe unter dem Schutz der Sturmg\u00f6ttin. Menschen sind ein abergl\u00e4ubisches Volk, ganz besonders das kriminelle Gesindel unter ihnen, wenn er es weitererz\u00e4hlt wird uns bis zur Weiterreise nach Korinn hoffentlich niemand behelligen.<br \/>\nIch habe beschlossen mich zusammen mit Jenotus nach einer Unterkunft umzusehen, weil wir beide genug von H\u00e4ngematten haben. Mir macht die H\u00e4ngematte nichts aus, aber ich bin einfach froh, wieder festen Erdboden unter meinen F\u00fc\u00dfen zu haben.<\/p>\n<p>Auch wenn mir das Reisen zu Schiff unangenehm ist, das K\u00e4mpfen an Deck ist \u00fcberraschend leicht. Man hat in jede Richtung klare Sicht und nicht zu viel Raum zwischen sich und potentiellen Gefahren zu decken, mit einem soliden Speer und einem festen Stand kann man sich auf einem Schiff sehr gut verteidigen. Und sollte doch ein Pirat oder Ungeheuer lebend an meinem Speer vorbeikommen, habe ich immer noch meine neue Machete.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Erste Eindr\u00fccke von Mintarn-Hafen<\/strong> <strong>von Tamrosekincaiwellyn AKA Totes Pferd<\/strong><\/p>\n<p>Jenotus und ich sind auf Empfehlung von Kapit\u00e4n Friesel im \u201cBetrunkenen Piraten\u201d eingekehrt, angeblich eines der besseren Gasth\u00e4user. Das Gasthaus selbst war angenehm. Ich habe die Gelegenheit genutzt um das erste hei\u00dfe Bad seit mindestens drei Wochen zu nehmen und mir wurde sogar eine Hure zur Verf\u00fcgung gestellt, eine Mischlingshexe mit scheinbar sehr vielseitigen Talenten. Leider scheint ihr daf\u00fcr das Gesp\u00fcr f\u00fcr Feingef\u00fchl und Heimlichkeit zu fehlen, als drau\u00dfen im Tavernenraum ein Kampf ausgebrochen ist habe ich versucht, mich durchs Get\u00fcmmel zu schleichen und einen feindseligen Zauberer- Magier von Thay, Abschaum unter Abschaum! \u2013 still und heimlich abzumurksen und besagte Mischlingsfrau kam scheinbar auf den Gedanken ich w\u00fcrde mich noch unauff\u00e4lliger bewegen k\u00f6nnen, wenn ich einen Meter gr\u00f6\u00dfer w\u00e4re. Idiotisch, aber was kann man schon von einem Halbmensch erwarten, noch dazu von einer Frau.<br \/>\nDie Mannschaft der Frenja ist nach wie vor so nutzlos, wie ich sie beim Kampf gegen die Scyllae schon eingesch\u00e4tzt habe, der Schiffspriester hat sich hinterm Tresen in seinen Flaschen verkrochen, der Kapit\u00e4n und der Erste Maat wurden schnell \u00fcberw\u00e4ltigt, der Magier, mit dem sich Jenotus angefreundet hat hat mit seinem Zauber mehr Schaden angerichtet als geholfen und der Halbling-S\u00e4nger hat w\u00e4hrend des ganzen Gefechts einfach in der Ecke seine Laute gespielt, sogar als einer der Kalim-M\u00e4nner versucht hat seine Gef\u00e4hrtin als Geisel zu nehmen.<br \/>\nWenn ich Jenotus nicht kennengelernt h\u00e4tte, w\u00fcrde ich vermuten es ist die Magie, die ihnen allen das Hirn weich macht, nicht ihre menschlichen Gene.<br \/>\nAuf engem Raum, mit improvisierten Waffen und Gegnern in allen Richtungen k\u00e4mpfte es sich nicht ann\u00e4hernd so gut wie auf dem Schiff und der Vergr\u00f6\u00dferungszauber hat dem Gef\u00fchl auch nicht geholfen. Ich bin mir vorgekommen wie ein gro\u00dfer dummer Oger der einfach planlos um sich schl\u00e4gt. Die anderen \u00dcberlebenden sagten mir nachher, ich h\u00e4tte im Kampfrausch jemandem mit einem Stuhl erschlagen. Eine peinliche Geschichte, zwischen dem Kampf heute und der Sache mit dem toten Pferd in Baldurs Tor scheine ich immer mehr zu einer Figur aus einem menschlichen Kneipenlied zu werden.<br \/>\nAber der Tag hatte auch seine guten Seiten. Es gibt zwei Rote Magier von Thay weniger auf dieser Welt, was immer ein Grund zu feiern ist und ich habe mehrere Dokumente gefunden, die mir den Weg zu einem ganzen Nest dieser widerw\u00e4rtigen Brut weisen k\u00f6nnte.<br \/>\nWie ich vor einigen Tagen auf ein Schiff nach Korrin gestiegen bin, hatte ich nur vor meine ehemaligen Br\u00fcder wieder zu finden und einen von ihnen seiner gerechten Strafe zuzuf\u00fchren, aber jetzt stellt sich heraus, dass es hier eine ganze Enklave voller Leute gibt, die den Tod genauso sehr verdient haben. W\u00e4re ich ein abergl\u00e4ubischer Mann, w\u00fcrde ich die heutige Begegnung f\u00fcr ein Zeichen der G\u00f6tter halten.<\/p>\n<p>Die Tavernenhure ist nach dem Kampf noch einmal zu mir gekommen und hat mit einem Zauberspruch einige meiner Wunden geschlossen. Ich habe ihr angeboten, sie bei der n\u00e4chsten Gelegenheit auch zu versorgen. Sie sagt sie freut sich darauf.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00dcber Mintarn &#8211; Eindr\u00fccke und Erkenntnisse von Tamrosekincaiwellyn AKA Totes Pferd<\/strong><\/p>\n<p>Es \u00fcberrascht mich manchmal selbst, wie schnell Instinkte die Oberhand nehmen k\u00f6nnen.<\/p>\n<p>Ich sollte Mintarn hassen. Ich hasse die Leute;\u00a0Gesindel in allen Formen und Gr\u00f6\u00dfen, vom Stra\u00dfenschwindler\u00a0bis zum Sklavenh\u00e4ndler. Ich hasse den Gestank im Hafen und die allgegenw\u00e4rtige feuchte Hitze in der Luft, die kein Wind zu vertreiben zu k\u00f6nnen scheint. Ich hasse die allgemeine Bereitschaft zum Blutvergie\u00dfen und ich hasse wie ansteckend sie ist. Jemand kommt zur T\u00fcr herein und mein erster Reflex ist zur Waffe zu greifen.\u00a0Meine neuen Kameraden und ich stellen einen unf\u00e4higen kleinen Wurm, wie er sich davon schleichen will und mein Instinkt r\u00e4t mir ihn zu t\u00f6ten, weil er mein Gesicht gesehen hat. Ich finde\u00a0einen unschuldigen Gaffer, der zur falschen Zeit am falschen Ort war und jede Faser meines K\u00f6rpers schreit gleich danach, ihm die Speerspitze durchs Genick zu treiben. Es widert mich an, wie leicht mich die Wut wieder \u00fcbernimmt, nachdem ich ihr so lange widerstanden habe.<\/p>\n<p>Ich f\u00fchle mich auf dieser verfluchten Insel\u00a0so lebendig wie schon seit f\u00fcnfzig Jahren nicht mehr.<\/p>\n<p>Es erinnert mich an Thay oder an die Au\u00dfenbezirke von Zentil, wo ich mit beiden Augen offen schlafen musste, wo ein unachtsamer Augenblick gereicht h\u00e4tte, um mich ans falsche Ende einer Klinge zu liefern. Ein Ort wo Grausamkeit und Gier gleichbedeutend mit purer Selbsterhaltung sind. Nur bin ich diesmal nicht als Opfer hier, sondern aus freien St\u00fccken und mit einem Ziel vor Augen.<\/p>\n<p>Jeder wei\u00df, dass Menschen dumm sind, aber ein besonders dummes Exemplar hat mich einmal gefragt, &#8222;Wie kommt es. dass ein Elfenkrieger, der f\u00fcnfhundert Jahre lang trainiert um die Kunst des Schwertkampfs zu meistern von einem Zwerg oder Mensch oder Ork besiegt werden kann, der erst seit zehn Jahren \u00fcbt?&#8220; Ich hab ihm die Nase gebrochen, weil er mir auf die Nerven gegangen ist, aber er hatte nicht Unrecht. Tatsache ist, ein Elf vergisst in seinem Leben mindestens genauso viel wie er lernt. Ich war nicht immer ein&#8230; was immer ich jetzt bin. Krieger? Das h\u00f6rt sich falsch an. Ich f\u00fchre keine Kriege, daf\u00fcr mangelt es mir an echten Feinden. Das ist keine Arroganz, das ist Tatsache. Aber der Punkt ist, diese Wut, die mich antreibt, die wurde erst vor wenigen Jahrzehnten in mir geweckt und obwohl ich wei\u00df, dass ich ohne sie Thay niemals lebend verlassen h\u00e4tte, war sie mir seitdem mehr Fluch als Segen. Bis jetzt.<\/p>\n<p>Was immer ich vorher war, hier kann ich es getrost vergessen. Hier kann ich versuchen aufzuh\u00f6ren, der zu sein der ich war und der sein, der ich will. Vielleicht vergesse ich hier irgendwann einmal den Namen Tamrosekincaiwellyn und nenne mich tats\u00e4chlich nur mehr Totes Pferd. Hier kann ich mich meiner Wut hingeben, denn dieser Ort und diese Leute\u00a0<em>verdienen<\/em> meinen Wut. Hier k\u00f6nnte ich hundert Jahre Krieg f\u00fchren,\u00a0ohne jemals Gefahr zu laufen jemanden zu t\u00f6ten, der es nicht verdient h\u00e4tte.<\/p>\n<p>Ein trauriger Gedanke, aber auch ein befl\u00fcgelnder.<\/p>\n<p><strong>\u00dcber\u00a0Gl\u00fcckspiel- von Tamrosekincaiwellyn, AKA Totes Pferd<\/strong><\/p>\n<p>Wie ich erwartet hatte, gibt es auch hier in Mintarn waffenlose Wettk\u00e4mpfe. Und wie ich ebenfalls erwartet hatte, wird hier genauso wetteifrig betrogen, wie gek\u00e4mpft wird. H\u00e4tte ich die Zeit, w\u00fcrde ich die Leute hier besser kennen lernen, vielleicht ein paar Mal in den Ring steigen &#8211; professionelle Schwalben, wie es sie in der Arena von Zentil gibt\u00a0verdienen hier sicher auch nicht schlecht &#8211; ich w\u00fcrde lernen, wie das Spiel hier gespielt wird, nicht der Faustkampf, sondern dass Spiel der Buchmacher und der Wettmeister. Die K\u00e4mpfer und Zuschauer in dieser Arena sind ein wahrer Querschnitt von Mintarn, vom Handelsbaron zum T\u00fcrsteher. Und sie scheinen recht offen mit Informationen zu sein, zwei verschiedene Quellen &#8211; eine vertrauensw\u00fcrdig, die andere weniger &#8211; haben mir eine Liste von Namen und Gesichtern geliefert, denen ich in den n\u00e4chsten N\u00e4chten einen Besuch abstatten will.<\/p>\n<p>Ich habe dem anderen Mischling, Strave, die Liste vorgelegt, aber er scheint im Moment zu voreingenommen mit diesem mystischen Unsinn zu sein, in den ihn Jenotus und Alina hereingezogen haben. Jemand hat dem kleinen Jungen einen Schrecken eingejagt und jetzt will er von der Insel fl\u00fcchten, weil er den Zorn von irgendeinem Nekromanten f\u00fcrchtet. Als ob man vor Leuten, die\u00a0sich an die Toten wenden um Hilfe wenden Angst haben m\u00fcsste. Es ist wie bei den Karten oder in der Arena, manchmal reicht allein ein starker Bluff, um die Runde zu entscheiden. Leute, die noch nicht viel vom Tod gesehen haben, f\u00fcrchten sich vor Leichen,\u00a0also kommen ihnen Magier, die Leichen befehligen gef\u00e4hrlicher vor, als sie tats\u00e4chlich sind.<\/p>\n<p>Ich stelle fest, dass man in Mintarn doch Freundschaften schlie\u00dfen kann, allerdings nicht immer dort, wo man sie erwartet. Grumpf &#8211; seit der heutigen Nacht &#8222;Champion&#8220; Grumpf &#8211; scheint ein sehr anst\u00e4ndiger Kerl zu sein. Vielleicht kann ich ihn \u00fcberreden, ein paar Namen von meiner Liste zu kreuzen, fr\u00fcher oder sp\u00e4ter wird ein ehrlicher Wettk\u00e4mpfer wie er so oder so \u00c4rger mit den gewichtigen Namen im Gesch\u00e4ft bekommen und ich glaube Grumpf ist schlauer, als er vorgibt zu sein, er wird sicher den Sinn in einem Pr\u00e4ventivschlag sehen. Ich w\u00fcnschte nur, er w\u00e4re nicht ganz so umg\u00e4nglich mit den <em>Drow.<\/em><\/p>\n<p>Wo ich grade bei den Drow bin, es wird langsam Zeit, dass ich mir neue Kleidung kaufe, etwas, womit ich meine T\u00e4towierungen leichter verbergen kann. Und einen Hut, unter dem die Ohren nicht so leicht zu erkennen sind.<\/p>\n<p>\u00dcber \u201eH\u00e4rte\u201c \u2013 von Tamrosekincaiwellyn AKA Totes Pferd<img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/i0.wp.com\/www.hireanillustrator.com\/i\/images\/2015\/06\/slaine-sketch.jpg?w=1080\" alt=\"\" \/><\/p>\n<p>Viele praktizierende der Kriegskunst, besonders die jungen, wie meine derzeitigen Begleiter pflegen eine Gewohnheit, die ihnen oft schneller zum Verh\u00e4ngnis wird kann als Klingen oder Zauber; das Ideal der \u201eH\u00e4rte\u201c, der Gedanke dass ein wahrer Krieger keine Ruhe braucht und dass Erholungspausen etwas f\u00fcr Schw\u00e4chlinge sind. Ein aufmerksamer Leser dieses Werkes wird gemerkt haben, dass ich andauernd von K\u00e4mpfen schreibe, K\u00e4mpfe zu Schiff, K\u00e4mpfe in Tavernen, K\u00e4mpfe mit Magiern und M\u00f6rdern und grauslichem Getier, K\u00e4mpfe mit Waffen oder blo\u00dfen H\u00e4nden. Der Grund daf\u00fcr ist einfach, dass ich seit ich in Mintarn angekommen andauernd k\u00e4mpfe, ohne Pause und ohne Gelegenheit, mich zu erholen und heute haben mich endlich die Folgen dieser r\u00fccksichtslosen Narretei eingeholt.<br \/>\nDrei verschiedene K\u00e4mpfe haben wir heute bestritten, alle drei gegen heimt\u00fcckische Meuchelm\u00f6rder, die Hinterhalte, Gifte und den Kampf aus der Ferne bevorzugten. Keiner dieser Assassinen h\u00e4tte unter normalen Umst\u00e4nden eine Bedrohung f\u00fcr uns sein sollen. Grumpf ist ein Biest mit B\u00e4renkr\u00e4ften, der wahrscheinlich bereits mehr \u00fcber waffenlose Kampftechniken und Training vergessen hat, als ich w\u00e4hrend seiner ganzen Lebenszeit gelernt habe, Anskariat h\u00e4tte w\u00e4hrend meiner Zeit in Zentil locker mit Voldurs Jungs mitreiten k\u00f6nnen, ebenso die Sp\u00e4herin von der Arkanen Bruderschaft, der junge Zwerg ist ein zuverl\u00e4ssigerer Schildwall als ein zwei Mal so gro\u00dfer Mann und die Riesin ist\u2026 nunja, eine Riesin. Und trotzdem haben uns eine Hand Voll verlauster S\u00f6ldner mit Unterst\u00fctzung eines Magiers beinahe in die Knie gezwungen, wir alle haben immer wieder das selbe gedacht: Ein einziger Kampf noch. Ein letztes Mal, dann ist Ruhe. Vielleicht ist es einfach Stolz, der M\u00e4nner wie uns zu so etwas treibt, vielleicht wollen wir vor unseren Waffenbr\u00fcdern einfach keine Schw\u00e4che eingestehen, ihnen zeigen, dass sie sich auf uns verlassen k\u00f6nnen und dass wir nie aufgeben oder z\u00f6gern werden. Das wird hart genug sind, alles einzustecken, egal wie schnell die Schl\u00e4ge kommen.<br \/>\nEs ist t\u00f6richt. Nur weil man die Z\u00e4hne zusammenbei\u00dfen kann, hei\u00dft das nicht, dass es eine gute Idee ist. Unsere K\u00f6rper sind trainiert, um andere K\u00f6rper in ihre Einzelteile zu zerlegen, aber solche Leistungen fordern Kraft und niemand von uns hat unendlich Kraft.<br \/>\nW\u00e4hrend ich diese Worte schreibe, haben wir beschlossen im Tempel des Moradin Schutz zu suchen, damit wir uns erholen und unsere n\u00e4chsten Zug planen k\u00f6nnen. Selbst wilde Tiere m\u00fcssen sich Zeit nehmen ihre Wunden zu lecken.<br \/>\nDreizehn Assassinen und ein Diener des Barandan Zhan sind am Ende des heutigen Tages tot. Ich hoffe das bereitet dem elendigen Zauberer eine schlaflose Nacht, w\u00e4hrend wir uns unsere erste richtige Pause g\u00f6nnen.<\/p>\n<p>Zur\u00fcck aus dem Unterreich von Tamrosekinkaiwellyn AKA Totes Pferd<\/p>\n<p>Freier Himmel. Der Wind in meinem Haar. Das Fell eines gelegeten Feindes auf meinen Schultern und auf meinem R\u00fccken h\u00e4lt mich warm.<br \/>\nIch hab keine Ahnung wo ich bin, aber ich hab mich schon lange nicht mehr so lebendig gef\u00fchlt.<br \/>\nAuf ans Werk.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Totes Pferd Du hast ihn sicher\u00a0schon irgendwo gesehen, wenn du\u00a0in letzter Zeit in Baldurs Tor warst. Ein dunkelhaariger Elf, abartig gro\u00df und schlacksig mit Armen wie \u00c4sten und mehr T\u00e4towierungen auf seiner Haut als Kleidung. Wenn die spitzen Ohren nicht w\u00e4ren k\u00f6nnte man ihn fast f\u00fcr einen Nordl\u00e4nder halten&#8230; naja,einen rasierten Nordl\u00e4nder vielleicht. Nein, ich [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":15496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[335],"tags":[],"class_list":["post-6789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-totes-pferd-ben"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Totes Pferd - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Totes Pferd - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Totes Pferd Du hast ihn sicher\u00a0schon irgendwo gesehen, wenn du\u00a0in letzter Zeit in Baldurs Tor warst. Ein dunkelhaariger Elf, abartig gro\u00df und schlacksig mit Armen wie \u00c4sten und mehr T\u00e4towierungen auf seiner Haut als Kleidung. Wenn die spitzen Ohren nicht w\u00e4ren k\u00f6nnte man ihn fast f\u00fcr einen Nordl\u00e4nder halten&#8230; naja,einen rasierten Nordl\u00e4nder vielleicht. Nein, ich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-28T17:12:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-15T18:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Javier duBois\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Javier duBois\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"16\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/\"},\"author\":{\"name\":\"Javier duBois\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/6ca423eba932e65d094623c94493740c\"},\"headline\":\"Totes Pferd\",\"datePublished\":\"2015-02-28T17:12:34+00:00\",\"dateModified\":\"2018-04-15T18:42:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/\"},\"wordCount\":3290,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Totes-Pferd.png?fit=420%2C420&ssl=1\",\"articleSection\":[\"Totes Pferd (Ben)\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/\",\"name\":\"Totes Pferd - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Totes-Pferd.png?fit=420%2C420&ssl=1\",\"datePublished\":\"2015-02-28T17:12:34+00:00\",\"dateModified\":\"2018-04-15T18:42:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Totes-Pferd.png?fit=420%2C420&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/Totes-Pferd.png?fit=420%2C420&ssl=1\",\"width\":420,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/archiv\\\/inaktive_sc\\\/totes-pferd-ben\\\/totes-pferd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Totes Pferd\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/6ca423eba932e65d094623c94493740c\",\"name\":\"Javier duBois\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7019ca4adf4eaec890ba693f10351aaa58b6262e82e22dbb501f2a6f0c40692?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7019ca4adf4eaec890ba693f10351aaa58b6262e82e22dbb501f2a6f0c40692?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c7019ca4adf4eaec890ba693f10351aaa58b6262e82e22dbb501f2a6f0c40692?s=96&d=mm&r=g\",\"caption\":\"Javier duBois\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/100005853728943\"],\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/ben-kielar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Totes Pferd - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/","og_locale":"de_DE","og_type":"article","og_title":"Totes Pferd - RPG-Berlin.de","og_description":"Totes Pferd Du hast ihn sicher\u00a0schon irgendwo gesehen, wenn du\u00a0in letzter Zeit in Baldurs Tor warst. Ein dunkelhaariger Elf, abartig gro\u00df und schlacksig mit Armen wie \u00c4sten und mehr T\u00e4towierungen auf seiner Haut als Kleidung. Wenn die spitzen Ohren nicht w\u00e4ren k\u00f6nnte man ihn fast f\u00fcr einen Nordl\u00e4nder halten&#8230; naja,einen rasierten Nordl\u00e4nder vielleicht. Nein, ich [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2015-02-28T17:12:34+00:00","article_modified_time":"2018-04-15T18:42:11+00:00","og_image":[{"width":420,"height":420,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1","type":"image\/png"}],"author":"Javier duBois","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Javier duBois","Gesch\u00e4tzte Lesezeit":"16\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/"},"author":{"name":"Javier duBois","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/6ca423eba932e65d094623c94493740c"},"headline":"Totes Pferd","datePublished":"2015-02-28T17:12:34+00:00","dateModified":"2018-04-15T18:42:11+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/"},"wordCount":3290,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1","articleSection":["Totes Pferd (Ben)"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/","url":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/","name":"Totes Pferd - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1","datePublished":"2015-02-28T17:12:34+00:00","dateModified":"2018-04-15T18:42:11+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1","width":420,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/archiv\/inaktive_sc\/totes-pferd-ben\/totes-pferd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Totes Pferd"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/6ca423eba932e65d094623c94493740c","name":"Javier duBois","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c7019ca4adf4eaec890ba693f10351aaa58b6262e82e22dbb501f2a6f0c40692?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c7019ca4adf4eaec890ba693f10351aaa58b6262e82e22dbb501f2a6f0c40692?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7019ca4adf4eaec890ba693f10351aaa58b6262e82e22dbb501f2a6f0c40692?s=96&d=mm&r=g","caption":"Javier duBois"},"sameAs":["http:\/\/www.facebook.com\/100005853728943"],"url":"https:\/\/rpg-berlin.de\/rpg\/author\/ben-kielar\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2015\/02\/Totes-Pferd.png?fit=420%2C420&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-1Lv","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/6789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=6789"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/6789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/15496"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=6789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=6789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=6789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}