{"id":24933,"date":"2021-08-04T19:30:00","date_gmt":"2021-08-04T17:30:00","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=24933"},"modified":"2021-09-12T19:32:37","modified_gmt":"2021-09-12T17:32:37","slug":"der-feuerfinger-ankunft-raven-guard","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/","title":{"rendered":"Der Feuerfinger &#8211; Ankunft (Raven Guard)"},"content":{"rendered":"\n<ol class=\"wp-block-list\" start=\"11\"><li>&#8211; 12. Eleasias 1488<\/li><\/ol>\n\n\n\n<p>Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem gefl\u00fcgelten Feind nutze Xandala die Gelegenheit um gleich viele von ihnen auf einmal zu r\u00f6sten, im wahrsten Sinne des Wortes. Durch den heraufbeschworenen Feuerball entflammte allerdings auch der Urwald ringsum. Von daher war der neue Feind auch etwas lebendes, etwas \u00e4u\u00dfert unbarmherziges und zugleich kaltes. Der Waldbrand, der langsam aber sicher die Gruppe einzuholen und zu umschlie\u00dfen schien.<\/p>\n\n\n\n<p>Gl\u00fccklicherweise konnte Bee die Gruppe jedoch in eine Richtung f\u00fchren, in welcher sich auch der Fluss befand, an welchem sie ja bereits seit Tagen unterwegs gewesen waren. Also sprangen alle in die nassen Fluten und konnten somit dem tobenden Feuer entkommen. Wobei, nein. Nicht alle sind in den Fluss gesprungen. Romero ging \u00fcber das Wasser hinweg, warum und wieso auch immer, wusste keiner in diesem Moment.<br>Nun, es war auch derzeit nicht wichtig. Wichtig war es, von dem Feuer wegzukommen und die schmerzenden Glieder wie auch teilweise sehr starken Verbrennungen zu behandeln.<\/p>\n\n\n\n<p>An einer sicheren Stelle am anderen Flussufer, war die Hitze des Feuers nicht mehr stark zu sp\u00fcren, daf\u00fcr waren die rot-gelb lodernden Flammen bestens zu sehen, wie auch die enorme Rauchentwicklung, die den Himmel verdunkelte. Also wenn vorher niemand wusste, das hier jemand war, nun war dies nicht zu \u00fcbersehen. Zumindest das hier etwas los sein muss.<br>Aus den Fluten gezogen, kroch die Gruppe ein kleines St\u00fcck vom Wasser weg und schnappte nach Atem. Nicht nur durch den Schreck und der Ersch\u00f6pfung, sondern auch durch den Qualm den jeder einatmete.<br>Fitz w\u00fcrgte regelrecht und klang dazu noch heiser. Er meinte, das nicht nur seine Haut brannte, sondern auch sein Rachen. Ganz so, als ob ihn starke Halsschmerzen plagen w\u00fcrden. Bee hingegen dr\u00fcckte, nach dem Nim Ojoo seine restlich verbliebenen heilenden Worte nutze, Nim Ojoo ihre Angel in die Hand meint nur, er solle sofort Fischen gehen. Sie m\u00fcsse in den Wald und ist gleich wieder da. Nach einer kurzen Verschnaufpause baute der Rest das Lager auf, w\u00e4hrend Nim Ojoo sich die befehlenden Worte von Bee zu herzen nahm und fischen ging. Vielleicht lag es an seinem k\u00f6nnen, vielleicht an dem Feuer, vielleicht war es auch etwas anderes. Allerdings kam, fast zur gleichen Zeit mit Bee, der Elefant mit nur zwei kleinen K\u00f6derfischen zur\u00fcck. Bee hingegen hatte einen Kochtopf voller Beeren, Bl\u00e4tter, Wurzeln und was es sonst noch so gab im Urwald zur\u00fcck und fing auch direkt an, dies mit Seife, Wasser und noch etwas der Gruppe unbekanntem zu vermengen. Sie stellte eine Brandsalbe her, wie sie erkl\u00e4rte.<\/p>\n\n\n\n<p>Die Nachtruhe verging ereignislos, abgesehen von dem Waldbrand, welcher mit jeder Stunde weiter abebbte. Den noch ruhigen und von den Sonnenstrahlen in ein angenehm warmes, goldenes Licht getauchte Morgen nutzten Bee und Nim Ojoo auch gleich, um noch mal fischen zu gehen. Beide hatten auch so viel Gl\u00fcck dabei, dass sie mehrere Kocht\u00f6pfe voll von Fischen ins Lager brachten. Unter anderem waren da auch sehr seltene und unglaublich wertvolle Fische mit dabei. Jedoch, hier drau\u00dfen im Urwald waren die Fische nur f\u00fcr das \u00dcberleben wichtig, was der Gruppe auch reichte.<\/p>\n\n\n\n<p>W\u00e4hrend Bee und Nim Ojoo die Fische ausnahmen und zum verzehr, wie auch zur Lagerung vorbereiteten, ging der Rest vom Lager weg um sich zu waschen. Musharib kam als erstes zur\u00fcck und ihm lag auch ein L\u00e4cheln auf dem Gesicht, welches Nim Ojoo erwiderte. Kurz darauf kamen alle anderen zur\u00fcck. Jeder sah frisch und auch halbwegs erholt aus, nur nicht Arannis. Dieser kratze sich \u00fcberall, wo er nicht durch die lederne Kleidung und seiner R\u00fcstung bedeckt war.<br>Er ging sofort zu Musharib und flaumte diesen auch direkt an. Es entfachte sich eine kleine Diskussion zwischen den beiden und noch bevor diese endg\u00fcltig abgeschlossen war, rannte Arannis zum Fluss und sprang erneut in die Fluten. Als auch Arannis wieder kam, ohne sich st\u00e4ndig zu kratzen und auch Bee und Nim Ojoo sich gewaschen hatten, wurden alle Utensilien zusammen getragen und es ging auf dem trockenen Weg zum Feuerfinger.<\/p>\n\n\n\n<p>Durch den Waldbrand dauerte es auch gar nicht so lange, bis der Feuerfinger in Sicht kam. Eine fast senkrecht aufragende, gut 90 Meter hohe Steinnadel erhob sich inmitten eines Kohlefeldes, was mal ein Teil des m\u00e4chtigen und unber\u00fchrten Urwaldes war. Nicht nur dass die Steinnadel sehr hoch war, sie war auch noch in mehrere Etagen unterteilt. Es so von unten so aus, als ob die ersten zwei Drittel der Nadel in 3 Ebenen aufgeteilt worden ist. Zwei Strickleitern sind zu erkennen, die an der Au\u00dfenwand h\u00e4ngen und so etwas wie Balkone verbinden.<\/p>\n\n\n\n<p>Allerdings war noch kein direkter Aufstieg oder Eingang zu sichten, also wurde erst mal das Fundament umrundet. Auch wenn die Feuersbrunst heftigst gew\u00fctet hatte, so wurde ein Teil des Urwalds verschont. Daher stand der Feuerfinger nun zur H\u00e4lfte in Asche und im Wald. In dem Aschefeld konnte Romero eine kleine sich bewegende Puppe ausmachen, welche er sofort in Richtung des unber\u00fchrten Waldes verfolgte. Dort verlor er jedoch die Spur und kehrte zur Gruppe wieder zur\u00fcck. Diese fing bereits an, einen Weg in oder auf die Felsnadel zu finden.<\/p>\n\n\n\n<p>Nachdem die Felsnadel vollst\u00e4ndig umrundet worden war, wie auch mehrere nicht verbrannte Leichten gefunden wurden, stand die Gruppe vor einer Strickleiter. Allerdings, bevor mit dem Aufstieg begonnen wurde, waren die Leichen noch mal Thema. Diese sahen n\u00e4mlich so aus, als ob sie gefallen und hier unber\u00fchrt liegen gelassen worden w\u00e4ren. Von manchen Leichen waren sogar nur noch die Knochen \u00fcbrig, so lange mussten diese hier schon liegen.<\/p>\n\n\n\n<p>Na ja, es brachte alles nichts, weil es keine weiteren Anzeichen gab, was es mit den Leichen wirklich auf sich hatte, also klettere die Gruppe die Strickleiter hinauf. Hans Grauschild wurde am Fundament noch festgebunden, mit einer weiten Leine, damit er nicht weglief und sich im schlimmsten Fall noch verteidigen k\u00f6nne.<\/p>\n\n\n\n<p>Die Strickleiter war hoch und baumelte einfach nur am Fels. Sie war oben festgemacht worden, anderswo gab es jedoch keine Arretierung. Somit war das Klettern gar nicht so einfach, insbesondere die Leiter wirklich plan auf dem Felsen auflag. Dementsprechend sahen die Knie und die Kn\u00f6chel der Hand aus. Selbst Nim Ojoo, der mit Abstand der schwerste aus der Gruppe war, schaffte es allerdings ohne gro\u00dfe Hindernisse die Leiter hoch zu klettern. Allerdings merkten alle, dass die gut 18 Metern hohe Leiter nicht einfach werden w\u00fcrde, wieder hinabzuklettern.<\/p>\n\n\n\n<p>Oben angekommen er\u00f6ffnete sich der Gruppe eine H\u00f6hle, die vollkommen leer war. Nichts war hier zu finden, au\u00dfer eine 3 Meter tiefe Grube, die dazu noch 4 1\/2 Meter breit war und hinter sich einen nat\u00fcrlichen Kamin beheimatete.<\/p>\n\n\n\n<p>Arannis sprang \u00fcber die Grube und befestigte auf der anderen Seite ein Seil, welches vom Rest genutzt wurde um auch \u00fcber die Grube zu gelangen. Allerdings, wie sollten sie den nat\u00fcrlichen Kamin erklimmen?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; 12. Eleasias 1488 Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem gefl\u00fcgelten Feind nutze Xandala die Gelegenheit um gleich viele von ihnen auf einmal zu r\u00f6sten, im wahrsten Sinne des Wortes. Durch den heraufbeschworenen Feuerball entflammte allerdings auch der Urwald ringsum. [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":24934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[797],"tags":[],"class_list":["post-24933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe35"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Feuerfinger - Ankunft (Raven Guard) - RPG-Berlin.de<\/title>\n<meta name=\"description\" content=\"Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem ..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Feuerfinger - Ankunft (Raven Guard) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem ..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-04T17:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-12T17:32:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Celesil\/Cathari Leif\u2019c (Jan-Ole)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Celesil\/Cathari Leif\u2019c (Jan-Ole)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/\"},\"author\":{\"name\":\"Celesil\\\/Cathari Leif\u2019c (Jan-Ole)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/d9c6f81ba39265797b9626008f373c69\"},\"headline\":\"Der Feuerfinger &#8211; Ankunft (Raven Guard)\",\"datePublished\":\"2021-08-04T17:30:00+00:00\",\"dateModified\":\"2021-09-12T17:32:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/\"},\"wordCount\":1176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/firefinger.jpg?fit=275%2C600&ssl=1\",\"articleSection\":[\"Raven Guard\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/\",\"name\":\"Der Feuerfinger - Ankunft (Raven Guard) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/firefinger.jpg?fit=275%2C600&ssl=1\",\"datePublished\":\"2021-08-04T17:30:00+00:00\",\"dateModified\":\"2021-09-12T17:32:37+00:00\",\"description\":\"Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem ..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/firefinger.jpg?fit=275%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/firefinger.jpg?fit=275%2C600&ssl=1\",\"width\":275,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe35\\\/der-feuerfinger-ankunft-raven-guard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Feuerfinger &#8211; Ankunft (Raven Guard)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/d9c6f81ba39265797b9626008f373c69\",\"name\":\"Celesil\\\/Cathari Leif\u2019c (Jan-Ole)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5553fec83069d7f51e12fc1ee7027f7934073eaaacd46caa3fee0c734f80d79e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5553fec83069d7f51e12fc1ee7027f7934073eaaacd46caa3fee0c734f80d79e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5553fec83069d7f51e12fc1ee7027f7934073eaaacd46caa3fee0c734f80d79e?s=96&d=mm&r=g\",\"caption\":\"Celesil\\\/Cathari Leif\u2019c (Jan-Ole)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/celesil\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Feuerfinger - Ankunft (Raven Guard) - RPG-Berlin.de","description":"Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem ..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/","og_locale":"de_DE","og_type":"article","og_title":"Der Feuerfinger - Ankunft (Raven Guard) - RPG-Berlin.de","og_description":"Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem ..","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2021-08-04T17:30:00+00:00","article_modified_time":"2021-09-12T17:32:37+00:00","og_image":[{"width":275,"height":600,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1","type":"image\/jpeg"}],"author":"Celesil\/Cathari Leif\u2019c (Jan-Ole)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Celesil\/Cathari Leif\u2019c (Jan-Ole)","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/"},"author":{"name":"Celesil\/Cathari Leif\u2019c (Jan-Ole)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/d9c6f81ba39265797b9626008f373c69"},"headline":"Der Feuerfinger &#8211; Ankunft (Raven Guard)","datePublished":"2021-08-04T17:30:00+00:00","dateModified":"2021-09-12T17:32:37+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/"},"wordCount":1176,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1","articleSection":["Raven Guard"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/","name":"Der Feuerfinger - Ankunft (Raven Guard) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1","datePublished":"2021-08-04T17:30:00+00:00","dateModified":"2021-09-12T17:32:37+00:00","description":"Auch wenn der Kampf mit dem Pterafolk geschlagen war, so war die Auseinandersetzung weiterhin nicht \u00fcberstanden. In dem Kampf mit dem ..","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1","width":275,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe35\/der-feuerfinger-ankunft-raven-guard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Der Feuerfinger &#8211; Ankunft (Raven Guard)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/d9c6f81ba39265797b9626008f373c69","name":"Celesil\/Cathari Leif\u2019c (Jan-Ole)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5553fec83069d7f51e12fc1ee7027f7934073eaaacd46caa3fee0c734f80d79e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5553fec83069d7f51e12fc1ee7027f7934073eaaacd46caa3fee0c734f80d79e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5553fec83069d7f51e12fc1ee7027f7934073eaaacd46caa3fee0c734f80d79e?s=96&d=mm&r=g","caption":"Celesil\/Cathari Leif\u2019c (Jan-Ole)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/celesil\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2021\/08\/firefinger.jpg?fit=275%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-6u9","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/24933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=24933"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/24933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/24934"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=24933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=24933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=24933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}