{"id":23772,"date":"2020-04-18T23:56:00","date_gmt":"2020-04-18T21:56:00","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=23772"},"modified":"2020-07-21T10:31:27","modified_gmt":"2020-07-21T08:31:27","slug":"der-kampf-um-die-vorherrschaft-collectors","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/","title":{"rendered":"Der Kampf um die Vorherrschaft (Collectors)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Der Kampf um die Vorherrschaft (Collectors)<\/h2>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">Der Tag des Angriffs ist gekommen. Mit gemischten Gef\u00fchlen ist Postel aufgewacht, die Linie von dem was eigentlich Feind und was Freund ist verschwimmt stetig.&nbsp;Im Bund mit den Hexen sammelt die Truppe sich ihm Schwanenbot um von hinten in die Stadt vorzudringen.&nbsp;Asrock und seine M\u00e4nner sollten den Angriff von vorne unternehmen w\u00e4hrend wir von hinten die Drow \u00fcberfallen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Schwanenbot ist jeder angespannt soweit dass selbst Sir Dorn das lenken des Botes schwerf\u00e4llt und man ihn unterst\u00fctzen musste. Kurz bevor das Schwanenbot anlegegen wollteschwamm ein bekannter verfaulter Fisch an uns vorbei. &#8222;Wir haben unser Werk volbracht, der Rest h\u00e4ngt an euch&#8220; und der Fisch verschwand. Bis zum heutigen Tag bleibt es ein R\u00e4tsel ob die Hexen \u00fcberhaupt was gemacht haben.&nbsp;<br>Wir schlichen uns ein, ein paar Spinnen krabbelten als Scouts umher und eine muss sogar eliminiert werden. Wir schienen soweit gut voranzukommen aber es war zu Still, der Wind der normalerwei\u00dfe durch die G\u00e4nge br\u00fcllte ist auch erloschen ihrgendwas stimmte nicht, &#8230; dan drehte Postel sich um&nbsp;und seine nicht so Unsichtbaren Kolegen sind gegen seiner Aussage weiter vorr\u00fcckten.. in den Hinterhalt der Drow. Die Drow waren Unsichtbar und liesen sich von der Decke fallen. Creed und Naeri wurden sofort unter starken beschuss genommen.&nbsp;<br>Einer der st\u00e4rkeren K\u00e4mpfer der sich auf Creed niederlie\u00df wurde direkt von mehreren Bolzen und Brennenden Strahlen direkt erledigt und im Gang vom \u00dcberfall haben die beiden Drowkrieger auch etwas einstecken m\u00fcssen.. bis zum Event des HorrorsEtwas \u00fcbernahm die Kontrolle unserer Abenteurer, zuerst traf es Sir Dorn der aufeinaml auf Martha zurannte sich aber noch kurz vor dem Angriff selber aus der Kontrolle rei\u00dfen konnte.&nbsp;Naeri und Noah konnten sich aber nicht so schnell retten. Sie griffen sich gegenseitig an mit Lightningbolts Feuerb\u00e4llen und einem Cone of Cold der gl\u00fccklicherwei\u00dfe von Naeri aufgehalten wurde mit einem Counterspell.Postel ist wh\u00e4rendessen nach vorne gest\u00fcrmt und hat vereinzelt Drowkriger erschossen auf der Suche nach dem Magier der seine Kameraden verzaubert. Auf dem Weg fand die Gruppe die Garnision der Drow in der die Drow alle zussammen auf einem Punkt standen PERFECT f\u00fcr Creed der einen Feuerball in die Gruppe reinschmei\u00dft und inen einen Fatalen schlag verpasst.&nbsp;Postel hat fix Dornen in den Raum wachsen lassen und hat sich wieder auf die Suche begeben, Sir Dorn stellt sich vor die Garnision in Angriffstellung und der Rest der Gruppe wir die ganze Zeit \u00fcbernommen und selbst wenn sie nicht \u00fcbernommen werden haben sie angefangen sich gegenseitig zu bek\u00e4mpfen.Das gegenseitige angiften und bedrohen und zerst\u00f6ren von LEGEND\u00c4REN ROBEN hat seine spuren von missmut und paranoia hinterlassen ob vileicht diese Angriffe ein wachechter Verrat ist.&nbsp;Sir Dorn wird von den Drow die schon angesengt wurden und sich als Panikreaktion darauf Unsichtbar machten umsingelt und unter Beschuss genommen. Martha kommt aus dem Gang alleine hervor, was entweder bedeutet das sie nicht mehr kontroliert wird oder dass sie sich Naeri und Noah entledigt hat.&nbsp;Die frage ob sie \u00fcbernommen wurde war selbst dann nicht gekl\u00e4rt als sie manisch VER\u00c4TER !!!! schrie und Sir Dorn mit einem Feuerball in die Luft jagte. Postel hat in der Zwischenzeit mit schrecken erkannt das der giftige Nebel den wir das letzte mal nicht nicht ohne Martha beseitigen konnten.Aber er hatte Gl\u00fcck, der Nebel hat sich gerade erst ausgrebreitet und man kann ungef\u00e4hr erkennen wo es herkommt. Aber Postel sperrt sich erstmal in eine Sackgasse ein denn Gift ist B\u00f6se.&nbsp;Dann sammelt er all seinen Mut rennt zu dem Raum mit dem Jochlol und f\u00e4ngt an zu schie\u00dfen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?resize=600%2C600&#038;ssl=1\" alt=\"\" class=\"wp-image-23773\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?resize=270%2C270&amp;ssl=1 270w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?resize=230%2C230&amp;ssl=1 230w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption>Der Kampf um die Vorherrschaft (Collectors)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Beim Vorst\u00fcrmen wurden vereinzelte Drowkrieger schnell niedergestreckt, am der Garnision der Drow angekommen wurde die T\u00fcr von Sir Dorn aufgebrochen und Creed jagt das ganze in die Luft und Parati l\u00e4sst dornen spriesenuhm dem ganzen Chaos noch eins draufzusetzen bekamm die Gruppe besuch von 2 Jochlol. Die Jochlol haben versucht wieder den ganzen Kampfbreich in giftigem Nebel zu h\u00fcllen, das gl\u00fccklicherwei\u00dfe unterbrochen wurde. Dieses mal sind die Jochlol aber schnell hingerichtet worden.&nbsp;durch die Gruppe und einem der Zombie Beholder. Als der letzte Jochlol sein Leben lie\u00df kam auch schon Asroks Siegeschrei&nbsp;<br>Die Guppe will sich sammeln&#8230;. erfolglo\u00df. Sir Dorn hat Naeri erschlagen als er mitbekomen hat das Naeri letztenendes Noah mit einem seiner Angriffe Niedergeschlagen hat, Martha wurde auch Bewustlos geschlagen von Sir Dorn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Leichen wurden gepl\u00fcndert der Kampf war gewonnen.. aber niemand war wirklich gl\u00fccklich \u00fcber das Ende des Kampfe. Noah starb, die Sonnenelfe ist&nbsp;so verst\u00f6rt das sie nicht wirklich antworten kann und Naeri war kurz vor seiner Hinrichtung.&nbsp;<br>Naeri wurde aufgeweckt nachdem die Gruppe beschprochen hat was sie mit ihm anstellen wollten. Man sagte ihm dass er den Scimitar zur\u00fcckgeben sollte und dann durfte er nach Sch\u00e4delhafen weiterzeiehen und wir sehen uns nie wieder.&nbsp;Er antwortete nicht oder nur teilweise, als er von seinen Fesseln befreit wurde mit gez\u00fcckter Waffe auf ihn gerichtet ignorierte er alles was man ihm aufgetragen hatte.&nbsp;Er n\u00e4herte sich Noah von der er nicht wusste ob sie nur Bewustlos oder Tod ist und wurde sofort von Sir Dorn aufgehalten. Nachdem er noch ein paar feindselige Worte von ihm ge\u00e4u\u00dfert wurde wiedersetzt er sich dem Befehl den&nbsp;Scimitar fallen zu lassen und l\u00e4uft gen Flu\u00df und wurde niedergeschossen. Der Scimitar wurde ihm genommen und die Partie ist auf dem weg nach oben ins Portal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Kampf um die Vorherrschaft (Collectors) Der Tag des Angriffs ist gekommen. Mit gemischten Gef\u00fchlen ist Postel aufgewacht, die Linie von dem was eigentlich Feind und was Freund ist verschwimmt stetig.&nbsp;Im Bund mit den Hexen sammelt die Truppe sich ihm Schwanenbot um von hinten in die Stadt vorzudringen.&nbsp;Asrock und seine M\u00e4nner sollten den Angriff von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[730],"tags":[],"class_list":["post-23772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-the-halaster-group-i"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Kampf um die Vorherrschaft (Collectors) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Kampf um die Vorherrschaft (Collectors) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Der Kampf um die Vorherrschaft (Collectors) Der Tag des Angriffs ist gekommen. Mit gemischten Gef\u00fchlen ist Postel aufgewacht, die Linie von dem was eigentlich Feind und was Freund ist verschwimmt stetig.&nbsp;Im Bund mit den Hexen sammelt die Truppe sich ihm Schwanenbot um von hinten in die Stadt vorzudringen.&nbsp;Asrock und seine M\u00e4nner sollten den Angriff von [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-18T21:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-21T08:31:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/\"},\"author\":{\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\"},\"headline\":\"Der Kampf um die Vorherrschaft (Collectors)\",\"datePublished\":\"2020-04-18T21:56:00+00:00\",\"dateModified\":\"2020-07-21T08:31:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/\"},\"wordCount\":957,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1\",\"articleSection\":[\"Collectors (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/\",\"name\":\"Der Kampf um die Vorherrschaft (Collectors) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1\",\"datePublished\":\"2020-04-18T21:56:00+00:00\",\"dateModified\":\"2020-07-21T08:31:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-halaster-group-i\\\/der-kampf-um-die-vorherrschaft-collectors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Kampf um die Vorherrschaft (Collectors)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\",\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"caption\":\"Thinkleblink\\\/Dalwick (Mirko)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Kampf um die Vorherrschaft (Collectors) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/","og_locale":"de_DE","og_type":"article","og_title":"Der Kampf um die Vorherrschaft (Collectors) - RPG-Berlin.de","og_description":"Der Kampf um die Vorherrschaft (Collectors) Der Tag des Angriffs ist gekommen. Mit gemischten Gef\u00fchlen ist Postel aufgewacht, die Linie von dem was eigentlich Feind und was Freund ist verschwimmt stetig.&nbsp;Im Bund mit den Hexen sammelt die Truppe sich ihm Schwanenbot um von hinten in die Stadt vorzudringen.&nbsp;Asrock und seine M\u00e4nner sollten den Angriff von [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2020-04-18T21:56:00+00:00","article_modified_time":"2020-07-21T08:31:27+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1","type":"image\/jpeg"}],"author":"Thinkleblink\/Dalwick (Mirko)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thinkleblink\/Dalwick (Mirko)","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/"},"author":{"name":"Thinkleblink\/Dalwick (Mirko)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec"},"headline":"Der Kampf um die Vorherrschaft (Collectors)","datePublished":"2020-04-18T21:56:00+00:00","dateModified":"2020-07-21T08:31:27+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/"},"wordCount":957,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1","articleSection":["Collectors (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/","name":"Der Kampf um die Vorherrschaft (Collectors) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1","datePublished":"2020-04-18T21:56:00+00:00","dateModified":"2020-07-21T08:31:27+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-halaster-group-i\/der-kampf-um-die-vorherrschaft-collectors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Der Kampf um die Vorherrschaft (Collectors)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec","name":"Thinkleblink\/Dalwick (Mirko)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","caption":"Thinkleblink\/Dalwick (Mirko)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/05\/previewfile_1616444433.jpg?fit=600%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-6bq","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/23772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=23772"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/23772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/23773"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=23772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=23772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=23772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}