{"id":23729,"date":"2020-04-25T20:00:00","date_gmt":"2020-04-25T18:00:00","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=23729"},"modified":"2020-05-16T16:02:52","modified_gmt":"2020-05-16T14:02:52","slug":"eine-seltsame-hoehle","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/","title":{"rendered":"Eine seltsame H\u00f6hle (The Sea Goblins)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Eine seltsame H\u00f6hle (The Sea Goblins)<\/h2>\n\n\n\n<p>Thra setzte sie an der Felswand, neben dem H\u00f6hleeingan, lehnend hin. Er war fertig von den Strapatzen welche sie in der H\u00f6hle erlebt hatten. Als etwas feuchtes sein Hals ber\u00fchrte bewegte er langsam und vorsichtig seine Hand hin. Der kleine Fuchswelpe, der sich zwischen seinem Panzer und dem Umhang verkrochen hatte, sprang auf seine Hand. &#8222;Ahh dir gehen es gut kleine Welpin!&#8220; sagte er erfreut da ihr nichts Passiert war.<\/p>\n\n\n\n<p>&#8222;Gut das du haben dich versteckt hast. Menge sein passiert.&#8220; sprach die Schildkr\u00f6te zu ihr und l\u00e4chelte &#8222;Viele gef\u00e4hrliche Dinge passiert. Die nicht gut f\u00fcr dich gewesen w\u00e4ren. jaja&#8220; sagte er und erinnerte sich an den zweiten Raum den sie betraten. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTi.jpg?resize=223%2C338&#038;ssl=1\" alt=\"\" class=\"wp-image-23737\" width=\"223\" height=\"338\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTi.jpg?w=395&amp;ssl=1 395w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTi.jpg?resize=198%2C300&amp;ssl=1 198w\" sizes=\"(max-width: 223px) 100vw, 223px\" \/><figcaption>Yuan-Ti<\/figcaption><\/figure><\/div>\n\n\n\n<p>Als sie den ersten Raum verlie\u00dfen trafen sie auf einen Raum dessen Boden endlos in die Tiefen zu gehen schien. Der einzige Boden den sie hatten warren am Eingan, dem Ausgang gegen\u00fcber und einer Plattform die in der mitte des Raumes zu schweben schien, nur verbunden jeweils mit einem d\u00fcnnen Weg zum Eingang Aussgang. In der Mitte der Plattform war eine Schlangenfrau die auf die Gruppe wartete. &#8222;Du m\u00fcssen wissen kleine, die sein Gewesen Yanti. Nicht gut gewesen sein f\u00fcr dich bestimmt. Sie gewollt haben Duell mit uns.&#8220; Um genau zu sein lies sie die Gruppe erst nach einem gewonnen Duell durch. Das erste Duell durfte sich die Gruppe aussuchen. So stellte sich Gnomin Ella erstes ihr gegen\u00fcber. Sie forderte die Yantie zu einem Wettbewerb des Geschichten erz\u00e4hlens auf. Doch kaum fing es an bekam sie Lampenfieber und gab auf. Als n\u00e4chstes stellte sich der paladin Anur ihr. Diesmal gab die Yanti die Herausfforderung auf. Jeder nahm eine Kerze, Anur eine kleine dickeund die Yanti eine gro\u00dfe lange, und derjenige dessen Flame als erstes Aussging hatte verloren. &#8222;Du wissen musst Annur sein clever gewesen. Als begann wurde es sein windig uns Kerze von brannt heller und kr\u00e4ftig als ihrs. Er also einfach pusten ihre aus. Er so gewonnen. Sehr clever&#8220; lobte die Schildkr\u00f6te sein Gruppen Kamerad.<\/p>\n\n\n\n<p>Darauf hin lies die Yanti sie durch und schenkte ihnen einen Schl\u00fcssel. Als sie den weiteren Raum betraten waren sie pl\u00f6tzlich in einem Wald. &#8222;Da ist dir bestimmt gefallen h\u00e4tte. Sein fast wie Wald drau\u00dfen. Doch im Berg seltsam es sein&#8220; Als sie den wunderlichen Wald durchliefen traffen sie zu einer Lichtung mit einem Lager. Das Lager bestand aus einem Lagerfeuer, zwei Truhen und einer H\u00e4ngematte. In der Matte lag ein Saty der der gruppe einfach den n\u00e4chsten Schl\u00fcssel schenkte. Aber auch sagte das man einen zweiten brauchte den seine Schwester hatte. So fand Thra sie zwar kurz in den B\u00e4umen aber sie war schwer zu fassen und spiellte der Gruppe immer wieder gerne Streiche. W\u00e4hrend Thra sie suchte und die Elfin Mira sie mit ihrem Panfl\u00f6tenspiel hervor zu locken versuchte, stellte ihr Bruder den anderen ein R\u00e4tsel &#8218;Die dritte Aussage ist wahr, doch was ist gelogen? Was ist wahr und was nicht?&#8216;. Immer wieder kahm die Satyrin auf und war wieder und wurde sie endlich von Annur gefangen. Doch stellte es sich herraus das sie den Schl\u00fcssel nicht hatte. Doch wo war der Schl\u00fcssel und was war des R\u00e4tsels l\u00f6sung? <\/p>\n\n\n\n<p>&#8222;Du wissen musst das ich kahm auf Idee. Was ist wen er sagen das zweiter Schl\u00fcssel das sein gelogen. Ich gehen also zu Ausgang aber das seien noch verschlossen gewesen. Das sein wahr&#8220; Als kur verschwunden wahr untersuchte Anur die Truhen. die anderen drei machten es sich mit den Satyren am Lagerfeuer gem\u00fctlich. Anur versuchte eins der Truhen zu \u00f6ffnen aber versagte dabei. Nymphadora die Tabaksiedame der Schiffscrew wiederum schaffte es ohne Probleme das Schloss der Truhe zu knacken. Doch war die Truhe g\u00e4hnden leer. Als thra wieder kahm erkannten er und Ella das auf dieser Truhe ein Zauber lag &#8222;Auf Truhe waren Runen von druiden. Das sein Zauber gewesen auf Truhe der alles drin verstecken tut. Also ich zerkratzen Runen, zauber weg. Und drin sein gewesen zweiter Schl\u00fcssel&#8220; Kaum hatten sie den zweiten Schl\u00fcssel waren die satyr pl\u00f6tzlich verschwunden. Und so machte sich die Gruppe auf zum n\u00e4chsten Raum.<\/p>\n\n\n\n<p>Der n\u00e4chste Raum war wieder ein Raum mit einer Plattform. Diesesmal kam ein Engelswesen herrab gestiegen und forderte die Gruppe herraus. &#8222;Er sagen das einer k\u00e4mpfen gegen ihn muss. Der landen in H\u00f6lle. Derjenige Siegen seiner kameraden k\u00f6nnen weiter. Derjenige es nicht tun alle in H\u00f6lle landen. Dies seien nicht gut&#8220; Die Gruppe durfte rasten, durften sich aber nicht absprechen. Sollte dies passieren w\u00fcrden alle in der H\u00f6lle landen. So schwieg die gruppe die ganze Rast lang und hatten nur ihre eigenen Gedanken. nach der rast vorderte das Engelswesen auf das einer vortreten sollte. &#8222;Eella sein als erstes vorgetreten. Wohl jeder fand nicht richtig das nur sie ging. So ging alle vor. Man sehen konnte das Engel war erstaunt. Jaja, ganz verwunderlich&#8220; Als die ganze Gruppe war das Engelswesen sichtlich erastaunt aber lies alle durch ohne einen Kampf zu vordern. warnte aber die Gruppe das nur einer Gewinnen konnte.<\/p>\n\n\n\n<p>&#8222;Als wir wir betraten n\u00e4chsten Raum, wir standen in Stadt. Es immer merkw\u00fcrdiger Berg wurde.&#8220; Sie betraten pl\u00f6tzlich eine Stadt. Es war Nachts und die Stimmung war sehr bedr\u00fcckend. Thra und Ella fanden ein M\u00e4dchen in der sonst leeren Stadt. Um ihr herum waren Leichen &#8222;Sie haben Angst gehabt. Wir dachten sie in Gefahr sein. Sie deute auf Gasse. Da kahm herraus Frau mit eiserenen Panzer wie Annur haben&#8220; Als die Frau die Gasse verlies deute sie auf das M\u00e4dchen die sie haben wollte. Doch die Gruppe hielt sie auf. Die Ritterin sprach von einem Krieg um ein Artefakt. Ein Artefakt was jedem der es hatte einen Wunsch erf\u00fcllte. Die war ein krieg auf Leben und Tod. Der letzte der Stand h\u00e4tte gewonnen und w\u00fcrde das Artefakt bekommen. Bevor sie mehr sagen konnte wurde Anur fast von einem Pfeil getroffen h\u00e4tte es Nymphador es nicht mitbekommen und ihn weggerissen. Darauf hin waren aber die Ritterin und das M\u00e4dchen verschwunden. W\u00e4rend die anderen sich wunderten wo sie verschwunden waren untersuchte Nymphadora die Leichen. Allen Leichen wurde die Herzen herraus geschnitten. <\/p>\n\n\n\n<p>Bevor sie die anderen warnen konnte kippte Thra um &#8222;Ich haben gesp\u00fcrt Stich hinter Panzer. Dann alles dunkel. Gut sein das ich gefallen bin auf Bauch. Nicht das sonst h\u00e4tte zerquetscht&#8220; Thra wurde von dem M\u00e4dchen angegriffen was sich als Assasinen heraustellte. Nun war die Gruppe im kampf mit ihr und ihren vergifteten Dolchen die auch Nymphador zu sp\u00fcren behahm. Miraka schaffte es wieder Thra zu heilen und gemeinsam konnte die Gruppe sie bek\u00e4mpfen. Als die Assasinen besiegt war tauchte pl\u00f6tzlich die Ritterin wieder auf und die Sch\u00fctzin, die eine Zentaurin war, die Anur angegriffen hatte. Die beiden bek\u00e4mpften sich aber auch die Gruppe. Mit erheblicher anstrengung schaffte es die Gruppe aber sie zu bek\u00e4mpfen. Zwar lag nach dem Kampf Thra wieder am Boden aber es ging ihm gut. Nach die Ritterin und und die Bogensch\u00fctzen besigt war ein ein lila Mond. Das besagte Artefakt. Nachdem sie das Artefakt erhielten waren sie wieder urpl\u00f6tzlich Vorm Eingang der H\u00f6hle.<\/p>\n\n\n\n<p>&#8222;Und sein wir wieder hier. Wir noch uns ein wenig m\u00fcssen erholen. Aber uns gehen gut.&#8220; sagte Thra und strechelte vorsichtig die kleine Fuchs Welpin. Und er fragte sich was sonst noch so alles passieren k\u00f6nnte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine seltsame H\u00f6hle (The Sea Goblins) Thra setzte sie an der Felswand, neben dem H\u00f6hleeingan, lehnend hin. Er war fertig von den Strapatzen welche sie in der H\u00f6hle erlebt hatten. Als etwas feuchtes sein Hals ber\u00fchrte bewegte er langsam und vorsichtig seine Hand hin. Der kleine Fuchswelpe, der sich zwischen seinem Panzer und dem Umhang [&hellip;]<\/p>\n","protected":false},"author":157,"featured_media":23740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[679],"tags":[],"class_list":["post-23729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grupp24"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine seltsame H\u00f6hle (The Sea Goblins) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine seltsame H\u00f6hle (The Sea Goblins) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Eine seltsame H\u00f6hle (The Sea Goblins) Thra setzte sie an der Felswand, neben dem H\u00f6hleeingan, lehnend hin. Er war fertig von den Strapatzen welche sie in der H\u00f6hle erlebt hatten. Als etwas feuchtes sein Hals ber\u00fchrte bewegte er langsam und vorsichtig seine Hand hin. Der kleine Fuchswelpe, der sich zwischen seinem Panzer und dem Umhang [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-25T18:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-16T14:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"319\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lucc de Carpon\/ Thra (Jan W)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucc de Carpon\/ Thra (Jan W)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/\"},\"author\":{\"name\":\"Lucc de Carpon\\\/ Thra (Jan W)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/da1f1beb01eb089d951251ef508f71be\"},\"headline\":\"Eine seltsame H\u00f6hle (The Sea Goblins)\",\"datePublished\":\"2020-04-25T18:00:00+00:00\",\"dateModified\":\"2020-05-16T14:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/\"},\"wordCount\":1279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/YuanTiToken.png?fit=319%2C474&ssl=1\",\"articleSection\":[\"The sea goblins\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/\",\"name\":\"Eine seltsame H\u00f6hle (The Sea Goblins) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/YuanTiToken.png?fit=319%2C474&ssl=1\",\"datePublished\":\"2020-04-25T18:00:00+00:00\",\"dateModified\":\"2020-05-16T14:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/YuanTiToken.png?fit=319%2C474&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/YuanTiToken.png?fit=319%2C474&ssl=1\",\"width\":319,\"height\":474},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/grupp24\\\/eine-seltsame-hoehle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine seltsame H\u00f6hle (The Sea Goblins)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/da1f1beb01eb089d951251ef508f71be\",\"name\":\"Lucc de Carpon\\\/ Thra (Jan W)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df40792ac20bd889e1b61613b42f3bd05d2fec4f169133f25118095e38504cf3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df40792ac20bd889e1b61613b42f3bd05d2fec4f169133f25118095e38504cf3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/df40792ac20bd889e1b61613b42f3bd05d2fec4f169133f25118095e38504cf3?s=96&d=mm&r=g\",\"caption\":\"Lucc de Carpon\\\/ Thra (Jan W)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/jan-wodrich\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine seltsame H\u00f6hle (The Sea Goblins) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/","og_locale":"de_DE","og_type":"article","og_title":"Eine seltsame H\u00f6hle (The Sea Goblins) - RPG-Berlin.de","og_description":"Eine seltsame H\u00f6hle (The Sea Goblins) Thra setzte sie an der Felswand, neben dem H\u00f6hleeingan, lehnend hin. Er war fertig von den Strapatzen welche sie in der H\u00f6hle erlebt hatten. Als etwas feuchtes sein Hals ber\u00fchrte bewegte er langsam und vorsichtig seine Hand hin. Der kleine Fuchswelpe, der sich zwischen seinem Panzer und dem Umhang [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2020-04-25T18:00:00+00:00","article_modified_time":"2020-05-16T14:02:52+00:00","og_image":[{"width":319,"height":474,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1","type":"image\/png"}],"author":"Lucc de Carpon\/ Thra (Jan W)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Lucc de Carpon\/ Thra (Jan W)","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/"},"author":{"name":"Lucc de Carpon\/ Thra (Jan W)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/da1f1beb01eb089d951251ef508f71be"},"headline":"Eine seltsame H\u00f6hle (The Sea Goblins)","datePublished":"2020-04-25T18:00:00+00:00","dateModified":"2020-05-16T14:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/"},"wordCount":1279,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1","articleSection":["The sea goblins"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/","name":"Eine seltsame H\u00f6hle (The Sea Goblins) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1","datePublished":"2020-04-25T18:00:00+00:00","dateModified":"2020-05-16T14:02:52+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1","width":319,"height":474},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/grupp24\/eine-seltsame-hoehle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Eine seltsame H\u00f6hle (The Sea Goblins)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/da1f1beb01eb089d951251ef508f71be","name":"Lucc de Carpon\/ Thra (Jan W)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/df40792ac20bd889e1b61613b42f3bd05d2fec4f169133f25118095e38504cf3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/df40792ac20bd889e1b61613b42f3bd05d2fec4f169133f25118095e38504cf3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/df40792ac20bd889e1b61613b42f3bd05d2fec4f169133f25118095e38504cf3?s=96&d=mm&r=g","caption":"Lucc de Carpon\/ Thra (Jan W)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/jan-wodrich\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/04\/YuanTiToken.png?fit=319%2C474&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-6aJ","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/23729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/157"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=23729"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/23729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/23740"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=23729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=23729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=23729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}