{"id":22856,"date":"2020-02-07T20:00:00","date_gmt":"2020-02-07T19:00:00","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=22856"},"modified":"2020-02-28T08:41:05","modified_gmt":"2020-02-28T07:41:05","slug":"die-jagd-nach-den-dreien-the-guardians","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/","title":{"rendered":"Die Jagd nach den Dreien (The Guardians)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Die Jagd nach den Dreien (The Guardians)<\/h2>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?resize=300%2C300&#038;ssl=1\" alt=\"\" class=\"wp-image-22857\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?resize=270%2C270&amp;ssl=1 270w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?resize=230%2C230&amp;ssl=1 230w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?w=600&amp;ssl=1 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>In den Katakomben von dem Badehaus stank es nach F\u00e4kalien,\nBlut und Tod. Mit den F\u00e4kalien komme ich noch klar, aber mit dem Rest? Es ist,\nals ob die Steine selbst das B\u00f6se angenommen haben. Bei dem Wasser selbst habe\nich das Gef\u00fchl, dass es verderbt ist. Wie der Rest der Stadt. Wir waren hier,\num die Anh\u00e4nger der drei verderbten G\u00f6tter zu jagen. Bhaal, Bane und Myrkul.\nWie ich diese G\u00f6tter hasse. Denen geht es nur um ihren eigenen Gewinn und\nwollen daf\u00fcr eine ganze Stadt ins Verderben bringen. &nbsp;Und darum sind wir hier. Die Reinigung der\nStadt vor den \u00dcbeln. Mag sein, dass man mich f\u00fcr eine Fanatikerin h\u00e4lt. Aber Lathander\nhat mich vermutlich f\u00fcr einen weiteren Grund zur\u00fcck ins Leben geholt.\nVermutlich, um meine Heimat zu sch\u00fctzen. Darum bin ich hier. Bereit, diese\nStadt von dem \u00dcbeln zu befreien, dass die einfachen Leute wieder sicher in den\nStra\u00dfen der Stadt gehen k\u00f6nnen. Egal, ob Selune oder S\u00fbne \u00fcber die Stadt wacht.\n<\/p>\n\n\n\n<p><strong>Da<em>s Opfer der Folter<\/em><\/strong>:<\/p>\n\n\n\n<p>Und so sind wir hier. In den Abw\u00e4ssern von dem Badehaus. Vor uns drei Gestalten. Die eine Gestalt war ein Mann, welcher an Ketten gefesselt war und einen dunklen Sack \u00fcber den Kopf hatte. Davor waren zwei Kuttentr\u00e4ger, welche die gefesselten Gestalt qu\u00e4lten. Wir mussten eingreifen. W\u00e4hrend Maevina mit ihrer Handarmbrust aus der Distanz angriff, versuchte ich Feaharn mit einem Zauber zu sch\u00fctzen. Arramior lies seine Pfeile fliegen und Anakis unterst\u00fctzte uns mit ihren Kr\u00e4ften der Natur. Feaharn st\u00fcrmte auf die Gegnerin zu und ich rannte an seine Seite. K\u00fcmmerte mich um die andere Gegnerin, damit die Kultisten nicht die anderen angreifen k\u00f6nnen. Es war ein kurzer, aber blutiger Kampf. Zumal noch schwebende Dolche beschworen wurden, die uns angreifen. Der Pflanzenwachstum schaffte es nicht, die Dolche zu behindern. Doch nach dem die zweite Kuttentr\u00e4gerin ihre verderbte Seele zu Kelemvor schickte, l\u00f6sten sie sich auf. <\/p>\n\n\n\n<p>Der Mann selber, den wir retteten, stellte sich als Klim Jhasso vor. Einer der Adligen aus der Stadt. Wir gaben ihm ein Schild und eine einfache Waffe, damit er sich verteidigen konnte. Die wunden konnten versorgt werden und wir gingen weiter. Der Adlige mit der Fackel in der Hand sollte noch f\u00fcr eine kleine unangenehme \u00dcberraschung sorgen. Eine \u00dcberraschung, f\u00fcr die er nichts konnte. In einem Gang rochen wir faulige, abgestandene Luft. Als wir die T\u00fcr \u00f6ffneten und die Fackel n\u00e4her kam, gab es eine Explosion und der Gang fiel in sich zusammen. <\/p>\n\n\n\n<p><strong><em>Des Zombies letzten Atemzug<\/em><\/strong>:<\/p>\n\n\n\n<p> Es gab nicht viele Verletzungen. Wir beschlossen, dass Klim dort wo wir ihn gefunden haben, auf uns wartet und gingen weiter. Wir folgten einer Treppe und ein Gemurmel erregte unser Interesse. Und wir sahen eine Dame, welche gerade dabei ist, einen gro\u00dfen Zombie zu beschw\u00f6ren. Ich hasse Untote. Sie sind eine Perversion des Lebens. Und so griffen wir an. Das Licht meines Gottes war mit wohlgesonnen und ich konnte den Zombie zur\u00fcck in sein Grab schicken. Maevina zog es vor, aus dem Schatten anzugreifen. Feaharn selber sch\u00fctzte ich erneut mit einem einfach Zauber. Doch untote Ratten kamen auf uns zu, aber mit der Magie von Anakis konnte der Schwarm aus knochenartigen Ratten schnell vernichtet werden. Auch die Nekromantin hauchte ihren letzten Atemzug aus. Eine Robe und ein Zauberbuch fielen zu Boden. <\/p>\n\n\n\n<p>Eigentlich hatte ich gedacht, dass mit der Zeit die neuen Abenteurer dazu gelernt haben und nicht einfach so irgendwelche Gegenst\u00e4nde ber\u00fchren. Aber ich sollte mich irren. Richtig einer ber\u00fchrte das Buch und wurde entsprechend verletzt. Das Buch und die Robe waren durch die Bank weg B\u00f6se. Es gab keine andere Wahl. Es musste verbrannt werden. Etwas, was Anakis mit gro\u00dfer Freude erledigte. Feaharn wurde verarztet und wir gingen weiter. Maevina war unsere Augen in diesen Katakomben. <\/p>\n\n\n\n<p><strong><em>Weitere G\u00e4nge<\/em><\/strong>:<\/p>\n\n\n\n<p> Die G\u00e4nge f\u00fchrten uns immer weiter und tiefer in die Katakomben. Hinter einer T\u00fcr h\u00f6rten und sahen wir weitere Schw\u00e4rme von untoten Ratten. Feaharn stellte die vorderste reihe und Anakis lies ihr Feuer in die Gruppe fahren. Und durch mich fuhr der Zorn von Lathander und heiliges Feuer regnete auf die untoten Ratten hinab. Die, welche \u00fcberlebt haben, flohen. Und unsere Verfolgung endete in einer Sackgasse. Mit einem Sarkophag aus Stein. In dem Sarkophag war jemand begraben und eine magische Axt scheint den Ort zu besch\u00fctzen. Dann sollten wir die Toten ruhen lassen. <\/p>\n\n\n\n<p><strong><em>Leben und Tod<\/em><\/strong>:<\/p>\n\n\n\n<p>Der Weg f\u00fchrte uns durch die nassen G\u00e4nge wieder zur\u00fcck. Zu einem weiteren Raum, wo ein Altar stand. Auf dem Altar stehen schwarze Kerzen und dem gegen\u00fcber ein Haufen von Knochen. Eine Untersuchung ergab, dass es ein Altar von Myrkul, m\u00f6gen seine Knochen endlich verrotten, war. Diese L\u00e4sterung an das Leben musste vernichtet werden und diesen Unmut gab ich auch bekannt. Das war vermutlich ein Signal f\u00fcr die Druidin gewesen. Mit ihrem Feuer entz\u00fcndete sie die Kerzen auf dem Altar. \u201eBezahlt den preis und Ihr k\u00f6nnt gehen.\u201c Dieser Satz erschien in dunkler unheilvoller Farbe auf der Mauer \u00fcber dem Altar. Maevina las den Satz vor und wie sollte es auch anders kommen? Richtig. Aus dem Knochenhaufen erschienen drei Skelette, welche uns t\u00f6ten wollen. Was auch sonst? Die Kerzen konnte ich auch schnell l\u00f6schen. <\/p>\n\n\n\n<p>Mit ihrer Magie sorgte Anakis daf\u00fcr, dass die Skelette zu Boden gingen und mit stumpfen oder magischen Waffen konnten wir auch dieser Bedrohung Herr werden. Auch der Altar wurde vernichtet. Doch wir alle konnten eine Pause gebrauchen. Ich sp\u00fcrte, wie das Licht in mir st\u00e4rker wurde. Meine Kr\u00e4fte immer wieder st\u00e4rker wurden und ich mich auch an Zauberspr\u00fcche erinnere, welche ich vor \u00fcber einem Jahrhundert gewirkt habe. Doch wir haben noch eine Menge Arbeit vor uns und stehen immer noch am Anfang. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Jagd nach den Dreien (The Guardians) In den Katakomben von dem Badehaus stank es nach F\u00e4kalien, Blut und Tod. Mit den F\u00e4kalien komme ich noch klar, aber mit dem Rest? Es ist, als ob die Steine selbst das B\u00f6se angenommen haben. Bei dem Wasser selbst habe ich das Gef\u00fchl, dass es verderbt ist. Wie [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[709],"tags":[],"class_list":["post-22856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe30"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Jagd nach den Dreien (The Guardians) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Jagd nach den Dreien (The Guardians) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Die Jagd nach den Dreien (The Guardians) In den Katakomben von dem Badehaus stank es nach F\u00e4kalien, Blut und Tod. Mit den F\u00e4kalien komme ich noch klar, aber mit dem Rest? Es ist, als ob die Steine selbst das B\u00f6se angenommen haben. Bei dem Wasser selbst habe ich das Gef\u00fchl, dass es verderbt ist. Wie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-07T19:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-28T07:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aurora \/ Delia(Sebastian)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aurora \/ Delia(Sebastian)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/\"},\"author\":{\"name\":\"Aurora \\\/ Delia(Sebastian)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/f4119000f772e0fdc40b614851833b22\"},\"headline\":\"Die Jagd nach den Dreien (The Guardians)\",\"datePublished\":\"2020-02-07T19:00:00+00:00\",\"dateModified\":\"2020-02-28T07:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/\"},\"wordCount\":1009,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Myrkul.jpg?fit=600%2C600&ssl=1\",\"articleSection\":[\"The Guardians (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/\",\"name\":\"Die Jagd nach den Dreien (The Guardians) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Myrkul.jpg?fit=600%2C600&ssl=1\",\"datePublished\":\"2020-02-07T19:00:00+00:00\",\"dateModified\":\"2020-02-28T07:41:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Myrkul.jpg?fit=600%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Myrkul.jpg?fit=600%2C600&ssl=1\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/die-jagd-nach-den-dreien-the-guardians\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Jagd nach den Dreien (The Guardians)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/f4119000f772e0fdc40b614851833b22\",\"name\":\"Aurora \\\/ Delia(Sebastian)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81de071c7d49fd206550a3ccc5351beeabaeb2f864c7432f164199e3d0eb7a9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81de071c7d49fd206550a3ccc5351beeabaeb2f864c7432f164199e3d0eb7a9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81de071c7d49fd206550a3ccc5351beeabaeb2f864c7432f164199e3d0eb7a9b?s=96&d=mm&r=g\",\"caption\":\"Aurora \\\/ Delia(Sebastian)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/mondsilber\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Jagd nach den Dreien (The Guardians) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/","og_locale":"de_DE","og_type":"article","og_title":"Die Jagd nach den Dreien (The Guardians) - RPG-Berlin.de","og_description":"Die Jagd nach den Dreien (The Guardians) In den Katakomben von dem Badehaus stank es nach F\u00e4kalien, Blut und Tod. Mit den F\u00e4kalien komme ich noch klar, aber mit dem Rest? Es ist, als ob die Steine selbst das B\u00f6se angenommen haben. Bei dem Wasser selbst habe ich das Gef\u00fchl, dass es verderbt ist. Wie [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2020-02-07T19:00:00+00:00","article_modified_time":"2020-02-28T07:41:05+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1","type":"image\/jpeg"}],"author":"Aurora \/ Delia(Sebastian)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Aurora \/ Delia(Sebastian)","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/"},"author":{"name":"Aurora \/ Delia(Sebastian)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/f4119000f772e0fdc40b614851833b22"},"headline":"Die Jagd nach den Dreien (The Guardians)","datePublished":"2020-02-07T19:00:00+00:00","dateModified":"2020-02-28T07:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/"},"wordCount":1009,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1","articleSection":["The Guardians (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/","name":"Die Jagd nach den Dreien (The Guardians) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1","datePublished":"2020-02-07T19:00:00+00:00","dateModified":"2020-02-28T07:41:05+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/die-jagd-nach-den-dreien-the-guardians\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Die Jagd nach den Dreien (The Guardians)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/f4119000f772e0fdc40b614851833b22","name":"Aurora \/ Delia(Sebastian)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/81de071c7d49fd206550a3ccc5351beeabaeb2f864c7432f164199e3d0eb7a9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81de071c7d49fd206550a3ccc5351beeabaeb2f864c7432f164199e3d0eb7a9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81de071c7d49fd206550a3ccc5351beeabaeb2f864c7432f164199e3d0eb7a9b?s=96&d=mm&r=g","caption":"Aurora \/ Delia(Sebastian)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/mondsilber\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2020\/02\/Myrkul.jpg?fit=600%2C600&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-5WE","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/22856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=22856"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/22856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/22857"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=22856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=22856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=22856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}