{"id":22031,"date":"2019-12-20T23:00:00","date_gmt":"2019-12-20T22:00:00","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=22031"},"modified":"2019-12-27T22:18:59","modified_gmt":"2019-12-27T21:18:59","slug":"erkundigungen-und-vorbereitungen-the-guardians","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/","title":{"rendered":"Erkundigungen und Vorbereitungen (The Guardians)"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Erkundigungen und Vorbereitungen (The Guardians)<\/h1>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"600\" height=\"413\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?resize=600%2C413&#038;ssl=1\" alt=\"Erkundigungen und Vorbereitungen (The Guardians)\" class=\"wp-image-22045\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?resize=300%2C207&amp;ssl=1 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption> Erkundigungen und Vorbereitungen (The Guardians) <\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Der Neue<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In den fr\u00fchen Morgenstunden treffen wir uns alle wieder im Gastraum der Taverne &#8222;Elfsong&#8220;. Beim Berichten unserer Erkundigungen, tritt ein Mensch in einer R\u00fcstung mit einem Zweih\u00e4nder und Narben auf den Armen an unseren Tisch heran. Er stellt sich als Feaharn L\u00e0thspell, ein D\u00e4monenj\u00e4ger, vor. Er hatte geh\u00f6rt, da\u00df wir Kampfkraft-Unterst\u00fctzung suchen. Die Gruppe hat nichts dagegen, aber den Lohn f\u00fcr seine M\u00fchen soll er mit dem Stellvertreten Kommandanten der Flaming Fist aushandeln. Dies tut er am Morgen, nachdem die Sonne aufgegangen ist, auch. Er erh\u00e4lt zudem auch Informationen, da\u00df hier in Baldurs Gate alles langsam ins Chaos versinkt und da\u00df er die Avatare der DREI (Toteng\u00f6tter: Bane, Bhaal und Myrkul) t\u00f6ten und Elturel befreien. Tr\u00e4nke kann man ihm nicht geben bzw. diese sind zu teuer, aber er erh\u00e4lt einen sehr guten Streitkolben und die Information, da\u00df er bei Terina in der Elfsong-Taverne zus\u00e4tzliche Infos und ggf. Tr\u00e4nke erhalten kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Zwischenzeit \u00fcberlegen wir, was f\u00fcr Vorbereitungen f\u00fcr den Kampf gegen die Diener der Toteng\u00f6tter notwendig ist und wie wir uns vorbereiten k\u00f6nnen. Dabei wei\u00df Camilla, da\u00df man Skelette eher mit stumpfen Hiebwaffen effektiv bel\u00e4mpft und bei Untoten man kein Gift verwenden sollte. Wir ben\u00f6tigen Antidots, Weihwasser und Tr\u00e4nke gegen Seuchen und Krankheiten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tempeltour<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Camilla und Arramior gehen dann nach Sonnenaufgang in den Tempel des Lathander, um Informationen einzuholen und ggf. Tr\u00e4nke und Weihwasser zu bekommen. Camilla trifft dort ihren Meister Kelddath Ormlyr (Hohepriester) und dessen ehemaligem Leibw\u00e4chter Taerom &#8222;Thunderhammer&#8220; Fuiruim wieder. Beide sind schon sehr alt. Das letzte Mal als sie sich gesehen haben ist schon \u00fcber 100 Jahre her. Kelddath Ormlyr ist der Meinung, da\u00df die Anh\u00e4nger der DREI vlt. einen  Pakt mit den D\u00e4monen au\u00dferhalb der Stadt geschlossen haben. Er denkt, da\u00df Beste w\u00e4re, die DREI gegeneinander auszuspielen, damit sie sich gegenseitig dezimieren. Auch k\u00f6nnte man in der Oberstadt weitere Infos einholen, da sich verw\u00f6hnte Jungadlige vlt. den Kulten der DREI angeschlossen haben, um gegen ihre  Eltern sich aufzulehnen. Von ihm erhalten Camilla 10 Phiolen Weihwasser und Arramior des legend\u00e4re Langschwert &#8222;Defender&#8220; als Leihgabe von Kelddath pers\u00f6nlich. <\/p>\n\n\n\n<div class=\"wp-block-image is-style-default\"><figure class=\"aligncenter size-medium\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/Defender_Longsword.png?resize=300%2C300&#038;ssl=1\" alt=\"Das legend\u00e4re Langschwert Defender\" class=\"wp-image-22033\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/Defender_Longsword.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/Defender_Longsword.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/Defender_Longsword.png?resize=270%2C270&amp;ssl=1 270w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/Defender_Longsword.png?resize=230%2C230&amp;ssl=1 230w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/Defender_Longsword.png?w=600&amp;ssl=1 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption>Das legend\u00e4re Langschwert &#8222;Defender&#8220;<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> Leider bekommen sie von Taerom &#8222;Thunderhammer&#8220; Fuiruim keine Neuigkeiten, da dieser scheinbar schon sehr senil ist und ehrer in der Vergangenheit (in Beregost) lebt. Nach einem Gebet gehen sie zur\u00fcck zur Taverne. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Feaharn trifft sich w\u00e4hrenddessen mit Terina und mu\u00df erst einmal mit ihr spielen. Leider gab es keine neue Information.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fliegende Kundschafter<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Anakis kundschaftet, als Fliege, derweil das Badehaus auf dem Anwesen des Duke of Thalamra Vanthampur aus. Sie findet heraus, da\u00df immer 3 Wachen von &#8222;Nightblade&#8220; (Niederes Fu\u00dfvolk von Bane oder Bhaal, arbeiten gern mit Giften) in der N\u00e4he eines Sees auf dem Grundst\u00fcck aufhalten. Diese werden in regelm\u00e4\u00dfigen Abst\u00e4nden von 3 Anderen Mitglieder von Nightblade, in Lederr\u00fcstungen mit Dolchen und Kurzschwertern, abgel\u00f6st. Diese gelten als ausgebildete Spezialisten der Abwehr. An der Nordwand des n\u00f6rdlichen Massageraumes findet sie eine Geheimt\u00fcr, aus der ein fauliger, kanalartiger Gestank str\u00f6mt, mit einer Treppe in die Tiefe. An den W\u00e4nden befinden sich Wandleuchter. Sie kommt zur\u00fcck und teilt uns dies mit.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Und nun &#8230;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sind uns nun unschl\u00fcssig, wie wir weiter vorgehen wollen: Angriff oder sie gegeneinander ausspielen?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erkundigungen und Vorbereitungen (The Guardians) Der Neue In den fr\u00fchen Morgenstunden treffen wir uns alle wieder im Gastraum der Taverne &#8222;Elfsong&#8220;. Beim Berichten unserer Erkundigungen, tritt ein Mensch in einer R\u00fcstung mit einem Zweih\u00e4nder und Narben auf den Armen an unseren Tisch heran. Er stellt sich als Feaharn L\u00e0thspell, ein D\u00e4monenj\u00e4ger, vor. Er hatte geh\u00f6rt, [&hellip;]<\/p>\n","protected":false},"author":166,"featured_media":22045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[709],"tags":[],"class_list":["post-22031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe30"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erkundigungen und Vorbereitungen (The Guardians) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erkundigungen und Vorbereitungen (The Guardians) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Erkundigungen und Vorbereitungen (The Guardians) Der Neue In den fr\u00fchen Morgenstunden treffen wir uns alle wieder im Gastraum der Taverne &#8222;Elfsong&#8220;. Beim Berichten unserer Erkundigungen, tritt ein Mensch in einer R\u00fcstung mit einem Zweih\u00e4nder und Narben auf den Armen an unseren Tisch heran. Er stellt sich als Feaharn L\u00e0thspell, ein D\u00e4monenj\u00e4ger, vor. Er hatte geh\u00f6rt, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-20T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-27T21:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"413\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mardred (Oli)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mardred (Oli)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/\"},\"author\":{\"name\":\"Mardred (Oli)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/a8dbff33826d316bcc1327abcd75d632\"},\"headline\":\"Erkundigungen und Vorbereitungen (The Guardians)\",\"datePublished\":\"2019-12-20T22:00:00+00:00\",\"dateModified\":\"2019-12-27T21:18:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/\"},\"wordCount\":584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1\",\"articleSection\":[\"The Guardians (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/\",\"name\":\"Erkundigungen und Vorbereitungen (The Guardians) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1\",\"datePublished\":\"2019-12-20T22:00:00+00:00\",\"dateModified\":\"2019-12-27T21:18:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1\",\"width\":600,\"height\":413},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe30\\\/erkundigungen-und-vorbereitungen-the-guardians\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erkundigungen und Vorbereitungen (The Guardians)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/a8dbff33826d316bcc1327abcd75d632\",\"name\":\"Mardred (Oli)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/182c823844859dd99e528dba05b2f73def4acded2d76ec3c11cc7d1b9f1b6d09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/182c823844859dd99e528dba05b2f73def4acded2d76ec3c11cc7d1b9f1b6d09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/182c823844859dd99e528dba05b2f73def4acded2d76ec3c11cc7d1b9f1b6d09?s=96&d=mm&r=g\",\"caption\":\"Mardred (Oli)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/grahammcfergash\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erkundigungen und Vorbereitungen (The Guardians) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/","og_locale":"de_DE","og_type":"article","og_title":"Erkundigungen und Vorbereitungen (The Guardians) - RPG-Berlin.de","og_description":"Erkundigungen und Vorbereitungen (The Guardians) Der Neue In den fr\u00fchen Morgenstunden treffen wir uns alle wieder im Gastraum der Taverne &#8222;Elfsong&#8220;. Beim Berichten unserer Erkundigungen, tritt ein Mensch in einer R\u00fcstung mit einem Zweih\u00e4nder und Narben auf den Armen an unseren Tisch heran. Er stellt sich als Feaharn L\u00e0thspell, ein D\u00e4monenj\u00e4ger, vor. Er hatte geh\u00f6rt, [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2019-12-20T22:00:00+00:00","article_modified_time":"2019-12-27T21:18:59+00:00","og_image":[{"width":600,"height":413,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1","type":"image\/jpeg"}],"author":"Mardred (Oli)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mardred (Oli)","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/"},"author":{"name":"Mardred (Oli)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/a8dbff33826d316bcc1327abcd75d632"},"headline":"Erkundigungen und Vorbereitungen (The Guardians)","datePublished":"2019-12-20T22:00:00+00:00","dateModified":"2019-12-27T21:18:59+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/"},"wordCount":584,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1","articleSection":["The Guardians (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/","name":"Erkundigungen und Vorbereitungen (The Guardians) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1","datePublished":"2019-12-20T22:00:00+00:00","dateModified":"2019-12-27T21:18:59+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1","width":600,"height":413},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe30\/erkundigungen-und-vorbereitungen-the-guardians\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Erkundigungen und Vorbereitungen (The Guardians)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/a8dbff33826d316bcc1327abcd75d632","name":"Mardred (Oli)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/182c823844859dd99e528dba05b2f73def4acded2d76ec3c11cc7d1b9f1b6d09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/182c823844859dd99e528dba05b2f73def4acded2d76ec3c11cc7d1b9f1b6d09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/182c823844859dd99e528dba05b2f73def4acded2d76ec3c11cc7d1b9f1b6d09?s=96&d=mm&r=g","caption":"Mardred (Oli)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/grahammcfergash\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/12\/murderous-servants-of-the-dead-three-corner-their-prey-near_rh4r.1080.jpg?fit=600%2C413&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-5Jl","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/22031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/166"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=22031"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/22031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/22045"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=22031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=22031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=22031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}