{"id":18693,"date":"2018-08-25T20:19:23","date_gmt":"2018-08-25T18:19:23","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=18693"},"modified":"2018-09-08T22:15:02","modified_gmt":"2018-09-08T20:15:02","slug":"das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/","title":{"rendered":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats)<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Das n\u00e4chste Vorhaben<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nach den Geschehnissen in der Kanalisation und den danach folgenden Erkenntnissen erwachte ich erneut in dem Haus von Laurenzio und Schall und Rauch auf. Zu meinem Erstaunen, sah ich Tulwar ersch\u00f6pft\u00a0 wach liegen, blass wie eine Wasserleiche und von Schwei\u00df bedeckt.<br\/>W\u00e4hrend wir gegessen haben brachten wir Tulwar auf den Stand der Dinge: die Infiltrierung in die Stadt der Feinde, selbst gemachte Schlangentattoos und die teilweise Zerst\u00f6rung der Stadt durch unser Eindringen in die tieferen Teile der Kanalisation.<br\/>Nach alldem begann Tulwar langsam wieder Farbe zu bekommen, aber mir fiel auf das sowohl Blinki als auch Schall und Rauch nicht bei uns waren, es schien als w\u00e4ren sie noch nicht wieder zur\u00fcck von dem Besuch des Freudenhauses.<br\/>Auf Grund des Standortes, den sie aufsuchten, entschlossen wir uns der Sache nicht weiter anzugehen und ihnen ihren &#8222;Stress-Abbau&#8220; zu lassen und stattdessen uns Gedanken zu machen was unser n\u00e4chster Plan ist.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Das schwarze Brett und das S\u00f6ldnerhaus<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ideen reichten von direkten Angriffen zu Guerrilla Taktiken, aber nichts \u00fcberzeugte uns komplett. W\u00e4hrend der Diskussion kam Laurenzius dazu und schlug vor einige Tage es ruhig angehen zu lassen und uns vielleicht in die Stadt zu integrieren. Daraufhin erz\u00e4hlte er uns von einem schwarzem Brett, bei dem allerlei an Auftr\u00e4gen und Aufgaben aush\u00e4ngen, die von den Einwohnern und der Stadt selbst aufgegeben wurden.<br\/>Das erf\u00fcllen dieser Auftr\u00e4ge w\u00fcrde einem die Gunst der Stadt gewinnen und sogar M\u00f6glichkeiten des Aufstiegs geben.<br\/>Um dort jedoch Auftr\u00e4ge annehmen zu d\u00fcrfen sollte man sich bei dem S\u00f6ldnerhaus regestrieren, denn das Brett wird von den Yuanti \u00fcberwacht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir entschlossen uns der Sache mal anzugehen und begaben uns zum S\u00f6ldnerhaus, dort empfing uns eine kleine Tabaxxi Dame namens Board.<br\/>Unter genauerer Betrachtung fielen mir eine Vielzahl an kleinen Taschen auf und die eine oder andere verstecke Waffen an ihr.<br\/>Auch war das Geb\u00e4ude gef\u00fcllt von allerlei Rassen mit unterschiedlichster Ausr\u00fcstung, was zu erwarten war in solch einer Unterkunft.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Board stellte uns Fragen zu unseren Kampferfahrungen, Gruppentauglichkeit und zu den Tattoos. Wir erkl\u00e4rten ihr, dass wir unsere selbst gemacht h\u00e4tten, mit der Begr\u00fcndung es w\u00fcrde eins gebraucht werden in der Stadt. Dies schien sie jedoch nicht zu \u00fcberraschen, da wir nicht ersten w\u00e4ren die sowas gemacht h\u00e4tten, dies w\u00e4re allerdings ein kleines Problem mit der Registrierung. Es w\u00fcrde zus\u00e4tzliche organisatorische Schritte bed\u00fcrfen, jedoch bot sie uns an die Tattoos entfernen zu lassen um dies alles einfacher zu machen.<br\/>Um nicht Aufsehen von den Yuanti zu erwecken entschied ich mich mein Tattoo hier schnell selbst zu entfernen. Ich schnitt es heraus und heilte es zugleich mit meinen Kr\u00e4ften, was Board leicht verschreckte und missfiel.<br\/>Xerxies und Tulwar hingegen nahmen das Angebot von Board an, woraufhin zwei Yuanti hereinkamen, einer zum schneiden und der anderen zum heilen.<br\/>Anschlie\u00dfend bekamen wir ein Token, das unsere Verbindung zum S\u00f6ldnerhaus zeigt und machten uns auf den Weg zum schwarzen Brett, das bei der Pyramide steht.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Die Auftr\u00e4ge<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Dort angekommen mussten wir unsere Token einem Yuanti aush\u00e4ndigen, der mit der Hand \u00fcber sie ging und anscheinend Informationen dadurch gewann und sie anschlie\u00dfend wiedergab.<br\/>Er bot uns zwei Auftr\u00e4ge an:<br\/>Das Beseitigen von Lycantropen, die H\u00e4ndler zu der Stadt Weirding angreifen.<br\/>Das Auffinden eines vermissten Kenkus, dessen letzter Aufenthalt in Weirding zu seinen schien.<br\/><br\/>Da es erlaubt war mehrere Auftr\u00e4ge zur gleichen Zeit anzunehmen und beide in der gleichen Gegend lagen, nahmen wir beide an. Daraufhin wurden den Auftraggebern Bescheid gegeben, dass die Auftr\u00e4ge angenommen wurden und wir machten uns auf den Weg sie zu treffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als erstes haben wir die H\u00e4ndler getroffen mit dem Lycantropen Problem, dies waren die Giants, die mir meine neue R\u00fcstung verkauft haben, die Genassi, die den Zaubereiladen betrieben und zwei Kenku. Von ihnen erfuhren wir, dass alle von einer Gruppe von Lycantropen bestehend aus Werb\u00e4ren, Werebern und anderen Lycanern bestanden, die auch unterschiedlich bewaffnet waren, angegriffen wurden auf dem Weg zu dem nord\u00f6stlich liegendenden Stadt Weirding. Au\u00dferdem wurden wir auch gewarnt uns vor jedem Tier in acht zu nehmen.<br\/>Der zweite Auftraggeber war ein Genassi, eine Mischung aus Erde und Luft, namens Storm. Er teilte uns mit, dass er uns bereits seit einiger Zeit beobachtet hatte und wusste weswegen wir eigentlich hier sind. Es stellte sich heraus, dass er einer Gruppe angeh\u00f6rt, die \u00e4hnliche Ziele wie wir verfolgten.<br\/>Der vermisste Kenku, Cawkin Jones, w\u00e4re einer von ihnen und war auf einer Mission einer verd\u00e4chtigen Person in Weirding nachzugehen. Die besagte Person w\u00e4re der Namensgr\u00fcnder der Stadt selbst: Herr Weirding.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Das Unterfangen: Z\u00e4hmen<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Uns wurde gesagt, dass Weirding einige Tage von hier entfernt ist und um nicht zu viel Zeit zu verlieren entschieden wir uns noch nach einem Pferd umzuschauen. Jedoch schien dies schwerer zu sein als erwartet und unsere einzige M\u00f6glichkeit war anscheinend 50g zu zahlen f\u00fcr ein Token, das ein Pferd einmal beschw\u00f6rt, vermutlich auf \u00e4hnliche Weise, wie ich mein Gest\u00fct herbeirufe. Diese Stadt gef\u00e4llt mir immer weniger, 50g f\u00fcr einmal ein Pferd beschw\u00f6ren! Das ist totaler Wucher!\u00a0<br\/>Nach diesem ziemlich schlechten Gesch\u00e4ft machten wir uns dann auf den Weg nach Weirding. Nach kurzer Zeit sind mir auf einer Lichtung, etwas abseits vom Weg, eine Gruppe von zebra-\u00e4hnlichen Tieren mit Schn\u00e4bel aufgefallen. Daraufhin sagte ich zu Xerxies halb scherzend, dass er sich mal eben eins dieser Kreaturen z\u00e4hmen soll damit wir nicht nochmal so viel Geld abgezogen bekommen. Er \u00fcberlegte kurz, aber machte sich dann pirschend an die Herde heran jedoch \u00e4nderte er pl\u00f6tzlich die Richtung und begann auf eine komplett andere Kreatur zu st\u00fcrmen.<br\/>Es handelte sich um einen Kamadan, eine gefleckte Raubkatze mit sechs Schlangen, die sich an seinem Hals verbunden sind.<\/p>\n\n\n\n<figure class=\"wp-block-image is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?resize=464%2C472&#038;ssl=1\" alt=\"\" class=\"wp-image-18713\" width=\"464\" height=\"472\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?w=590&amp;ssl=1 590w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?resize=295%2C300&amp;ssl=1 295w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?resize=768%2C781&amp;ssl=1 768w\" sizes=\"(max-width: 464px) 100vw, 464px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Xerxies sprang auf die Kreatur herauf und krallte sich an seinem Fell fest worauf dann der Kamadan versuchte ihn abzuwerfen, jedoch blieb Xerxies stur auf dem Biest fest weshalb ihn aber die Schlangen ihn ebenfalls angegriffen haben. Nachdem wir sahen, dass die Situation mal wieder nicht nach Plan verlief und Xerxies bereits gut verletzt wurde machte ich mich, mit Tulwar hinter mir auf dem R\u00fccken meines Pferdes auf zum Kampf.<br\/>W\u00e4hrenddessen versuchte er mit all seinen Kr\u00e4ften den Kamadan unter Kontrolle zubekommen, jedoch wehrte sich das Biest stark und auch das Seil, das Xerxies um den Hals der Kreatur schlang, schien nicht zu helfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich lies Tulwar ein wenig auf Distanz herunter und sprang danach vom Pferd wonach mir gelang einige Schlangen mit meinem Schwert abzutrennen. Zu dritt gelang es uns recht einfach die Kreatur zu binden und schlie\u00dflich bewusstlos zu hauen.<br\/>Xerxies versuchte mit allerlei Ma\u00dfnahmen sich der Kreaturen vertrauter zu machen, jedoch lies sich der Kamadan nicht einsch\u00fcchtern. Tulwar stellte uns wieder sein magisches Haus zur Verf\u00fcgung damit wir wieder sicher ruhen k\u00f6nnen.<br\/>Als Xerxies am n\u00e4chsten Morgen immer noch keine Fortschritte gemacht hatte, entschied ich die Bestie frei zu lassen um nicht noch mehr Zeit an ihr zu verschwenden. Xerxies hat das \u00fcberhaupt nicht gefallen, hat aber letztendlich es auch eingesehen, dass es eher ein l\u00e4ngeres Unterfangen sei als von einem Tag.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Das Geheimnis von Weirding<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wir reisten ereignislos weiter und erreichten den Wald, der kurz vor Weirding lag. W\u00e4hrend wir uns behutsam durch den Wald bewegten fielen mir einige ungew\u00f6hnliche Ansammlungen von verschiedensten Tieren auf und auch h\u00f6rte man das gelegentliche Heulen von W\u00f6lfen.\u00a0<br\/>Um nicht die Gefahr einzugehen von mehreren Gruppen eventuell eingekreist zu werden, lenkte ich auf eine der Gruppen ein. Doch kurz darauf wurde ich von drei Kr\u00e4hen angegriffen und auch machte sich die Gruppe bereit und begann uns zu umzingeln. Kaum hatte der Kampf angefangen schallte ein gewaltiges Br\u00fcllen durch den Wald und ein riesiger wei\u00dfer Alphawerwolf kam aus dem Nichts gesprungen.\u00a0<br\/>Doch griff er uns nicht an sondern kommandierte er die anderen Tieren auf Abstand zu gehen und sich bereitzustellen. Doch die Raubkatze, die Xerxies umgeworfen hatte und auf ihn sa\u00df, bleib so wie sie war. Anschlie\u00dfend begann er uns zu fragen was wir hier suchten worauf ich antwortete, dass wir einen Auftrag haben Weirding zu untersuchen und den Angriffen von den Lycantropen einen Halt zu machen. Als auch Herr Weirding selbst unter die Lupe zu nehmen um gegebenenfalls Anl\u00e4ufe f\u00fcr den vermissten Kenku zu finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daraufhin erz\u00e4hlte der Anf\u00fchrer uns, dass Weirding seltsame Experimenten an den Einwohner von der Stadt macht und alle Lycantropen ehemalige Menschen der Stadt waren und nun aber als Lycantropen an Weirding gebunden sind sofern sie sich in der Stadt oder in der n\u00e4he von Herr Weirding befinden.<br\/>Der Grund f\u00fcr die Angriffe auf die H\u00e4ndler w\u00e4re allein dazu da um Gold und andere Ressourcen von der Stadt abzutrennen und den B\u00fcrgermeister Weirding in die Enge zu hetzen.<br\/>Wir haben angeboten ihnen zu helfen, da wir anscheinend mehr mit Herr Weirding zu tun schein haben als uns lieb ist, jedoch k\u00f6nnten wir dadurch vermutlich beide unserer Auftr\u00e4ge dadurch erf\u00fcllen. Auch schlug er uns vor seinen Arm als Beweis zu geben, dass wir die Lycantropen get\u00f6tet haben, doch fand ich das ein wenig \u00fcbertrieben und verneinte, da wir mehr als genug Gr\u00fcnde haben um Herr Weirding zu sehen und er uns.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Weirding ist weird<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nachdem Gespr\u00e4ch mit den Lycanern machten wir uns wieder auf den Weg und erreichten am sp\u00e4ten Nachmittag die Stadt. Sie schien zun\u00e4chst wie jede andere Stadt zu sein, von haupts\u00e4chlich Menschen bewohnt sah man einige ihrer Arbeit nachgehen oder auch davon widerkehren. Doch einige Personen verhielten sich seltsam, sie liefen nicht wie alle anderen und hatten auch einen leeren Blick in ihren Augen sowie Narben an den Schl\u00e4fen, die mich wieder an die Experimente von Weirding erinnerten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da sich aber die Nacht schon n\u00e4herte machten wir uns auf die Suche nach einer Unterkunft, die wir auch nach Kurzem fanden. Bucket&#8217;s Bottom hie\u00df die Taverne in die wir traten und bereits im herein kommen bemerkten wir eine gr\u00f6\u00dfere Menge an Leuten um einen leicht niedergelassen Ring versammelt. Dort schien gerade ein Kampf stattzufinden bei dem auch Wetten entgegen genommen wurden. Xerxies holte sich wie immer auf schnellstem Wege ein Krug Bier und ging zum Ring.<br\/>Tulwar und ich dagegen suchten uns einen leeren Tisch und bestellten uns etwas zu essen und trinken und w\u00e4hrend wir auf unsere Bestellung warteten fielen uns verd\u00e4chtige Personen auf, die nicht in die Massen passten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die erste Person war eine Halbelfe, genauer genommen Teil Sonnenelfe, namens Mez Kara, sie w\u00e4re der Lehrling von Herr Weirding und k\u00f6nnte uns eine Audienz mit ihm verschaffen, da wir sagten, dass wir hier waren um das Problem mit den Lycantropen zu l\u00f6sen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Danach gingen wir auch zum Ring wo wir eine Gruppe von drei Leuten fanden, die hier ihr Geld mit diversen Wetten machten. Der Kopf der Gruppe war ein in die Jahre gekommener Mensch namens Gregor Forskog.<br\/>Er erz\u00e4hlte uns \u00fcber die ganzen Wetten, die sie hier machen. Von Ringk\u00e4mpfen zu Wettbewerbswetten unter den Minenarbeiter wer mehr Erz und anderen Ertrag aus der Mine gewinnen kann. Bis jetzt hatten sie noch keinen \u00c4rger oder Probleme mit Herr Weirding, doch sagten sie auch, dass seitdem er hier in der Stadt die Macht hat w\u00e4re einiges besser geworden und auch die Minenarbeiter w\u00e4ren zufrieden.<br\/>Die Muskeln des Dreiergespann war eine Goliath Frau ausger\u00fcstet mit einem Greatsword und mit unz\u00e4hligen Narben verziert. Es stellte sich heraus, dass ihr Name Catkeeper ist und Katzen sehr stark mag, was ihr seltsames Interesse an Xerxies erkl\u00e4ren w\u00fcrde, da er in den letzten Tagen einige Erlebnisse mit solchen Tieren hatte.<br\/>Der Letzte von ihnen war eine m\u00e4nnliche Echse namens Tooth, der f\u00fcr das sammeln und ausgeben des Golden zust\u00e4ndig war.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu Schluss setzten wir uns an den Tisch von einem Furbolg, der leicht zusammengekauert sa\u00df und immer wieder zu dem Ring schaute und seinen Veranstaltern.<br\/>Es stellte sich heraus, dass Gnator Grimcap einige Schulden bei den Leuten hatte und hoffte, dass diesmal seine Wette aufging. Er erz\u00e4hlte uns, dass er unseren Gesuchten Kenku kannte, im Gegensatz zu allen anderen die wir bis jetzt befragt hatten. Au\u00dferdem wusste er auch, dass Jones in die Villa von Weirding wollte und seitdem ihn nicht mehr gesehen hatte. F\u00fcr den Preis seiner Schulden (78g) w\u00fcrde er uns einen geheimen Eintritt in die Villa zeigen.<br\/>Da wir uns aber erstmal noch weiter informieren und nicht gleich in die Villa einbrechen wollten schlugen wir das Angebot erstmal ab und machten uns dann auf zu unseren R\u00e4umen um ausgeschlafen am n\u00e4chsten Tag den seltsamen Geschehnissen nachzugehen, die in dieser Stadt passieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) Das n\u00e4chste Vorhaben Nach den Geschehnissen in der Kanalisation und den danach folgenden Erkenntnissen erwachte ich erneut in dem Haus von Laurenzio und Schall und Rauch auf. Zu meinem Erstaunen, sah ich Tulwar ersch\u00f6pft\u00a0 wach liegen, blass wie eine Wasserleiche und von Schwei\u00df bedeckt.W\u00e4hrend [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":18713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[668],"tags":[],"class_list":["post-18693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe23"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) Das n\u00e4chste Vorhaben Nach den Geschehnissen in der Kanalisation und den danach folgenden Erkenntnissen erwachte ich erneut in dem Haus von Laurenzio und Schall und Rauch auf. Zu meinem Erstaunen, sah ich Tulwar ersch\u00f6pft\u00a0 wach liegen, blass wie eine Wasserleiche und von Schwei\u00df bedeckt.W\u00e4hrend [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-25T18:19:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-08T20:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Varoxian (Marvin)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Varoxian (Marvin)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/\"},\"author\":{\"name\":\"Varoxian (Marvin)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/a8e4eddbb8bfee0d9e27a785d6763a57\"},\"headline\":\"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats)\",\"datePublished\":\"2018-08-25T18:19:23+00:00\",\"dateModified\":\"2018-09-08T20:15:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/\"},\"wordCount\":2194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Kamadan.png?fit=590%2C600&ssl=1\",\"articleSection\":[\"The swamp rats (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/\",\"name\":\"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Kamadan.png?fit=590%2C600&ssl=1\",\"datePublished\":\"2018-08-25T18:19:23+00:00\",\"dateModified\":\"2018-09-08T20:15:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Kamadan.png?fit=590%2C600&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Kamadan.png?fit=590%2C600&ssl=1\",\"width\":590,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/a8e4eddbb8bfee0d9e27a785d6763a57\",\"name\":\"Varoxian (Marvin)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99da781c8c805e0a6b7b3d19c4b59d3a0a262fa0cd8473ad060d34a82f282ad3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99da781c8c805e0a6b7b3d19c4b59d3a0a262fa0cd8473ad060d34a82f282ad3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/99da781c8c805e0a6b7b3d19c4b59d3a0a262fa0cd8473ad060d34a82f282ad3?s=96&d=mm&r=g\",\"caption\":\"Varoxian (Marvin)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/marvin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/","og_locale":"de_DE","og_type":"article","og_title":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) - RPG-Berlin.de","og_description":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) Das n\u00e4chste Vorhaben Nach den Geschehnissen in der Kanalisation und den danach folgenden Erkenntnissen erwachte ich erneut in dem Haus von Laurenzio und Schall und Rauch auf. Zu meinem Erstaunen, sah ich Tulwar ersch\u00f6pft\u00a0 wach liegen, blass wie eine Wasserleiche und von Schwei\u00df bedeckt.W\u00e4hrend [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2018-08-25T18:19:23+00:00","article_modified_time":"2018-09-08T20:15:02+00:00","og_image":[{"width":590,"height":600,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1","type":"image\/png"}],"author":"Varoxian (Marvin)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Varoxian (Marvin)","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/"},"author":{"name":"Varoxian (Marvin)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/a8e4eddbb8bfee0d9e27a785d6763a57"},"headline":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats)","datePublished":"2018-08-25T18:19:23+00:00","dateModified":"2018-09-08T20:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/"},"wordCount":2194,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1","articleSection":["The swamp rats (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/","name":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1","datePublished":"2018-08-25T18:19:23+00:00","dateModified":"2018-09-08T20:15:02+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1","width":590,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/das-schwarze-brett-und-der-versuch-des-zaehmens-the-swamp-rats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Das schwarze Brett und der Versuch des Z\u00e4hmens (The swamp rats)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/a8e4eddbb8bfee0d9e27a785d6763a57","name":"Varoxian (Marvin)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/99da781c8c805e0a6b7b3d19c4b59d3a0a262fa0cd8473ad060d34a82f282ad3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/99da781c8c805e0a6b7b3d19c4b59d3a0a262fa0cd8473ad060d34a82f282ad3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/99da781c8c805e0a6b7b3d19c4b59d3a0a262fa0cd8473ad060d34a82f282ad3?s=96&d=mm&r=g","caption":"Varoxian (Marvin)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/marvin\/"}]}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-4Rv","jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Kamadan.png?fit=590%2C600&ssl=1","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/18693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=18693"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/18693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/18713"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=18693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=18693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=18693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}