{"id":18268,"date":"2018-05-26T23:05:39","date_gmt":"2018-05-26T21:05:39","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=18268"},"modified":"2018-07-18T09:30:40","modified_gmt":"2018-07-18T07:30:40","slug":"sightseeing-der-etwas-anderen-art-the-swamp-rats","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/","title":{"rendered":"Sightseeing der etwas anderen Art (The swamp rats)"},"content":{"rendered":"<h4>Sightseeing der etwas anderen Art (The swamp rats)<\/h4>\n<h5><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft wp-image-18270 size-medium\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?resize=300%2C280&#038;ssl=1\" alt=\"Sightseeing der etwas anderen Art (The swamp rats)\" width=\"300\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?resize=300%2C280&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?w=515&amp;ssl=1 515w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Die Unterkunft<\/h5>\n<p>Nachdem uns <span class=\"_5yl5\">Laurenzius<\/span> in seinem Haus beherbergte und wir \u00fcber die Yuan ti zu sprechen kamen. Insbesondere \u00fcber die G\u00f6ttin <span class=\"_5yl5\">Sseth, dem Anf\u00fchrer Oasi<\/span> und dessen Anh\u00e4ngerschaften brach die Nacht \u00fcber uns herein und die Gruppe konnte Ihre Kr\u00e4fte beim erholsamen Schlaf neu sammeln.<\/p>\n<p>Am n\u00e4chsten Morgen war Schall und Rauch nachdem <span class=\"_5yl5\">Laurenzius<\/span> zu seiner Gerberei aufgebrochen war, bei einer der Wachen auf den Mauern nach den Gesuchten erkundigt. Ja wir waren endlich Gesuchte und hatten f\u00fcr ein kleines Aufsehen gesorgt in der Stadt, als wir am Vortag uns der T\u00e4towierung bzw. den Ritual widersetzt hatten. Der Sache wollte man sich zwar annehmen, aber war von weniger Belangen. Als Blinki von Schall und Rauch nach der R\u00fcckkehr diese Worte vernommen hatte.. fing er an zu Schmunzeln.<\/p>\n<p>Ja der Tag hatte erst angefangen. Unterdessen beratschlagte die Gruppe Ihr weiteres vorgehen und kam zu dem Entschluss den Bazar der Stadt aufzusuchen, Blinki ben\u00f6tigte ein neues Buch um seine Zauber einzutragen, (das Alte war leider der eigenen Kloake zum Opfer gefallen) Varoxian gel\u00fcstete es nach einer neuen R\u00fcstungen und Xerxies wollte sich auf die Suche nach neuen vlt. auch exotischeren Kr\u00e4utern begeben und gegebenfalls sich mit einem Kundigen \u00fcber Rezepturen austauschen.<\/p>\n<h5>Der Bazar<\/h5>\n<p>Nach einer einfachen Kontrolle unserer Tataoos und unseren Anliegen kamen wir zum Bazar der am Fu\u00dfe der Pyramide lag. Der Markt war im Inbegriff aufgebaut zu werden und so sah man diverse Verk\u00e4ufer, aus unterschiedlichen V\u00f6lker die sich auf dem Bazar tummelten. Unter anderen Kenkus, Genasi und anderen V\u00f6lkern, es fiel auf das es keine konkurrierende St\u00e4nde gab. Merkw\u00fcrdig, machte doch erst die Konkurrenz einen Bazar aus. Nun aber andere L\u00e4nder andere Sitten. W\u00e4hrend jeder seinem Anliegen nachgegangen war, mal mehr, mal weniger erfolgreich wie man nach einer halben Stunde feststellen musste, beobachtete Schall und Rauch das ganze Treiben von einem steinernen Kanalisationsdeckel aus.<\/p>\n<p>Blinki hatte recht schnell bei einer Gruppe von Genasi f\u00fcr einen passenden Ersatz, sein alten Zauberbuch und f\u00fcr einen guten Preis gefunden und auch Varoxian hatte mit seiner Suche Erfolg bei ein paar Goliaths und pr\u00e4sentierte uns sp\u00e4ter seinen neuen B\u00e4nderpanzer. Einzig Xerxies war ein wenig verloren \u00fcber den Markt geirrt und hatte nichts gefunden. Da Genasi die Hilfe von dem Gnom abgeleht hatten, hatte dieser versucht den Nordman auf dem Markt zu finden, dabei war Ihm ein recht ungleichtes Paar aufgefallen.<\/p>\n<h5>Lanu und Mirafir<\/h5>\n<p>Eine Schildkr\u00f6te und ein Fulborg eilten sich einen Stand zu errichten und hatten das Interesse von Blinki geweckt. Neugierig betrachtete der Gnom die Runen und die Einfassungen auf dem Panzer der Schildkr\u00f6te. Dem Anschein nach, war diese recht alt. Die Neugierde blieb nicht unbemerkt und schnell kam er und die Schildkr\u00f6te mit dem Namen Lanu ins Gespr\u00e4ch. An Xerxies sich erinnernd erkundigte sich der Gnom nach diversen Elexieren, Tr\u00e4nken und Tinkturen. Er hatte zwar nicht die Ahnung, aber er wusste was sich geh\u00f6rte und so wechselte alsbald ein wenig Schmauchkraut, ein Kraut das abf\u00fchrend wirkte, als auch ein paar andere Dinge den Besitzer. Als Lanu Ihm auch noch eine Abschrift eines besonderen Buches gew\u00e4hrte war die \u00dcberraschung umso gr\u00f6\u00dfer wie sich sp\u00e4ter herausstellen sollte. In der Hoffnung sich bald wieder zu treffen mit dem Nordmann an seiner Seite verabschiedete sich der Gnom von Lanu und Mirafir dem Fulborg.<\/p>\n<p>Das Zusammentreffen und das weitere Vorgehen an der Steinplatte bedufte recht kurz und auch die Mine von Xerxies erhellte sich, als er von Blinki die Abschrift, als auch einen guten Zug aus der Pfeiffe von Blinki mit dem neuen Schmauchkraut bekam. Irgendwie hinterlies die Pfeiffe Nebenwirkungen, doch das hinderte nicht die Gruppe nach und nach in die Kanalisation zu gelangen.<\/p>\n<h5>Die Kanalisation<\/h5>\n<p><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/31cfa4d6f6ed29fc5ef5f33c753ec73c_flash.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-18289 size-medium alignleft\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/31cfa4d6f6ed29fc5ef5f33c753ec73c_flash.jpg?resize=300%2C208&#038;ssl=1\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/31cfa4d6f6ed29fc5ef5f33c753ec73c_flash.jpg?resize=300%2C208&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/31cfa4d6f6ed29fc5ef5f33c753ec73c_flash.jpg?w=635&amp;ssl=1 635w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Unten war es ruhig, das Rauschen der Kanalisation war zu h\u00f6ren, als auch die Gespr\u00e4chsfetzen die vom Trubel des Bazars nach unten drang. Nachdem Varoxian die Steinplatte mit einem knirschendenden Ger\u00e4usch wieder verschlossen hatte. Blieb nur noch das Rauschen. Am Boden des Kanals waren Spuren der Schlangenwesen zu sehen die hier des \u00f6fteren vorbei kamen. Also entschloss sich die Gruppe sich Richtung Pyramide zu begeben und wurde kurz davor in ihrem Enthusiasmus gebremst, da ein Eisengitter den Weg weiter in das Innere zu gelangen versperrte.<\/p>\n<p>Es half nichts und so begab sich Varoxian in die Br\u00fche und rutsche darin aus und prallte schmerzhaft gegen das Gitter. Xerxies bekommt einen Anfall und drischt unverholen auf die Gitterst\u00e4be ein, aber selbst nach einer l\u00e4ngeren Zeit habe diese sich kaum verformt. Nachdem er Unterst\u00fctzung von Varoxian erh\u00e4lt \u00e4ndert sich die Situation kaum, auch das Gitter mittels eines Netzes herauszureissen scheitern. So vergeht einige Zeit in der Kanalisation. Immerhin bekommt die Gruppe heraus warum sie sich mit dem Gitter so schwer tun. Sp\u00e4testens aber nachdem ein Beben die Stadt erzitterte, als Blinki einen Zauber ausprobiert hatte, sich das Gitternetz zusammengezogen der Gruppe nun den Weg freigab, war allen klar das man hier einiges f\u00fcr den Schutz gemacht hatte. Es w\u00fcrden noch mehr H\u00fcrden auf sie warten.<\/p>\n<h5>Die Pyramide von unten<\/h5>\n<p>Nachdem das Gitter \u00fcberwunden war, ging die Kanalisation steil herab. Schall und Rauch bildete die Vorhut und kam schnell voran, bis er eine riesige H\u00f6hle erreichte, dessen obere Mitte einen\u00a0 umgedrehten pyramidenf\u00f6rmigen Stalagtit bildete der mit diversen Edelsteinen besetzt war, den Abschluss bildete ein roter geschliffener Edelstein. Leider war diese Pyramide nicht so ohne weiteres zu erreichen, lagen doch mehrere Meter Luftlinie dazwischen. Nach unten hin erstreckte sich eine Steile die in einem Loch endete. Das Tosen lies darauf schliessen, das es da noch nicht zuende war. Die Abf\u00e4lle der Stadt ergossen sich in ein schmalles Loch, in eine Art Vase, in Form einer eisernen Jungfrau. Umrahmt wurde sie von einem Becken, welches verhinderte das die Kloake der Stadt in die Vase laufen konnte.<\/p>\n<h5>Aktion Brechstange<\/h5>\n<p>Unterdessen hatte die Gruppe zu Schall und Rauch aufgeschlossen. Nachdem dieser der Gruppe seine Erkenntnisse mitgeteilt hatte und die Vertraute von Blinki, die Eule, nicht mehr berichten konnte, kletterte Schall und Rauch an den W\u00e4nden entlang zur Pyramide und erkundete diese. Abgesehen von den Farben der Steine von orange, blau, rot, lila und gr\u00fcn, entdeckte er ab dem lilanen Berich, drakonische Runen die sich \u00fcber die Etage hinwegzogen. Am untersten Bereich beim \u00dcbergang zu dem roten Stein zogen besondere Runen seine Aufmerksamkeit an.<\/p>\n<p>Sp\u00e4ter wurden diese 4 Lebensrunen von Blinki entschl\u00fcsselt, der sich nachdem Schall und Rauch und auch Xerxies sich dank der Slipper sich an der Pyramide probiert hatten. Die H\u00f6hle wurde von einem Brummen erf\u00fcllt, nachdem Blinki versucht hatte den roten Rubin zu zerst\u00f6ren. Auch vor ihn hatte Xerxies es versucht und hatte seinen Hammer eingeb\u00fc\u00dft. Ebenso erging es Blinki der es mit diversen Zaubern versucht hatte, den Stein zu zerst\u00f6ren. Als diese Zauber sich aber gegen ihn wanden und die selbst zugef\u00fcgten Schmerzen des Feuerbolzen langsam nachlie\u00dfen, kehrte dieser zu den anderen zur\u00fcck.<\/p>\n<h5>Die Vase<\/h5>\n<p>Schall und Rauch, der inzwischen seine Slipper wieder hatte, machte sich nun auf den Weg nach unten und entdeckte unter anderem gr\u00fcnen Schleim, der Ihn sehr schnell klar machte das dieser Schleim weitaus mehr war, als er zu sein schien. Denn nachdem er in das Loch gesp\u00e4ht hatte, erwachte dieser Schleim, formte sich neu und verfolgte ihm zwar langsam aber stetig. Den Heraufeilenden auf sich zukommend, packte der Rest der Gruppe Ihre Sachen zusammen und begann den Aufstieg. Schall und Rauch \u00fcberholte sie und teilte Ihnen mit, welche Gefahr von hinter Ihnen drohte. Schnell war die Gruppe wieder hinter dem Gitter.<\/p>\n<h5>Die Verfolger<\/h5>\n<p>Doch was war das, der schwere steinere Deckel zu der Kanalisation vom Bazar war offen. Das konnte nur eins bedeutet, das Beben oben hatte das Interesse der Stadtoberh\u00e4upter geweckt. Also entschloss sich die Gruppe weiter der Kanalisation zu folgen, wobei Schall und Rauch der Gruppe immer ein wenig voraus war. Blinki brachte einen Sensor in der Kanalisation an um Verfolger fr\u00fchzeitig zu entdecken, w\u00e4hrend Schall und Rauch eine kleine Abzweigung ausfindig machte, um der kleinen Gruppen Sichtschutz zu gew\u00e4hren und das vor ihm Gegner waren, so entschloss sich die Gruppe, sich um die 5 Verfolger zu k\u00fcmmern.<\/p>\n<p>Schnell hatte die Gruppe Ihre Position eingenommen, die Eidechsen heran und wurden v\u00f6llig \u00fcberrumpelt, den Auftakt machte Varoxian und ehe der erste Gegner auch nur wusste was Sache war, wurde er an die Wand der Kanalisation gestossen und machte die Bekanntschaft von Xerxies seiner Waffe, die ihn zusammensacken lie\u00df und Schall und Rauch zwischen den \u00fcberraschten Gegner hin und herwirbelte. Sie starben lautlos und selbst der Schamane brachte keinen Laut mehr \u00fcber seine Lippen, einer von den Eidechsen wurde noch verh\u00f6rt, bevor auch seine Wirbel, von Schall und Rauch gebrochen wurden.<\/p>\n<h5>Feierabend in der Gerberei<\/h5>\n<p>Die Gruppe hatte beschlossen die Leichen zur\u00fcck in der Kanalisation zu lassen und war an die Oberfl\u00e4che zur\u00fcckgekehrt. Behutsam hatte Schall und Rauch die Platte zur Seite geschoben und so stand die kleine Gruppe, die zuvor von dem Blut der Echsen gereinigt worden war, vor der Gerberei von <span class=\"_5yl5\">Laurenzius<\/span>. Sie traten ein und holten ihn ab. Er hatte Feierabend. Anscheinend hatte das Beben seine Spuren hier in der Stadt hinterlassen. Einige Sch\u00e4den waren entstanden, soviel war den Wachen zu entlocken die sie auf den Weg zu <span class=\"_5yl5\">Laurenzius<\/span> trafen bzw. leicht kontrolliert wurden. Beim Haus von <span class=\"_5yl5\">Laurenzius<\/span> angekommen schmiedete die Gruppe weitere Pl\u00e4ne f\u00fcr den Abend, es ging zum Vergnungungsviertel. Gesagt getan.<\/p>\n<h5>Das Vergn\u00fcngunsviertel<\/h5>\n<p>Die Gruppe gelangte am Abend ohne gro\u00dfe Probleme und nur einer leichten Kontrolle von einen paar Tabaxis am Tor zu dem Viertel hinein. Die Sonne war bereits schon untergegangen und reges Treiben in den riesigen H\u00e4usern war schon von draussen wahrnehmbar. Die Gruppe teilte sich auf und w\u00e4hrend Varoxian und Xerxies sich in die riesige Taverne &#8222;Zur zischelnden Echse&#8220; gingen, zog es Schall und Rauch und Blinki in das Etablissement &#8222;Zur gespaltenen Zunge&#8220;.<\/p>\n<p>W\u00e4hrend die Taverne Ihre Pforten, unter einem in schrill gr\u00fcn gehaltenem Ying-Yang symbolisiernden Schild, f\u00fcr den Besucher freigab, waren es bei dem Bordell eher dezente Farben. Beide Einrichtungen waren riesig, fast schon \u00fcberdimensoniert. Etliche 100er Fu\u00df lang und ebenso breit.<\/p>\n<h5>Die Taverne &#8222;Zur zischelnden Echse&#8220;<\/h5>\n<p>Schnell hatte Xerxies sich an die Bar gesellt und setzte sich zu einer bunt gemischte Gesellschaft, bestehend aus Tabaxi, Tortle und einem Genasi. Er f\u00fcllte sein Fass. Als er versucht seine Pfeiffe zu z\u00fccken um damit Kontakte zu der Tortle zu kn\u00fcpfen, wird er von dieser auf die Kr\u00e4uter hingewiesen. Nach einer kleinen Unterhaltung bietet die Tortle ihm einen kleinen Workshop an, falls diese wieder in der Stadt sei. Varoxian setzt sich unterdessen an einen anderen Tisch und beh\u00e4lt die Taverne, soweit dies m\u00f6glich sei, im Blick.<\/p>\n<h5>Das Etablissement &#8222;Zur gespaltenen Zunge&#8220;<\/h5>\n<p>S\u00fc\u00dfer Duft und Maserungen aus Kirschholz schl\u00e4gt den anderen beiden entgegen. W\u00e4hrend Schall und Rauch zum Wartebereich schlenderte, hatte sich Fizzle unsichtbar gemacht und war in die oberen R\u00e4ume des Etablissements gelangt. Schall und Rauch wurde zu einem Treffen in die unteren R\u00e4umlichkeiten gef\u00fchrt und erhielt dort Informationen zum Verbleib einer gewissen weiblichen Person, auf dessen Suche er nach wie vor war. Der Gnom hatte unterdessen einen Raum gefunden der offen war und hatte diesen pr\u00e4pariert. Was hatte dieser Gnom vor?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sightseeing der etwas anderen Art (The swamp rats) Die Unterkunft Nachdem uns Laurenzius in seinem Haus beherbergte und wir \u00fcber die Yuan ti zu sprechen kamen. Insbesondere \u00fcber die G\u00f6ttin Sseth, dem Anf\u00fchrer Oasi und dessen Anh\u00e4ngerschaften brach die Nacht \u00fcber uns herein und die Gruppe konnte Ihre Kr\u00e4fte beim erholsamen Schlaf neu sammeln. Am [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[668],"tags":[],"class_list":["post-18268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe23"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sightseeing der etwas anderen Art (The swamp rats) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sightseeing der etwas anderen Art (The swamp rats) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Sightseeing der etwas anderen Art (The swamp rats) Die Unterkunft Nachdem uns Laurenzius in seinem Haus beherbergte und wir \u00fcber die Yuan ti zu sprechen kamen. Insbesondere \u00fcber die G\u00f6ttin Sseth, dem Anf\u00fchrer Oasi und dessen Anh\u00e4ngerschaften brach die Nacht \u00fcber uns herein und die Gruppe konnte Ihre Kr\u00e4fte beim erholsamen Schlaf neu sammeln. Am [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-26T21:05:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-18T07:30:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/\"},\"author\":{\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\"},\"headline\":\"Sightseeing der etwas anderen Art (The swamp rats)\",\"datePublished\":\"2018-05-26T21:05:39+00:00\",\"dateModified\":\"2018-07-18T07:30:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/\"},\"wordCount\":1931,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1\",\"articleSection\":[\"The swamp rats (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/\",\"name\":\"Sightseeing der etwas anderen Art (The swamp rats) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1\",\"datePublished\":\"2018-05-26T21:05:39+00:00\",\"dateModified\":\"2018-07-18T07:30:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1\",\"width\":515,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe23\\\/sightseeing-der-etwas-anderen-art-the-swamp-rats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sightseeing der etwas anderen Art (The swamp rats)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\",\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"caption\":\"Thinkleblink\\\/Dalwick (Mirko)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sightseeing der etwas anderen Art (The swamp rats) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/","og_locale":"de_DE","og_type":"article","og_title":"Sightseeing der etwas anderen Art (The swamp rats) - RPG-Berlin.de","og_description":"Sightseeing der etwas anderen Art (The swamp rats) Die Unterkunft Nachdem uns Laurenzius in seinem Haus beherbergte und wir \u00fcber die Yuan ti zu sprechen kamen. Insbesondere \u00fcber die G\u00f6ttin Sseth, dem Anf\u00fchrer Oasi und dessen Anh\u00e4ngerschaften brach die Nacht \u00fcber uns herein und die Gruppe konnte Ihre Kr\u00e4fte beim erholsamen Schlaf neu sammeln. Am [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2018-05-26T21:05:39+00:00","article_modified_time":"2018-07-18T07:30:40+00:00","og_image":[{"width":515,"height":480,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1","type":"image\/jpeg"}],"author":"Thinkleblink\/Dalwick (Mirko)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thinkleblink\/Dalwick (Mirko)","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/"},"author":{"name":"Thinkleblink\/Dalwick (Mirko)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec"},"headline":"Sightseeing der etwas anderen Art (The swamp rats)","datePublished":"2018-05-26T21:05:39+00:00","dateModified":"2018-07-18T07:30:40+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/"},"wordCount":1931,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1","articleSection":["The swamp rats (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/","name":"Sightseeing der etwas anderen Art (The swamp rats) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1","datePublished":"2018-05-26T21:05:39+00:00","dateModified":"2018-07-18T07:30:40+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1","width":515,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe23\/sightseeing-der-etwas-anderen-art-the-swamp-rats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Sightseeing der etwas anderen Art (The swamp rats)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec","name":"Thinkleblink\/Dalwick (Mirko)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","caption":"Thinkleblink\/Dalwick (Mirko)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/05\/53f26c0e03d4129dbd417cb0006fe933.jpg?fit=515%2C480&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-4KE","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/18268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=18268"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/18268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/18270"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=18268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=18268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=18268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}