{"id":17734,"date":"2017-08-27T20:15:34","date_gmt":"2017-08-27T18:15:34","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=17734"},"modified":"2018-03-09T23:40:51","modified_gmt":"2018-03-09T22:40:51","slug":"journey-into-the-fallen-city","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/","title":{"rendered":"Journey into the fallen City (Dragon Knife)"},"content":{"rendered":"<p>Journey into the fallen City (Dragon Knife)<\/p>\n<p>\u201eWEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAHHHHHHHHHHHH\u201c Rotes Licht durchsucht systematisch das Areal und ein rhythmisches Lauter werdendes Stampfen k\u00fcndigt das ann\u00e4hern von Unbekannten Wesen an. In einem Anfall von Gruppen-Telepathie h\u00f6rt man f\u00f6rmlich wie sich jeder bis auf einen denkt \u201eALEX DU IDIOT\u201c. Unverst\u00e4ndliche Blicke gepaart mit Furcht gegen\u00fcber dem kommenden wandern durch den Raum in den sich die Gruppe vor\u00fcbergehend gerettet hat. Das stampfen wird lauter und die Blicke ratloser, w\u00e4hrend die Gef\u00e4hrten verzweifelt, trotzdem m\u00f6glichst Leise, nach einem Ausweg suchen.<br \/>\n\u2026<br \/>\n\u2026<br \/>\n\u2026<br \/>\nMit einem Mal dringt zum Fenster glei\u00dfenden Licht herein als ob au\u00dferhalb des Geb\u00e4udes ein starkes Gewitter stattfinden w\u00fcrde. Nach mehreren Sekunden erlischt alles von au\u00dferhalb kommendes Licht und gefolgt von dr\u00f6hnender Stille. \u201eDas war knapp\u201c l\u00e4sst eine aus den denn Schatten tretende Gestalt verlauten welche auf Mysteri\u00f6se Weise von niemanden in der Gruppe war genommen wurde, obwohl sie den Raum durchsucht hatten. \u201eWoher seid ihr und was wollt ihr\u201c keift ihm Tragrim entgegen. \u201eEs ist ein wunder das ihr bis hierhergekommen seid, ich folge euch seitdem ihr die H\u00f6hle betreten habt und niemand von euch hat mich auch nur im Entferntesten bemerkt? Euer Freund der Druide m\u00fcsste mich eigentlich erkennen.\u201c Auch nach mehreren Sekunden \u00e4ndert sich der Stumpfe Ausdruck auf Hakkons Gesicht nicht. \u201eIch bin ein Freund Dargosses und bin hier um euch zu helfen, mein Name ist Manks, Manks Netz. Dargoss und ich sind bereits vor ein paar Tagen hier angekommen und haben begonnen diesen Ort zu erkunden.<\/p>\n<p>Das Rote Licht welches ihr vorhin war genommen habt wird von Seltsamen Konstrukten ausgestrahlt, deren Ursprung mir nicht bekannt ist. Sie sind jedoch relativ einfach zu besiegen wie ich finde.\u201c Noch bevor die Worte verklungen sind fragt Tragrim mit gro\u00df aufgerissenen Augen, \u201eIhr habt eines dieser &#8222;Konstrukte&#8222; besiegt? Wo und wann war das. Ich muss das sehen!\u201c. Schnell gelingt es Tragrim, der ein schon fast fanatisches Gl\u00e4nzen in den Augen aufweist, seine Bekannten dazu aufzuraffen sich das lahmgelegte Konstrukt n\u00e4her zu betrachten. Vorsichtig und unter dem Versuch sich leise zu bewegen, macht sich die Gruppe auf den Weg zum gefallenen Konstrukt. Unterwegs sehen sie in der Ferne wieder die gewitterartigen Erscheinungen welche jedoch dem Anblick nach deutlich Schw\u00e4cher sind als die vorherigen. Auch merkw\u00fcrdige Rillen fallen ihnen im Boden auf welche keinen erkennbaren Zweck zu erf\u00fcllen scheinen. \u201eWir sind gleich da, dort vorne habe ich das Konstrukt niedergestreckt.\u201c<\/p>\n<p>Kurz daraufhin erreichen sie den angesprochenen Ort. Sie sehen eine \u00e4u\u00dfert seltsam erscheinende Konstruktion mit mehreren Beinen, fast wie bei einer Spinne, welches in seiner Mitte in einer Vertiefung einen Kristall tr\u00e4gt. Tragrim, anscheinend komplett verz\u00fcckt, st\u00fcrzt sich geradezu auf die Konstruktion und beginnt sie zu Untersuchen. \u201eEs war einfach es auszuschalten, es ist anscheinend ausreichend den Kristall in der Mitte des Konstrukts zu besch\u00e4digen und sie verlieren jegliche Funktion.\u201c \u201eVon denen laufen hier mehrere herum?\u201c. Das Entsetzen steht Hakkon ins Gesicht geschrieben. W\u00e4hrend Tragrim das Konstrukt untersucht n\u00e4hert sich Zukuu auf einmal und be\u00e4ugt den Kristall der die Konstruktion anzutreiben scheint.<\/p>\n<p>Mit einem seltsamen Glitzern in den Augen beugt er sich an den angebrochenen Kristall heran, besieht ihn sich n\u00e4her, tastet eine bestimmte Stelle ab und leckt diese ab. Anscheinend unzufrieden mit dem Ergebnis zieht er sich zur\u00fcck und bemerkt das er sich anscheinend an einer scharfen Stelle des Kristalles geschnitten hat. Tragrim winkt Lee zu, \u201eHey Lee, hilf mir mal und brich aus dem Kristall weitere St\u00fccke heraus, ich bin daf\u00fcr zu schwach\u201c. \u201eIch brauch was zu schreiben wo bekomme ich jetzt was zu schreiben her. Hey Zukuu, ich biete dir 2 H\u00e4nde voll K\u00e4se an gegen 5 Seiten Pergament.\u201c<\/p>\n<p>Nach erfolgreichem Tausch der Handelswahre beginnt Tragrim damit den inneren Aufbau des Sockels in dem der Kristall gelegen hat zu Skizzieren\u201c. Unbemerkt von ihm aber zur Verwunderung der anderen beginnt Zukuu damit sich den eben erhandelten K\u00e4se ins Gesicht zu schmieren. Die Gruppe entschlie\u00dft sich das am n\u00e4chsten stehende Geb\u00e4ude aufzusuchen, Nachdem die Skizzen erstellt sind, schl\u00e4gt Tragrim vor das Konstrukt auf ihrem Weg aus der H\u00f6hle mitzunehmen und beginnt vertr\u00e4umt zu beschreiben was man alles mit solchen Maschinen machen k\u00f6nnte nachdem man sie erst einmal erforscht hat. Seine Bem\u00fchungen fokussieren sich auf Lee welcher sich hinsichtlich seiner Entscheidung nicht sicher scheint. Auf einmal fliegt ein Ball schwarzer Flammen an Tragrim vorbei und schl\u00e4gt in die \u00dcberreste des Konstrukts ein. Wutentbrannt zieht Tragrim seine Waffe und schie\u00dft impulsiv auf Zukuu, der soeben den Fokus seines Interesses zerst\u00f6rt hat. \u00a0Getroffen taumelt Zukuu mehrere Schritte nach hinten.<\/p>\n<p>Das Blut das aus seinen Mundwinkeln und der Schusswunde fliest ignorierend beginnt er einen Zauber zu wirken, mit der Klaren Absicht sich f\u00fcr diesen aus seiner Sicht nicht provozierten Angriff zu R\u00e4chen. Die Gruppe, bleich im Gesicht, geht dazwischen und verhindert schlimmeres. Lee entrei\u00dft Tragrim seine Waffe und Hakkon ringt Zukuu zu Boden und unterbricht somit seinen Zauber. \u201eIst dir eigentlich klar was du gerade getan hast? Es war in perfektem Zustand, solch ein Objekt in so perfekten Zustand zu erhalten wird nie wieder geschehen!\u201c schreit Tragrim Zukuu an, sich vor Wut sch\u00fcttelnd.<\/p>\n<p>Lee und Hakkon reden auf beide beruhigend ein w\u00e4hrenddessen Manks und Alex sich nerv\u00f6s den Fenstern zuwenden um herauszufinden ob das nicht gerade leise abgelaufene Spektakel bemerkt wurde. \u201eSeid ihr eigentlich alle wahnsinnig??\u201c l\u00e4sst Manks vernehmen. \u201eWenn die uns nicht geh\u00f6rt haben ist das ein reines Wund\u2026.\u201c In just diesem Moment schie\u00dfen zwei Schatten in dem Raum. Es sind zwei der spinnenartigen Konstrukte mit einem Kristall als K\u00f6rper. Eines von ihnen spiest bei seiner Landung Zukuu und Hakkon mit zwei seiner Beine auf w\u00e4hrend das zweite sich dem Rest der Gruppe zuwandt.<\/p>\n<p>W\u00e4hrend sich Zukuu und Hakkon zu befreien versuchten, bek\u00e4mpften Lee und Tragrim das andere Konstrukt welches es auf sie abgesehen hatte. Alex, bedingt durch den nur begrenzt zur Verf\u00fcgung stehenden Platz innerhalb des Geb\u00e4udes und den eher gro\u00dfen Wirkungsradius der ihm zur Verf\u00fcgung stehenden M\u00f6glichkeiten beschr\u00e4nkt sich darauf Wache zu stehen und darauf zu achten das von drau\u00dfen keine weiteren Konstrukte sich anschleichen. Die beiden zu Boden gepinnten schaffen es nach kurzen Kampf sich zu befreien. Zukuu schleudert seine Schattenmagie in Form eines Schwarz brennenden Feuerballs auf das Konstrukt. Hakkon verwandelt sich und greift in Wolfsform an indem er eines der Beine herausrei\u00dft. Tragrim, noch entwaffnet da er sich weigerte seine Waffe wieder an sich zu nehmen, zieht aus seinem Bag of Holding zwei zuvor eingesammelte Holst\u00fccke heraus und bem\u00fcht sich das Konstrukt aus dem Gleichgewicht zu bringen, was ihm \u00fcberraschend auch gelingt.<\/p>\n<p>Lee, in seiner Natur als Kung-Fu Master, schnellt sich nach vorne, f\u00fchrt einen Roundhouse kick aus mit dem Ziel den Kristall zu zerst\u00f6ren. Er trifft zwar, erreicht jedoch keinen Sichtbaren Effekt abgesehen davon das das Konstrukt sein Gleichgewicht wiederfindet. Auf der anderen Seite des Raums stehend versucht Manks mittels Wurfdolchen, wie er es bereits zuvorgetan hat, den Kristall der Konstrukte zu zerst\u00f6ren.<\/p>\n<p>Als Reaktion auf die Angriffe springt das erste Konstrukt erneut Zukuu und Hakkon an und versucht sie erneut aufzuspie\u00dfen, verfehlt sie jedoch knapp so dass sie nur geringen Schaden nehmen. Das zweite Konstrukt, anscheinend Lee`s Aktionen kopierend f\u00fchrt einen mehrbeinigen Roundhouse kick gegen Tragrim und Lee aus. Da Tragrim als Gnom eine nur geringe K\u00f6rpergr\u00f6\u00dfe aufweist geht der Angriff wortw\u00f6rtlich \u00fcber seinen Kopf hinweg und trifft jedoch Lee welcher dank seiner Kung-Fu Reflexe nicht ernsthaft verletzt wird. Nach einer weiteren Reihe von Angriffen der Gruppe erstrahlte mit einem Mal ein rotes Licht aus dem Kristall des zweiten Konstrukts.<\/p>\n<p>Schnell stellte es sich als eine Art konzentrierter Lichtstrahl heraus welcher bei Kontakt eine unglaublich starke Hitzeeinwirkung verursacht. Tragrim, aufgrund seiner N\u00e4he zu dem Konstrukt sowie seines kleinen K\u00f6rperbaus wird verfehlt, der Rest der Gruppe jedoch getroffen. Am schlimmsten trifft es Zukuu welcher einmal Quer \u00fcber seine Brust eine schwelende Brandnarbe davontr\u00e4gt. Hakkon in Wolfsform, in einem Versuch Zukuu zu helfen, nimmt Anlauf um das Konstrukt aus dem Weg zu rempeln. Er rennt, er springt, er verfehlt, er segelt zum Fenster hinaus. Anschlie\u00dfend f\u00fchrte eine Kombination aus Teamarbeit sowie gezielten Angriffen zur schnellen Vernichtung der eingedrungenen Konstrukte. Nachdem sich die Gem\u00fcter beruhigt hatten, machte sich die Gruppe weiter auf den Weg.<\/p>\n<p>Manks Wissen nach sind die Konstrukte aus mehreren gro\u00dfen Geb\u00e4uden hervorgekommen. Nachdem die Gruppe die Geb\u00e4ude erreicht hatte, stellte sich heraus das in diesen eine Art von Automatischer Produktion aufgebaut ist, welche anscheinend fortlaufende Konstrukte unterschiedlicher Bauart herstellten. In einem angrenzenden Raum des Geb\u00e4udes fanden sie teilweise zerst\u00f6rte Kontrollanlagen. Noch w\u00e4hrend die Gruppe diskutierte was der n\u00e4chste beste Schritt w\u00e4re um die Maschine abzuschalten, geht Zukuu zu einer der Anlagen bin einer Metallstange die er gefunden hat, steckt sie in eine passende Kontrollstelle und legt nach einem kurzen herunterz\u00e4hlen von einer arbitr\u00e4ren Zahl den Hebel um. Rumpelnd komm die Produktion zu einem Stillstand. Zwar ist nun eine der Produktionsanlagen ausgeschaltet, Manks wei\u00df jedoch von wenigstens drei weiteren von denen er wei\u00df.<\/p>\n<p>Geschlossen macht sich die Gruppe auf dem Weg zur am n\u00e4chsten Gelegenen um auch diese Abzuschalten. Als sie das Geb\u00e4ude verlassen um sich auf den Weg zu machen entdecken sie das die zuvor gefundenen Leeren Rillen die den Boden durchziehen sich mit geschmolzenem Stein gef\u00fcllt haben welches ihrer Vermutung nach zuvor in das Konstrukt Herstellung genutzt wurde. Schnell erreichen sie die n\u00e4chste Produktionsstelle, nur um zu erkennen das anscheinend aus der Mitte der H\u00f6hle ausgehend, vom Mittelpunkt der Gewitterartigen Entladungen aus, eine kristalline Narbe sich nach au\u00dfen hin ausbreitet. Innerhalb der Narbe erkennen sie Zwerge die anscheinend Panisch vor irgendetwas Fl\u00fcchten.<\/p>\n<p>Ganze Ziegen Kutschen sowie mehrere Zug karren sind zu erkennen die anscheinend versucht haben dem, was dies ausgel\u00f6st hat, zu entkommen. Ein Teil des Geb\u00e4udes befindet sich innerhalb der Narbe und ist ebenfalls kristallisiert und hat somit seine Funktion eingestellt. Folgend auf eine Kurze Beratung einigt sich die Gruppe darauf sich auf den Weg in die Mitte der H\u00f6hle zu machen um herauszufinden was genau hier passiert ist und wo genau sich Dargoss befindet.\u00a0 Auf ihrem Weg hin zum Mittelpunkt beobachten sie wie die in Kristall eingefrorenen Zwerge immer mehr den Anschein erwecken alles fallen und liegen gelassen zu haben um Abstand zu gewinnen.<\/p>\n<p>Nachdem sie sich der Mitte weiter gen\u00e4hert haben vernehmen sie lautes Krachen. Sie erblicken Konstrukte die anscheinend gegeneinander k\u00e4mpfen. Schnell wird klar, dass es sich nicht um normale Konstrukte handelt da die eine Fraktion der beiden zum Teil mit kristallen bedeckt ist und gegen die \u201enormal\u201c aussehenden Konstrukte K\u00e4mpft. Diese reagieren auf die Ankunft der Gruppe empfindlich und beginnen sie einzukreisen. Nach einem Fehlschluss von Tragrim l\u00e4sst Alex eine ganze Gruppe der Konstrukte unter Verwendung des Zaubers levitieren schweben. Anschlie\u00dfend entbrennt ein hitziger Kampf gegen die anst\u00fcrmenden Konstrukte. Eines der von Alex angehobenen Konstrukte feuert einen weiteren Hitzestrahl ab und trifft Hakkon sowie Alex. Pl\u00f6tzlich wirft eines der gr\u00f6\u00dferen Humanoiden Konstrukte mit dem Spinnenf\u00f6rmigen nach Lee welche ihn jedoch verfehlt und neben ihm zerplatzt. Lee spannt seine Beinmuskeln an, springt hoch auf das schwebende Konstrukt und zerpulvert es mit blo\u00dfen F\u00e4usten.<\/p>\n<p>Zukuu, deutlich angespornt durch Lees Erfolg, nutzt seine schwarze Magie um einen weiteren Golem anzugreifen und richtet deutlichen Schaden an. Tragrim schie\u00dft wieder, Trift zur Abwechslung sogar sein Ziel und richtet ebenfalls deutlichen Schaden an. Hakkon verwandelt sich wieder in Wolf Form, und greift eines der Spinnen Konstrukte an gefolgt von mehreren Feuerb\u00e4llen die Alex gewirkt hat. Nachdem die Gruppe auf diese Weise alle sichtbaren Konstrukte zerst\u00f6rt hat, bricht aus einer nebenstehenden Halle ein Riesiges Humanoides Konstrukt hervor, welches von Kristallen besetzt ist. Entsetzt sieht die Gruppe das Konstrukt nahen und bereitet sich auf einen harten Kampf vor.<\/p>\n<p>Nach die Gruppe und das Konstrukt eine Reihe von Angriffen ausgetauscht haben, schwingt die Lage zugunsten des Konstrukts um. Es ergreift Lee an der Kehle und schl\u00e4gt ihm mit Wucht in die Magengrube. Lee gibt ein r\u00f6cheln von sich und wird anschlie\u00dfend zu Boden geschleudert wo er das Bewusstsein verliert. Nachdem der Rest der Gruppe den bewusstlosen Lee am Boden liegen sieht legt sich ein Schleier der Verzweiflung auf sie. In Panik attackiert die Gruppe das Konstrukt mit allen, ihn verbleibenden M\u00f6glichkeiten. Knapp schaffen sie es das Konstrukt so zu besch\u00e4digen das es seine Funktion einstellt. Nachdem Hakkon Lee behandelt hat zieht sich die Gruppe in das Lagerhaus aus dem das Konstrukt hervorgebrochen ist zur\u00fcck um sich eine Pause zu G\u00f6nnen. Dort finden mehrere tote Zwerge und Gesichtsfresser sowie den schwer verletzten Bruder Hakons, Hutan Runenleser.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Journey into the fallen City (Dragon Knife) \u201eWEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAHHHHHHHHHHHH\u201c Rotes Licht durchsucht systematisch das Areal und ein rhythmisches Lauter werdendes Stampfen k\u00fcndigt das ann\u00e4hern von Unbekannten Wesen an. In einem Anfall von Gruppen-Telepathie h\u00f6rt man f\u00f6rmlich wie sich jeder bis auf einen denkt \u201eALEX DU IDIOT\u201c. Unverst\u00e4ndliche Blicke gepaart mit Furcht gegen\u00fcber dem kommenden wandern durch [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[599],"tags":[],"class_list":["post-17734","post","type-post","status-publish","format-standard","hentry","category-gruppe20"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Journey into the fallen City (Dragon Knife) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Journey into the fallen City (Dragon Knife) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Journey into the fallen City (Dragon Knife) \u201eWEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAHHHHHHHHHHHH\u201c Rotes Licht durchsucht systematisch das Areal und ein rhythmisches Lauter werdendes Stampfen k\u00fcndigt das ann\u00e4hern von Unbekannten Wesen an. In einem Anfall von Gruppen-Telepathie h\u00f6rt man f\u00f6rmlich wie sich jeder bis auf einen denkt \u201eALEX DU IDIOT\u201c. Unverst\u00e4ndliche Blicke gepaart mit Furcht gegen\u00fcber dem kommenden wandern durch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-27T18:15:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-09T22:40:51+00:00\" \/>\n<meta name=\"author\" content=\"Erkumis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erkumis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/\"},\"author\":{\"name\":\"Erkumis\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/9bddd97b78f887c641ab19b0e08efebe\"},\"headline\":\"Journey into the fallen City (Dragon Knife)\",\"datePublished\":\"2017-08-27T18:15:34+00:00\",\"dateModified\":\"2018-03-09T22:40:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/\"},\"wordCount\":2174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"articleSection\":[\"Dragon Knife (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/\",\"name\":\"Journey into the fallen City (Dragon Knife) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"datePublished\":\"2017-08-27T18:15:34+00:00\",\"dateModified\":\"2018-03-09T22:40:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe20\\\/journey-into-the-fallen-city\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journey into the fallen City (Dragon Knife)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/9bddd97b78f887c641ab19b0e08efebe\",\"name\":\"Erkumis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/588e8c9a2e8e8b4e041105b8d97ac173847276e5f12b64ff6953ac776ceb2dd8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/588e8c9a2e8e8b4e041105b8d97ac173847276e5f12b64ff6953ac776ceb2dd8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/588e8c9a2e8e8b4e041105b8d97ac173847276e5f12b64ff6953ac776ceb2dd8?s=96&d=mm&r=g\",\"caption\":\"Erkumis\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/christoph\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Journey into the fallen City (Dragon Knife) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/","og_locale":"de_DE","og_type":"article","og_title":"Journey into the fallen City (Dragon Knife) - RPG-Berlin.de","og_description":"Journey into the fallen City (Dragon Knife) \u201eWEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAHHHHHHHHHHHH\u201c Rotes Licht durchsucht systematisch das Areal und ein rhythmisches Lauter werdendes Stampfen k\u00fcndigt das ann\u00e4hern von Unbekannten Wesen an. In einem Anfall von Gruppen-Telepathie h\u00f6rt man f\u00f6rmlich wie sich jeder bis auf einen denkt \u201eALEX DU IDIOT\u201c. Unverst\u00e4ndliche Blicke gepaart mit Furcht gegen\u00fcber dem kommenden wandern durch [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2017-08-27T18:15:34+00:00","article_modified_time":"2018-03-09T22:40:51+00:00","author":"Erkumis","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Erkumis","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/"},"author":{"name":"Erkumis","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/9bddd97b78f887c641ab19b0e08efebe"},"headline":"Journey into the fallen City (Dragon Knife)","datePublished":"2017-08-27T18:15:34+00:00","dateModified":"2018-03-09T22:40:51+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/"},"wordCount":2174,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"articleSection":["Dragon Knife (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/","name":"Journey into the fallen City (Dragon Knife) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"datePublished":"2017-08-27T18:15:34+00:00","dateModified":"2018-03-09T22:40:51+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe20\/journey-into-the-fallen-city\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Journey into the fallen City (Dragon Knife)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/9bddd97b78f887c641ab19b0e08efebe","name":"Erkumis","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/588e8c9a2e8e8b4e041105b8d97ac173847276e5f12b64ff6953ac776ceb2dd8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/588e8c9a2e8e8b4e041105b8d97ac173847276e5f12b64ff6953ac776ceb2dd8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/588e8c9a2e8e8b4e041105b8d97ac173847276e5f12b64ff6953ac776ceb2dd8?s=96&d=mm&r=g","caption":"Erkumis"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/christoph\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-4C2","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/17734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=17734"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/17734\/revisions"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=17734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=17734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=17734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}