{"id":13832,"date":"2017-05-21T00:54:43","date_gmt":"2017-05-20T22:54:43","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=13832"},"modified":"2018-09-09T10:09:09","modified_gmt":"2018-09-09T08:09:09","slug":"the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/","title":{"rendered":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians)"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-13834 size-medium alignleft\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?resize=300%2C188&#038;ssl=1\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?resize=300%2C188&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?resize=768%2C480&amp;ssl=1 768w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?w=900&amp;ssl=1 900w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians)<\/p>\n<p>The Adventurer hatten die D\u00e4monen besiegt und hatten als Belohnung von Zehnhammer eine Audienz beim Stadtrat bekommen. Als sie in den fr\u00fchen Morgenstunden aufgebrochen waren, \u00fcberkam ihn schon ein merkw\u00fcrdiges Gef\u00fchl. Als ein kleiner Junge mit schwarzen Harren eilend auf sie zukam und sie warnte, war allen klar das dieser Tag alles andere als normal werden w\u00fcrde. Sein Name war&nbsp;Geoffryn Kaladon und dessen Onkel,&nbsp;Lord Zatherin Kaladon wurde in der gleichen Nacht umgebracht von Rezmir einen Roten Magier aus Thay. Doch das sollte noch nicht alles sein, eine Armee von Oks hatten sich mittels Portal auf den Weg zur Stadt gemacht. Ausgangspunkt war der Mageholm Tower. Wie sie dar\u00fcber sprachen, h\u00f6rte man die Alarmglocke der Stadt l\u00e4uten. Ein monotones Stampfger\u00e4usch war auszumachen und schon tauchten die ersten Orks auf. Es blieb nicht viel Zeit und so rannte die Gruppe gen Osten, zum Stadttor. Unterwegs konnten Sie 4 Kinder retten, welche auf dem R\u00fccken von der verwandelten Shay, die als Pferd Ihr R\u00fccken anbot, sie vor die Stadt brachte. Auch die anderen waren nicht unt\u00e4tig und so schoss Kia unz\u00e4hlige Pfeile ab und die meisten trafen ihr Ziel.&nbsp; Ebenso geschickt ging Felicia mit ihrem Schwert um und der ein und andere Stadtbewohner w\u00e4re ohne sie von den Orks erschlagen worden, w\u00e4re sie nicht gewesen. Was Felica Ihr Schwert war war es bei Macer sein F\u00e4uste. Sie erreichten das zerst\u00f6rte Stadttor und erahnten das Sie hier in der Stadt nichts mehr ausrichten konnten. Die Stadt war dem Untergang geweiht. Die Thays hatten gewonnen, besser gesagt Rezmir und seine Schergen.<\/p>\n<p>Geoffryn Kaladon wartete auf seiner Schneem\u00e4hne vor den Stadtmauern auf Sie. Er gab den 4 Kindern, er war eigentlich selber noch ein Kind, einige Goldtaler und gab Ihnen Tips, woe sie in n\u00e4chster Zeit eine sichere Bleibe h\u00e4tten. Ein Waldhaus tief in den W\u00e4ldern war dabei die beste Option den Sie hatten. Nachdem die Kinder verschwunden waren setzte die Gruppe die Reise fort. Was w\u00fcrde sie erwarten? W\u00fcrden Sie in Greenest die Unterst\u00fctzung bekommen, wie Geoffryn es erhoffte. Dieses Mal hatten Sie keine andere Wahl um selber Hilfe f\u00fcr die Stadt zu suchen. Wer war dieser Rezmir und was wollte dieser?<\/p>\n<p>Nicht weit von Ihnen fl\u00fcchteten einige Kultisten in das Unterholz. Hinterher rannte eine Orkin und ein B\u00e4r, der sehr verwirrt schien. Ihnen folgte Ander. Cipher war nicht zu sehen, da er einer anderen kleineren Gruppe nachsetzt. Sie hatten schon einige Kultisten gestellt, doch nun wurde es gef\u00e4hrlich, V\u00f6glein zwitscherten und vor Ihnen lag eine Stra\u00dfe. Soweit bekannt war f\u00fchrte diese Stra\u00dfe nach Iriaebor und in weiter Ferne ersp\u00e4hten sie am Horizont auf einem H\u00fcgel eine Gruppe, einen wei\u00dfen Wolf und ein wei\u00dfes Pferd auf dem jemand sa\u00df.<\/p>\n<p>Rudger entdeckte als Erster eine Person hinter einem Baum und auch den Aufruf von Shay, sich der Gruppe zu erkennen zu geben schlug fehl. Pl\u00f6tzlich tauchten aus dem Unterholz mehrere dunkle Gestalten auf, sie schienen ein wenig uniformiert. Auf der linken Stra\u00dfenseite tauchten 3 dieser Gestalten auf und auf der rechten Seite waren es sogar noch mehr. Pl\u00f6tzlich ging alles blitzschnell, w\u00e4hrend Rudger ein Liedchen spielte und einige von den Banditen in die Flucht schlug, wurde Shay von mehreren Dolchen attackiert und verletzt. Macer der das mitbekommen hatte drosch mit seinen fliegenden F\u00e4usten und Tritten auf diesen ein bis er zusammenbrach. Pfeile surrten fanden aber nur selten ihre Ziele. Auch Kia konnte Anfangs kein genaues Ziel ausmachen und Ihr Wolf schnappte daneben. Anders hingegen Felicia, anders von den D\u00e4monen gewohnt schwang sie Ihr Schwert und teilte einen Angreifer in 2 H\u00e4lften. Noch bevor Shay zu einemZauber ansetzen konnte schoss Macer weiter nach vorne und verfolgte die panisch Fl\u00fcchtenden. Hier ein Tritt, da ein Schlag in die Nieren. Pl\u00f6tzlich knisteret die Luft und Macer sp\u00fcrte den Schmerz als die Fl\u00fcchtenden von einem Blitzschlag getroffen wurden und er davon ebenso getroffen wurde. Dem nicht genug, pl\u00f6tzlich entflammte ein Angreifer v\u00f6llig und loderte.<\/p>\n<p>Dem Blick nach vorne gerichtet sahen die Adventurer einen B\u00e4ren, eine Orkin und einen halbnackten Mann, desen H\u00e4nde noch von Feuer umfangen war. Die Okrin rannte mit lautem Gebr\u00fcll los holte Schwung, drosch Ihren Kriegshammer eine einen Baum z\u00fcckte Ihren Speer und surrend traf er sein Ziel. Dieser durchdrang den K\u00f6rper eines weiteren Angreifers und kurz darauf knistere die Luft und ein Strahl aus blau-violetten Licht, schoss auf diese arme Person herab, bis nur noch ein verkohltes Etwas auf der Stra\u00dfe steckte.<\/p>\n<p>Schnell waren die Angreifer bezwungen und einziger \u00dcberlebender hatte Gl\u00fcck gehabt. Schnell hatten die beiden Gruppen sich vorgestellt und w\u00e4hrend Felica den \u00dcberlebenden festhielt, verh\u00f6rte Thredi ihn auf Ihre Weise. Ander sammelte den von Toten ihre Habseligkeiten ein und begab sich dann auch zu dem Verh\u00f6r. W\u00e4hrend Geoffryn sich mit Anakis und Ander sich unterhielt. Brachte die Orkin einige Informationen aus&nbsp; Gefangenen heraus. Anscheinen wollte diese Gruppe verhindern das H\u00e4ndler oder Reisende der Stadt Iriaebor erreichten, Auftraggeber war niemand geringer als Rezmir der Rote Magier aus Thay. Nun f\u00fcgten sich wieder einige Puzzleteile zusammen. Doch die meisten Informationen bekamen die Adventurer von den Legacy of the Grey Guardians selber. Die Tatsache das die Maske von Tiamat, zerschlagen in mehrere Puzzleteile die Sache nicht besser machte, das Buch: Vile of the Darkness&nbsp; h\u00f6chstwahrscheinlich die Kerzenburg nie erreicht hatte und der Zustand von Greenest machte die Hoffnung einer schnellen Rettung Iriaebor zunichte.<\/p>\n<p>Pl\u00f6tzlich schoss ein Pfeil aus dem dicken Unterholz und traf die Orkin, die noch beim Verh\u00f6r des Gefangegenen war. Blitze zuckten um den Pfeil herum und schnell war klar das hier ein Scharfsch\u00fctze sie aufs Korn genommen hatte. Verdammt. Schnell standen die Gruppen beisamen. Ander wollte schon einenn Feuerball werfen, da hielt Ihn Rudger zur\u00fcck und war kurz darauf verschwunden. Es dauerte nicht lange wurde er sichtbar un ein Pfeil steckte in seiner Schulter, er hatte zwar Spuren gefunden, aber die waren geschickt gelegt. Rudger zog sich zur\u00fcck zur Gruppe.<\/p>\n<p>Nun platze Ander der Kragen und wollte seinen Feuerball losschicken, doch er stellte fest das er aus seinem Mund keine Worte kamen. Das bemerkten auch die anderen und auch Shay hatte Probleme ihren Zauber zu wirken. Schnell war eine blaue Rune die sich unter der Borke eines Baumes verbarg ausgemacht und zerst\u00f6rt. Danach setzte Ander nochmal an und dieses Mal gelang es Ihm. Erst eine Explosion, dann knisterten Flammen durch das Dickicht und es breitete sich sehr schnell aus. Die Gruppen schlossen sich zusammen und brachen nach Greenest auf. Unterwegs tarfen sie noch auf Cipher, der anscheinend auch sehr erfolgreich war. So erreichten sie nach 2 Tagen Greenest.<\/p>\n<p>&nbsp;<\/p>\n<p>Erfahrungspunkte: 180 f\u00fcr jeden<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Tyranny_of_Dragons.png?resize=690%2C138&#038;ssl=1\" alt=\"\" class=\"wp-image-18754\" width=\"690\" height=\"138\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Tyranny_of_Dragons.png?w=920&amp;ssl=1 920w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Tyranny_of_Dragons.png?resize=300%2C60&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2018\/09\/Tyranny_of_Dragons.png?resize=768%2C154&amp;ssl=1 768w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) The Adventurer hatten die D\u00e4monen besiegt und hatten als Belohnung von Zehnhammer eine Audienz beim Stadtrat bekommen. Als sie in den fr\u00fchen Morgenstunden aufgebrochen waren, \u00fcberkam ihn schon ein merkw\u00fcrdiges Gef\u00fchl. Als ein kleiner Junge mit schwarzen Harren eilend auf sie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[521,547],"tags":[],"class_list":["post-13832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe14","category-gruppe16"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) The Adventurer hatten die D\u00e4monen besiegt und hatten als Belohnung von Zehnhammer eine Audienz beim Stadtrat bekommen. Als sie in den fr\u00fchen Morgenstunden aufgebrochen waren, \u00fcberkam ihn schon ein merkw\u00fcrdiges Gef\u00fchl. Als ein kleiner Junge mit schwarzen Harren eilend auf sie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-20T22:54:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-09T08:09:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/\"},\"author\":{\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\"},\"headline\":\"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians)\",\"datePublished\":\"2017-05-20T22:54:43+00:00\",\"dateModified\":\"2018-09-09T08:09:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/\"},\"wordCount\":1180,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1\",\"articleSection\":[\"The Adventurer (inaktiv)\",\"The Legacy of the Grey Guardians\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/\",\"name\":\"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1\",\"datePublished\":\"2017-05-20T22:54:43+00:00\",\"dateModified\":\"2018-09-09T08:09:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1\",\"width\":900,\"height\":563},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe16\\\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\",\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"caption\":\"Thinkleblink\\\/Dalwick (Mirko)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/","og_locale":"de_DE","og_type":"article","og_title":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) - RPG-Berlin.de","og_description":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) The Adventurer hatten die D\u00e4monen besiegt und hatten als Belohnung von Zehnhammer eine Audienz beim Stadtrat bekommen. Als sie in den fr\u00fchen Morgenstunden aufgebrochen waren, \u00fcberkam ihn schon ein merkw\u00fcrdiges Gef\u00fchl. Als ein kleiner Junge mit schwarzen Harren eilend auf sie [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2017-05-20T22:54:43+00:00","article_modified_time":"2018-09-09T08:09:09+00:00","og_image":[{"width":900,"height":563,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1","type":"image\/png"}],"author":"Thinkleblink\/Dalwick (Mirko)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thinkleblink\/Dalwick (Mirko)","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/"},"author":{"name":"Thinkleblink\/Dalwick (Mirko)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec"},"headline":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians)","datePublished":"2017-05-20T22:54:43+00:00","dateModified":"2018-09-09T08:09:09+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/"},"wordCount":1180,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1","articleSection":["The Adventurer (inaktiv)","The Legacy of the Grey Guardians"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/","name":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1","datePublished":"2017-05-20T22:54:43+00:00","dateModified":"2018-09-09T08:09:09+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1","width":900,"height":563},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe16\/the-adventurer-the-legacy-of-the-grey-guardians-the-adventurer-the-legacy-of-the-grey-guardians\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Von Fl\u00fcchtenden und einer besonderen Maske (The Adventurer, The Legacy of the Grey Guardians)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec","name":"Thinkleblink\/Dalwick (Mirko)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","caption":"Thinkleblink\/Dalwick (Mirko)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2017\/05\/27d7f7b7-fd51-4cbc-9133-bb1cd4d5c271.png?fit=900%2C563&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-3B6","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/13832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=13832"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/13832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/13834"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=13832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=13832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=13832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}