{"id":12446,"date":"2016-08-23T19:29:00","date_gmt":"2016-08-23T17:29:00","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=12446"},"modified":"2018-04-15T21:02:35","modified_gmt":"2018-04-15T19:02:35","slug":"bennet","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/","title":{"rendered":"Bennet"},"content":{"rendered":"<p><a href=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp\"><img decoding=\"async\" class=\"alignleft wp-image-12447 size-full\" src=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp\" alt=\"Bennet\" width=\"203\" height=\"279\" \/><\/a>Bennet wuchs in einem Waisenhaus auf.<br \/>\nSeine Mutter verstarb kurz nach der Geburt. Sein Vater, Salth\u00b4oh\u00f3re B\u00b4nn\u00b4oreth war F\u00fchrer in einer Gro\u00dfen Stadt und f\u00fchrte zuletzt eine wichtige Expedition im Auftrag des K\u00f6nigs auf der er letztlich verschwand.<br \/>\nEs begab sich zu jener Zeit das sich ein gro\u00dfes \u00dcbel, etwas B\u00f6ses von unterhalb der Stadt ank\u00fcndigte. Eine Expedition in die Katakomben und Kanalisation der Stadt sollte unternommen werden um herauszufinden, um was f\u00fcr eine Gefahr es sich handelte.<br \/>\nWently Kelso ein Gelehrter und zwei seiner Lehrlinge sollten die Expedition leiten. Doch sie brauchten einen F\u00fchrer. Der beste war zu jener Zeit eben dieser<br \/>\nSalth\u00b4oh\u00f3re B\u00b4nn\u00b4oreth.<br \/>\nDie Expedition verschwand und kehrte nie zur\u00fcck. Einige Zeit danach kamen seltsame Kreaturen nach und nach aus dem Untergrund. Es wurden vier Helden losgeschickt die Bedrohung zur\u00fcckzuschlagen.<br \/>\nAuf ihrem Weg entdeckten sie ein Tagebuch von der vorausgegangenen Expedition, was ihnen eine gro\u00dfe Hilfe war auf ihrem langen Weg in die Tiefen wo sie letztendlich nach \u00fcber einem Monat ein m\u00e4chtiges b\u00f6ses Wesen genannt &#8222;Beholder&#8220; stellten und vernichteten.<\/p>\n<p>In der Tagebuch schrieb Wently Kelso ganz zu Anfang:<\/p>\n<p>&#8222;Our guide is a mangy humanoid of indeterminate species. I can&#8217;t\u00a0 pronounce his real name, so I call him Bennet, in honor of my mangy half-brother on my mothers side of the family.&#8220;<\/p>\n<p>Man \u00fcberreichte dem Jungen als einzige \u00dcberreste eine Abschrift dieser Aufzeichnungen.<br \/>\nDer Junge war fasziniert von dem Bericht. Von nun an stahl er sich immer wieder weg um selbst in der Kanalisation und den Katakomben der Stadt herumzustreunen. Er verschwand immer wieder mehrere Tage aus dem Waisenhaus. Er kehrte sich immer mehr in sich, verlor sich in seiner Phantasie die dem Bericht nachhing und insgeheim hoffte er vielleicht sogar irgendwann seinen Vater zu finden. Vielleicht lebte dieser ja doch noch.<\/p>\n<p>Irgendwann verlie\u00df er die Stadt um in der N\u00e4he in kleineren St\u00e4dten nach weiteren Katakomben und H\u00f6hlen zu suchen da er in der seiner Heimatstadt nicht weiterkam. Er \u00e4nderte seinen Namen in Bennet so wie sein Vater in dem Bericht genannt wurde und zog los&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>[pdf-embedder url=&#8220;https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/DnD_5E_CharacterSheet-Form-Fillable-Bennet.pdf&#8220; title=&#8220;DnD_5E_CharacterSheet-Form-Fillable Bennet&#8220;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bennet wuchs in einem Waisenhaus auf. Seine Mutter verstarb kurz nach der Geburt. Sein Vater, Salth\u00b4oh\u00f3re B\u00b4nn\u00b4oreth war F\u00fchrer in einer Gro\u00dfen Stadt und f\u00fchrte zuletzt eine wichtige Expedition im Auftrag des K\u00f6nigs auf der er letztlich verschwand. Es begab sich zu jener Zeit das sich ein gro\u00dfes \u00dcbel, etwas B\u00f6ses von unterhalb der Stadt [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":12447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[564],"tags":[],"class_list":["post-12446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bennet-uli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bennet - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bennet - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Bennet wuchs in einem Waisenhaus auf. Seine Mutter verstarb kurz nach der Geburt. Sein Vater, Salth\u00b4oh\u00f3re B\u00b4nn\u00b4oreth war F\u00fchrer in einer Gro\u00dfen Stadt und f\u00fchrte zuletzt eine wichtige Expedition im Auftrag des K\u00f6nigs auf der er letztlich verschwand. Es begab sich zu jener Zeit das sich ein gro\u00dfes \u00dcbel, etwas B\u00f6ses von unterhalb der Stadt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-23T17:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-15T19:02:35+00:00\" \/>\n<meta name=\"author\" content=\"Fenner (Uli)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fenner (Uli)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/\"},\"author\":{\"name\":\"Fenner (Uli)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/a67ea60907abee125c84ebb011eb771e\"},\"headline\":\"Bennet\",\"datePublished\":\"2016-08-23T17:29:00+00:00\",\"dateModified\":\"2018-04-15T19:02:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/\"},\"wordCount\":384,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Bennet-1.2.bmp\",\"articleSection\":[\"Bennet (Uli)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/\",\"name\":\"Bennet - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Bennet-1.2.bmp\",\"datePublished\":\"2016-08-23T17:29:00+00:00\",\"dateModified\":\"2018-04-15T19:02:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Bennet-1.2.bmp\",\"contentUrl\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Bennet-1.2.bmp\",\"width\":203,\"height\":279},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/character\\\/aktive_sc\\\/strider-of-the-ghostpath\\\/bennet-uli\\\/bennet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bennet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/a67ea60907abee125c84ebb011eb771e\",\"name\":\"Fenner (Uli)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/389d0e401f3fc213951a5958692120832adcd795b34f1408b24a10b3d3f655ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/389d0e401f3fc213951a5958692120832adcd795b34f1408b24a10b3d3f655ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/389d0e401f3fc213951a5958692120832adcd795b34f1408b24a10b3d3f655ed?s=96&d=mm&r=g\",\"caption\":\"Fenner (Uli)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/uli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bennet - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/","og_locale":"de_DE","og_type":"article","og_title":"Bennet - RPG-Berlin.de","og_description":"Bennet wuchs in einem Waisenhaus auf. Seine Mutter verstarb kurz nach der Geburt. Sein Vater, Salth\u00b4oh\u00f3re B\u00b4nn\u00b4oreth war F\u00fchrer in einer Gro\u00dfen Stadt und f\u00fchrte zuletzt eine wichtige Expedition im Auftrag des K\u00f6nigs auf der er letztlich verschwand. Es begab sich zu jener Zeit das sich ein gro\u00dfes \u00dcbel, etwas B\u00f6ses von unterhalb der Stadt [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2016-08-23T17:29:00+00:00","article_modified_time":"2018-04-15T19:02:35+00:00","author":"Fenner (Uli)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Fenner (Uli)","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/"},"author":{"name":"Fenner (Uli)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/a67ea60907abee125c84ebb011eb771e"},"headline":"Bennet","datePublished":"2016-08-23T17:29:00+00:00","dateModified":"2018-04-15T19:02:35+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/"},"wordCount":384,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#primaryimage"},"thumbnailUrl":"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp","articleSection":["Bennet (Uli)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/","url":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/","name":"Bennet - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#primaryimage"},"thumbnailUrl":"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp","datePublished":"2016-08-23T17:29:00+00:00","dateModified":"2018-04-15T19:02:35+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#primaryimage","url":"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp","contentUrl":"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp","width":203,"height":279},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/character\/aktive_sc\/strider-of-the-ghostpath\/bennet-uli\/bennet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Bennet"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/a67ea60907abee125c84ebb011eb771e","name":"Fenner (Uli)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/389d0e401f3fc213951a5958692120832adcd795b34f1408b24a10b3d3f655ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/389d0e401f3fc213951a5958692120832adcd795b34f1408b24a10b3d3f655ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/389d0e401f3fc213951a5958692120832adcd795b34f1408b24a10b3d3f655ed?s=96&d=mm&r=g","caption":"Fenner (Uli)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/uli\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/08\/Bennet-1.2.bmp","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s4p3r6-bennet","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/12446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=12446"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/12446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/12447"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=12446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=12446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=12446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}