{"id":12198,"date":"2016-06-16T23:07:46","date_gmt":"2016-06-16T21:07:46","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=12198"},"modified":"2018-02-03T22:22:21","modified_gmt":"2018-02-03T21:22:21","slug":"aufbruch-ins-abenteuer","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/","title":{"rendered":"Aufbruch ins Abenteuer (Strider of the Ghostpath)"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft wp-image-12217 size-medium\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?resize=300%2C225&#038;ssl=1\" alt=\"Aufbruch ins Abenteuer (Strider of the Ghostpath)\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?w=1024&amp;ssl=1 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Aufbruch ins Abenteuer (Strider of the Ghostpath)<\/p>\n<p>Und so zzzziehe ich hinaussss in die Welt. Ich Tharm, der schhhhl\u00fcpfte als der Blutmond am Himmel stand. Ssssagt Hoar nicht ein Auge f\u00fcr ein Auge und ihr Blut f\u00fcr mein Blut? Irgendwann werde ich Ihr Blut nehmen. Doch bissss dahin habe ich Zzzzzeit meine Rache zzzzu planen. Nur ein klarer Geissst, kann einen Gedanken fassssen.<\/p>\n<p>Ich bessssuchte Norvarkin, den gro\u00dfsssen Schhhhamanen, er isssst vom Alter gezzzzeichnet, doch ssssein Geissst issst klarer als ein blauer Himmel bei Ssssonnenaufgang. Er wies mir den Weg f\u00fcr meine Rache und daher werde ich an ssseiner Sssstatt das Wiesssel begleiten, zu diesssem Ort mit den traurigen Bildern. Und wenn die Grenzzzen dort zzzur Geissssterwelt ssso schhhwach ssssind wie esss der Schhhhamane verlauten l\u00e4ssst, dann werde ich dort mit den Meinigen reden k\u00f6nnen und erfahren, wer essss gewesssen issst, der Ihr Blut nahm.<\/p>\n<p>In der Stadt Helmstedt bin ich auf einen Priester des Totengottesss Kelemvor getroffen, der Begleitung ssssucht f\u00fcr eine Reissse die in meine Richtung geht und ich habe mich entschhhhlosssssen mit ihm zu reisssen, denn heisssst essss nicht, dasss man die Schhhwachen schhhh\u00fctzen mussss. Au\u00df\u00df\u00df\u00dferdem isssst er ein Priessster einessss Totengottessss und wassss g\u00e4be essss nicht f\u00fcr ein bessseres Zzzzeichen f\u00fcr meine Reisssse alssss ssssolch einen zzzzu begleiten. Ich denke er wird mir Gl\u00fcck bringen.<\/p>\n<p>Er heissst Weilandson und hat einen kleinen Helfer dabei, der teilweisssse eher unwichtigessss Wisssssen zu verbreiten schhhheint, aber davon hat er recht viel. Dessss weiten haben wir einen kleinen Halbling auf einem Hund dabei, Nick, ein guter F\u00e4hrtenlesssser, wenn auch kein gro\u00df\u00df\u00dfer Krieger, sowie einen wie mir schhhheint Halbriesen mit Namen Kaaran. Ihm sieht man an, dasss er schhhhon viele Leben genommen hat, aber er schhheint die Gesssselschhhhhaft anderer eher zu meiden, denn er raucht ein abscheulich riechendessss Kraut. Ansssssonsten haben wir noch einen kleinen Mann mit dabei der sich immer hecktischhhh umzzzzusssssehen schhhheint, er heissst Bennet und einen Zzzzwerg, der wohl ein Schhhhmied zzzzu ssssein schhheint, aber gekleidet isssst, alsss w\u00fcrde er gro\u00df\u00df\u00dfe Angsssst haben, verletzzzt zu werden. Ranock. Aber ich habe geh\u00f6rt dasss Zzzzwerge gute K\u00e4mpfer sssssind, daher lasssse ich mich von sssseiner Eissssenhaut nicht t\u00e4uschhhhen und wir werden sssssehen, wievel er im Kampf taugt.<\/p>\n<p>Einen Tag nach der Abreise von der letzten sicheren Schhhh\u00e4nke, fand ich zzzzusssssammen mit Nick Wargsssspuren im Grasss neben unssserer Reisssseroute zu dem Tal, wo unssserer Priessster den Tempel des Myrkul Kelemvor weihen will. Wir r\u00e4tsssselten eine Weile ob essss vielleicht nicht doch ein Wolf war, aber dassss sssstellte sssssich alssss unwarschhhheinlich herausss, weil W\u00f6lfe sssselten allein wandern. Doch darauf angesprochen ignorierte Pater Weilandssssson diessse wo m\u00f6gliche Gefahr mit den Worten \u201eWir m\u00fcsssssen alle einmal sssterben.\u201c Da hat er nicht Unrecht, aber meine Zzzzeit wird, so Hoar es will, erssst nach der Erf\u00fcllung meiner Rache kommen. Ich hatte noch eine gute Unterhaltung mit Bennet, w\u00e4hrend ssssich Ranock begann mit Kaaran anzzzzufreunden und ich mir fesssst vorgenommen habe ihn dann ebenfallssss zzzzu meiden, oder in einen Eimer mit Wasssser zzzzu stecken, sssso bald er ebenfallssss zu sssstinken beginnt wie Kaaaran.<\/p>\n<p>Kurz bevor wir das Tal erreichten, wo sssssich der Tempel befinden sssssollte, ersssp\u00e4hte Bennet einen Ork in der Ferne. Diessser blieb aber au\u00dfssser Reichweite und ssssso setzen wir unssseren Weg fort. Der Priesssster kl\u00e4rte unsss noch auf, dasss in dem Tal in dasss wir reisssten, die Bev\u00f6lkerung ausss Mischhhhwessssen aller Rasssen zu bessstehen schhhheint. Was sssssie in meiner Achtung aber nicht ssssinken liesss, k\u00f6nnen doch alle V\u00f6lker gro\u00dfssse Krieger hervorbringen, warum dann nicht auch ein sssssolches.<\/p>\n<p>Der Eingang dessss Tals wurde von zzzzwei riesssigen Elfensssstatuen bewacht, die einander umarmen zzzzu schhhhienen. Und von dort wurden wir von zzzzzwei Halborks begr\u00fc\u00dfssst, denen wir unsssser Vorhaben schhhhildern mussssten, die unsss aber dann durchlie\u00dfsssen. Das ganze Tal schhhheint ein einzzziger Wald zzzzu sein. Daher fand ich essss damalssss unverssssst\u00e4ndlich, wie ssssich hier ein ganzzzes Volk ern\u00e4hren ssssolte. Wir gingen einen langen Weg durchhh einen dichten Wald hindurch, bisss wir in einen teuflischhhhen Hinterhalt gerieten. Essss war der schhhhlimmssste aller zu bef\u00fcrchtenden Feinde. Kleine Kinder. Ich mussste laut lachen und zzzzu meinen Erssstaunen waren zzzumindesssstensss Teile von ihnen nicht ssssso leicht zzzzu erschhhhrecken wie ich gedacht hatte. Nach schhhhweren Verhandlungen lie\u00dfssst Bennet einige Glasmurmeln als Wegezzzoll bei den Kleinen und wir durften weiter reisssen. Gl\u00fccklicherweisssse hinterlasssen Holzzzzschhhwerter keine zzzzu gro\u00dfsssen Wunden.<\/p>\n<p>Weiter den Weg entlang kamen wir dann endlich in dasss Tal und zzzzu H\u00e4usssern. Dort wurden wir begr\u00fc\u00dfssst und von der Dorf\u00e4ltesssten, eine Halbelfe mit Hirschgeweih mit Namen Lariel empfangen. Gerade alssss wir mit ihr ssssprachen, donnerte esss vom Passssseingang her und wenig ssssp\u00e4ter erklang das Horn desss einen Halborksss, der am Taleingang alssss Wache gessstanden hatte.<\/p>\n<p>Sssso riefen wir die K\u00e4mpfer desss Dorfesss zzzzusssammen und beratschhhhlagten wassss nun zzzzu tun sssei. Am Ende kam herausss, dasss eine Halborkin mit Namen Misssssa und ich aussskundschhhaften ssssolten wassss am Taleingang vor ssssich ging, w\u00e4hrend der Ressst ssssich darum k\u00fcmmert dasss Dorf in Ssssicherheit zzzzu bringen.<\/p>\n<p>Zzzzzussssammen gingen wir alsssso voran, wasss auch immer unsss erwarten w\u00fcrde. Doch erssst einmal fanden wir nichtssss bisss wir auf Rufe im Wald aufmerkssssam wurden und dann einige Orkssss entdeckten, die nach irgendetwasss auf der Jagd waren. Und dassss Irgendetwasss entpuppte ssssich alssss Bennet. Tapferer kleiner Mann, der sssich gleich gegen zzzzwei Orks in den Kampf warf, die ihn aber niedermachten. Doch die G\u00f6tter waren mit ihm, da Missssssa und ich die beiden \u00fcberraschhhhen konnten und ssssie unssss nichtsss entgegenzzzussssetzen hatten. Leider blieb keine Zeit Troph\u00e4en zzzu nehmen, aber Bennet war zzzzu schhhhwer verwundet und mussste schhhhnell wieder insss Dorf und auch der Kampf war nicht ssso gro\u00dfsssartig gewesssen alssss dasss er h\u00e4tte in Liedern besssungen werden m\u00fcssssen. Au\u00dfssserdem sssstellte ssssich herausss dasss Bennet ein kleinesss M\u00e4dchen gerettet hatte. Die widersssspenssstige Kleine vom Hinterhalt auf unssss.<\/p>\n<p>Und sssso machten wir unssss wieder auf den Weg zzzzur\u00fcck. Dort hatten die Dorfbewohner begonnen, an ihrem Kreissss der Macht eine Schhhhutzbarriere zzzzu ersssstellen. Doch Bennet \u00f6ffnete das Tor zum Temel des Myrkul und nach einiger Zzzzeit beschhhlossssen wir, die Dorfbewohner in den Temel zzzzu bringen, da wir ssssie dort bessser verteidigen konnten. Und sssso schhhafften wir ssssie. Alle vom Zauberritual sssehr geschhhhw\u00e4cht in dem Tempel. W\u00e4hrenddessssen Bennet und Ranock den Tempel ein wenig genauer untersssuchten. Gerade alsss wir alle im Tempel und die Verteidigung bessssprochen hatten, kam vor dem Tempel Bewegung auf und ein gro\u00dfer Ork trat aussss den B\u00fcschhhen herausss.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufbruch ins Abenteuer (Strider of the Ghostpath) Und so zzzziehe ich hinaussss in die Welt. Ich Tharm, der schhhhl\u00fcpfte als der Blutmond am Himmel stand. Ssssagt Hoar nicht ein Auge f\u00fcr ein Auge und ihr Blut f\u00fcr mein Blut? Irgendwann werde ich Ihr Blut nehmen. Doch bissss dahin habe ich Zzzzzeit meine Rache zzzzu planen. [&hellip;]<\/p>\n","protected":false},"author":98,"featured_media":12217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[549],"tags":[],"class_list":["post-12198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe17"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aufbruch ins Abenteuer (Strider of the Ghostpath) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aufbruch ins Abenteuer (Strider of the Ghostpath) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Aufbruch ins Abenteuer (Strider of the Ghostpath) Und so zzzziehe ich hinaussss in die Welt. Ich Tharm, der schhhhl\u00fcpfte als der Blutmond am Himmel stand. Ssssagt Hoar nicht ein Auge f\u00fcr ein Auge und ihr Blut f\u00fcr mein Blut? Irgendwann werde ich Ihr Blut nehmen. Doch bissss dahin habe ich Zzzzzeit meine Rache zzzzu planen. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-16T21:07:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-03T21:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arrat Bredan\/Xalasar (Jan)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arrat Bredan\/Xalasar (Jan)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/\"},\"author\":{\"name\":\"Arrat Bredan\\\/Xalasar (Jan)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/514594fb505b033cd4a28fb585e692cb\"},\"headline\":\"Aufbruch ins Abenteuer (Strider of the Ghostpath)\",\"datePublished\":\"2016-06-16T21:07:46+00:00\",\"dateModified\":\"2018-02-03T21:22:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/\"},\"wordCount\":1124,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1\",\"articleSection\":[\"Strider of the Ghostpath (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/\",\"name\":\"Aufbruch ins Abenteuer (Strider of the Ghostpath) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1\",\"datePublished\":\"2016-06-16T21:07:46+00:00\",\"dateModified\":\"2018-02-03T21:22:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe17\\\/aufbruch-ins-abenteuer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aufbruch ins Abenteuer (Strider of the Ghostpath)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/514594fb505b033cd4a28fb585e692cb\",\"name\":\"Arrat Bredan\\\/Xalasar (Jan)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80cd0c195c5b11ff161628d19baab6089e99b3027603cd11fccb463425c973a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80cd0c195c5b11ff161628d19baab6089e99b3027603cd11fccb463425c973a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80cd0c195c5b11ff161628d19baab6089e99b3027603cd11fccb463425c973a3?s=96&d=mm&r=g\",\"caption\":\"Arrat Bredan\\\/Xalasar (Jan)\"},\"description\":\"33 Jahre, Bundeswehrfachschule, komme aus Erkner, wohne in Berlin Lichtenberg, war 12 Jahre bei der Marine, davor habe ich Kartograph gelernt. Schaue und Lese gerne Fantasy, Sci-Fi, Horror, Krimi und Historiensachen.\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/jan-richter\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aufbruch ins Abenteuer (Strider of the Ghostpath) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/","og_locale":"de_DE","og_type":"article","og_title":"Aufbruch ins Abenteuer (Strider of the Ghostpath) - RPG-Berlin.de","og_description":"Aufbruch ins Abenteuer (Strider of the Ghostpath) Und so zzzziehe ich hinaussss in die Welt. Ich Tharm, der schhhhl\u00fcpfte als der Blutmond am Himmel stand. Ssssagt Hoar nicht ein Auge f\u00fcr ein Auge und ihr Blut f\u00fcr mein Blut? Irgendwann werde ich Ihr Blut nehmen. Doch bissss dahin habe ich Zzzzzeit meine Rache zzzzu planen. [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2016-06-16T21:07:46+00:00","article_modified_time":"2018-02-03T21:22:21+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1","type":"image\/jpeg"}],"author":"Arrat Bredan\/Xalasar (Jan)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Arrat Bredan\/Xalasar (Jan)","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/"},"author":{"name":"Arrat Bredan\/Xalasar (Jan)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/514594fb505b033cd4a28fb585e692cb"},"headline":"Aufbruch ins Abenteuer (Strider of the Ghostpath)","datePublished":"2016-06-16T21:07:46+00:00","dateModified":"2018-02-03T21:22:21+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/"},"wordCount":1124,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1","articleSection":["Strider of the Ghostpath (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/","name":"Aufbruch ins Abenteuer (Strider of the Ghostpath) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1","datePublished":"2016-06-16T21:07:46+00:00","dateModified":"2018-02-03T21:22:21+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe17\/aufbruch-ins-abenteuer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Aufbruch ins Abenteuer (Strider of the Ghostpath)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/514594fb505b033cd4a28fb585e692cb","name":"Arrat Bredan\/Xalasar (Jan)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/80cd0c195c5b11ff161628d19baab6089e99b3027603cd11fccb463425c973a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80cd0c195c5b11ff161628d19baab6089e99b3027603cd11fccb463425c973a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80cd0c195c5b11ff161628d19baab6089e99b3027603cd11fccb463425c973a3?s=96&d=mm&r=g","caption":"Arrat Bredan\/Xalasar (Jan)"},"description":"33 Jahre, Bundeswehrfachschule, komme aus Erkner, wohne in Berlin Lichtenberg, war 12 Jahre bei der Marine, davor habe ich Kartograph gelernt. Schaue und Lese gerne Fantasy, Sci-Fi, Horror, Krimi und Historiensachen.","url":"https:\/\/rpg-berlin.de\/rpg\/author\/jan-richter\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/06\/necromancer_by_shaman_2000-d5t4gnj.jpg?fit=1024%2C768&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-3aK","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/12198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=12198"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/12198\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/12217"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=12198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=12198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=12198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}