{"id":12024,"date":"2016-04-30T22:54:06","date_gmt":"2016-04-30T20:54:06","guid":{"rendered":"http:\/\/rpg-berlin.de\/rpg\/?p=12024"},"modified":"2018-02-03T22:43:27","modified_gmt":"2018-02-03T21:43:27","slug":"die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/","title":{"rendered":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)"},"content":{"rendered":"<p><strong><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignleft wp-image-12037 size-medium\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?resize=300%2C169&#038;ssl=1\" alt=\"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)\" width=\"300\" height=\"169\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?w=800&amp;ssl=1 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"line-height: 1.5;\">Die Gruppe hatte sich nach einiger Zeit in der Stadt Yenching \u00a0im Reiche Karatur eingelebt und Kultur und Sprache soweit wie m\u00f6glich in kurzer Zeit kennengelernt. Sie holten allerlei Informationen zusammen und konnten so ihre n\u00e4chsten Schritte planen wir sie am besten der j\u00fcngsten Prinzessin Schutz geben k\u00f6nnten und wie sie dem Kyo Clan zuvorkommen konnten um eine m\u00f6gliche Entf\u00fchrung von Miou verhindern w\u00fcrden.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Die Abenteurer stellten fest, das es eine F\u00e4de zwischen dem Sakura Clan und dem Kyo Clan gab. Man h\u00f6rte das der Kyo Clan mit dem lang vergessenen Ony Clan zusammenarbeitet, diese hielten sich anscheinend im Gebirgswald und in einer Goldmine nahe dem Dorf Imashou versteckt. Die Anh\u00e4nger des Kyo Clans haben anscheinend alle eine Schlange auf ihrer Haut t\u00e4towiert. Der Kyo Clan trachtete, Ger\u00fcchten zuvolge, nach dem Blut der j\u00fcngsten Tochter des Sakura Clans, bevor diese heiratet (was anscheinend auch bald geschehen sollte, Myou soll mit einem Prinzen aus dem Nachbarreich verheiratet werden damit die guten Handelbeziehungen bestehen bleiben). Wenn der Kyo Clan das Blut von Myou in die H\u00e4nde bek\u00e4me, w\u00fcrden sie ein Abyss Tor beschw\u00f6ren um warscheinlich einen m\u00e4chtigen verb\u00fcndeten D\u00e4mon auf ihrer Seite zu haben. Dies sollte nat\u00fcrlich schnellstens verhindet werden. Also suchte der Kult der Verdammten in der Stadt Yenching nach Hinweisen um einer Verbindung zum Kyo Clan zu finden.<\/p>\n<p>&nbsp;<\/p>\n<p>Es stellte sich auch heraus das in manchen Ecken der Stadt Menschenhandel getrieben wurde, was aber strengstens verboten war und worauf die Todesstrafe stand. Der Wirt Erc aus einem der Bordelle bot gelegentlich seiner Kundschaft Sklaven an. Ein Holzf\u00e4ller namens Almageit war vor kurzem hingerichtet, weil er am vom Hauptmann entdeckt wurde wie er zwei Sklaven nach Yenching schmuggeln wollte. Hauptmann Riku erz\u00e4hlte das der Holf\u00e4ller Almageit geistesabwesend am helligten Tag die Sklaven auf offenem Weg f\u00fchrte. Die Sklaven wurden von ihren Fessen befreit und Almageit wurde ohne Wiederstand festgenommen.<\/p>\n<p>&nbsp;<\/p>\n<p>Sota der Vorstand der Holzf\u00e4llergilde sagte, das Almageit in den letzten drei Monaten sehr unzuverl\u00e4ssig war und schlechte Arbeiten ablieferte obwohl er Hilfe von Tuptin hatte, eine Prostituierte die bei ihm wohnte und auch mitarbeitete. Man sagte das Almageit im Kasino der Stadt zu Geld gekommen war, dort war er anscheinend oft nach der Arbeit. Tuptin blieb an seiner Seite, da sie wohl bei Almageit das gro\u00dfe Geld roch. Freunde und Gildenmitglieder der Holzf\u00e4ller waren der Meinung, das Tuptin Almageit schlecht beeinflusste seitdem sie bei ihm wohnte.<\/p>\n<p>&nbsp;<\/p>\n<p>Das Kasino best\u00e4tigte das Almageit einen gro\u00dfen Gewinn bei einem Insektenkampf machte. Merkw\u00fcrdig war nur sein Auftreten und sein wortkarges Verhalten. Er war irgendwie nicht Herr seiner Sinne und er lie\u00df eine Gottesanbeterin gegen eine W\u00fcstenvespe k\u00e4mpfen, was ein sehr ungleicher Kampf war. Der Schidsrichter sah das der Holzf\u00e4ller wie kontrolliert wirkte und er bemerkteauch eine unangenehme Luftver\u00e4nderung im Raum als w\u00fcrde ein Zaubereffekt vollzogen. Almageit beglich danach seine Schulden beim Sakura Clan und konnte sogar das Dach seinen Hauses reparieren lassen. Man h\u00e4tte nie damit gerechnet das Almageit ein Sklavenh\u00e4ndler sei.<\/p>\n<p>&nbsp;<\/p>\n<p>Bei der Durchsuchung der Holzf\u00e4llerh\u00fctte fanden Amara und Jorax eine Brosche mit einem Symbol von zwei gewundenen Schlangen und darauf eine Inschrift in der Sprache Abyss. Da der Kyo Clan das Symbol der Schlange hatte, war Almageit warscheinlich mit dem Kyo Clan im Bunde gewesen. Als Amara am n\u00e4chsten Tag die H\u00fctte nochmal besuchte, bemerkte sie das Jemand die Sachen des Holzf\u00e4llers durchsucht hatte, anscheinend suchte wer nach dieser Brosche.<\/p>\n<p>&nbsp;<\/p>\n<p>Als Thimbr\u00e9 eines Nachts das Bordell des Wirts Erc beobachtete, bemerkte er einen Kampf in einem der vielen R\u00e4ume des Geb\u00e4udes. Als sich Thimbr\u00e8 hinein schlich sah er Erc tot am Tisch sitzen, doch keine Spur von seinem M\u00f6rder. Thimbr\u00e8 fand im Zimmer unter anderem eine interessante Karte auf der einige Holzf\u00e4llerh\u00fctten eingezeichnet waren, zudem etwas Geschriebenes in der Sprache Abyss.<\/p>\n<p>&nbsp;<\/p>\n<p>Am n\u00e4chsten Tag befragte die Abenteuergruppe die neue Besitzerin Narie nach dem Tot von Erc.Doch man erfuhr nur das Erc ein sehr fr\u00f6hlicher und gespr\u00e4chiger Mensch war. Jorax lud Timbi\u00e8 ein bei den Prostituierten Informationen zu suchen, nat\u00fcrlich lie\u00dfen die beiden sich nur kurz und kr\u00e4ftig durchmassieren um die ganzen Verspannungen des Abenteuers los zu werden. Sie erfuhren das der Wirt Erc \u00a0Probleme mit seiner Frau hatte und suchte deshalb oft die N\u00e4he zu der Prostituierten Tuptin die im Bordell wohnte. Nachdem Tuptin erfuhr das Erc tod sei, ist sie sofort ausgezogen und wollte anscheinend zur Goldmine bzw zum Dorf Imashou.<\/p>\n<p>&nbsp;<\/p>\n<p>Drizinil entzifferte die Abyss Inschriften auf der Karte, woauf stand, das sich in der Mine ein Zugang zum Schloss bef\u00e4nde. Die Brosche k\u00f6nnte eine Art Schl\u00fcssel sein um den Zugang zu \u00f6ffnen. Doch Sie fanden kein Portal welches sich mit der Brosche \u00f6ffnen lie\u00df.Die Gruppe war nun sicher das Tuptin den Holzf\u00e4ller und den Wirt magisch beeiflusste. Der Holzf\u00e4ller Almageit verlor auf Dauer sein Verstand, aber der Wirt Erc war anscheinen weniger f\u00fcr magische Kontrollzauber empf\u00e4nglich. Und daher brachte sie den Wirt um und floh zur Mine. Anscheinend war Tuptin eine D\u00e4monenkreatur in Menschenform die Gedanken manipulieren konnte, diese Kreatur wird auch weibliche succubus genannt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) &nbsp; Die Gruppe hatte sich nach einiger Zeit in der Stadt Yenching \u00a0im Reiche Karatur eingelebt und Kultur und Sprache soweit wie m\u00f6glich in kurzer Zeit kennengelernt. Sie holten allerlei Informationen zusammen und konnten so ihre n\u00e4chsten Schritte planen wir sie [&hellip;]<\/p>\n","protected":false},"author":43,"featured_media":12037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[128],"tags":[],"class_list":["post-12024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gruppe2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) &nbsp; Die Gruppe hatte sich nach einiger Zeit in der Stadt Yenching \u00a0im Reiche Karatur eingelebt und Kultur und Sprache soweit wie m\u00f6glich in kurzer Zeit kennengelernt. Sie holten allerlei Informationen zusammen und konnten so ihre n\u00e4chsten Schritte planen wir sie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-30T20:54:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-03T21:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Knartsch\/Thimbr\u00e9 Gildas (Marcel)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Knartsch\/Thimbr\u00e9 Gildas (Marcel)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/\"},\"author\":{\"name\":\"Knartsch\\\/Thimbr\u00e9 Gildas (Marcel)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/ef7a01227f615dd20dcf57f9621d16a8\"},\"headline\":\"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)\",\"datePublished\":\"2016-04-30T20:54:06+00:00\",\"dateModified\":\"2018-02-03T21:43:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/\"},\"wordCount\":929,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/assasine.jpg?fit=800%2C450&ssl=1\",\"articleSection\":[\"Cult of the Damned (inaktiv)\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/\",\"name\":\"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/assasine.jpg?fit=800%2C450&ssl=1\",\"datePublished\":\"2016-04-30T20:54:06+00:00\",\"dateModified\":\"2018-02-03T21:43:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/assasine.jpg?fit=800%2C450&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/assasine.jpg?fit=800%2C450&ssl=1\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/gruppe2\\\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/ef7a01227f615dd20dcf57f9621d16a8\",\"name\":\"Knartsch\\\/Thimbr\u00e9 Gildas (Marcel)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/782f04fec0cbf0368437ea81f8a979f98d215dd7564dc164eee828ca3943029f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/782f04fec0cbf0368437ea81f8a979f98d215dd7564dc164eee828ca3943029f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/782f04fec0cbf0368437ea81f8a979f98d215dd7564dc164eee828ca3943029f?s=96&d=mm&r=g\",\"caption\":\"Knartsch\\\/Thimbr\u00e9 Gildas (Marcel)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/marcel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/","og_locale":"de_DE","og_type":"article","og_title":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) - RPG-Berlin.de","og_description":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) &nbsp; Die Gruppe hatte sich nach einiger Zeit in der Stadt Yenching \u00a0im Reiche Karatur eingelebt und Kultur und Sprache soweit wie m\u00f6glich in kurzer Zeit kennengelernt. Sie holten allerlei Informationen zusammen und konnten so ihre n\u00e4chsten Schritte planen wir sie [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2016-04-30T20:54:06+00:00","article_modified_time":"2018-02-03T21:43:27+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1","type":"image\/jpeg"}],"author":"Knartsch\/Thimbr\u00e9 Gildas (Marcel)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Knartsch\/Thimbr\u00e9 Gildas (Marcel)","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/"},"author":{"name":"Knartsch\/Thimbr\u00e9 Gildas (Marcel)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/ef7a01227f615dd20dcf57f9621d16a8"},"headline":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)","datePublished":"2016-04-30T20:54:06+00:00","dateModified":"2018-02-03T21:43:27+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/"},"wordCount":929,"commentCount":1,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1","articleSection":["Cult of the Damned (inaktiv)"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/","name":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1","datePublished":"2016-04-30T20:54:06+00:00","dateModified":"2018-02-03T21:43:27+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/gruppe2\/die-suche-nach-tuptin-eine-succubus-und-ihr-verfuehrerisches-treiben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Die Suche nach Tuptin.. Eine Succubus und ihr verf\u00fchrerisches Treiben (Cult of the Damned)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/ef7a01227f615dd20dcf57f9621d16a8","name":"Knartsch\/Thimbr\u00e9 Gildas (Marcel)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/782f04fec0cbf0368437ea81f8a979f98d215dd7564dc164eee828ca3943029f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/782f04fec0cbf0368437ea81f8a979f98d215dd7564dc164eee828ca3943029f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/782f04fec0cbf0368437ea81f8a979f98d215dd7564dc164eee828ca3943029f?s=96&d=mm&r=g","caption":"Knartsch\/Thimbr\u00e9 Gildas (Marcel)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/marcel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2016\/04\/assasine.jpg?fit=800%2C450&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-37W","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/12024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=12024"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/12024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/12037"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=12024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=12024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=12024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}