{"id":1157,"date":"2012-09-17T08:39:57","date_gmt":"2012-09-17T06:39:57","guid":{"rendered":"http:\/\/www.mirkozimmermann.bplaced.net\/RPG\/?p=1157"},"modified":"2018-02-07T12:23:47","modified_gmt":"2018-02-07T11:23:47","slug":"verfolgt","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/","title":{"rendered":"Verfolgt (The Grey Guardians&#038;Cult of the Damned)"},"content":{"rendered":"<p>Verfolgt (The Grey Guardians&amp;Cult of the Damned)<\/p>\n<p><span style=\"text-decoration: underline;\">Vorwort:<\/span><\/p>\n<p>Vinley, Camilla, Dalwick, der Schwarzstab und 2 weitere Gnome hielten sich versteckt in der N\u00e4he der Werft, der Tays auf, als ein Tumult innerhalb des Geb\u00e4udes ausbrach (Zak\u00b4s Verschwinden aus dem Kerker war bemerkt worden) Ein Einschreiten war unumg\u00e4nglich,\u00a0 in der Werft war anscheinend ein Feuer ausgebrochen, magische Blitze zuckten, knisterten in der ozon geschw\u00e4ngerten Luft und Schreie von Sterbenden drang zu ihnen nach aussen.<\/p>\n<p>Dalwick handelte als Erster und aus dem Nichts tauchte ein Nashorn auf, was blindlings vor Wut auf die R\u00fcckseite des Geb\u00e4udes zurannte und es durchbrach. Die Holzplanken der Werft splitterten auseinander und rissen ein gro\u00dfes Loch in die R\u00fcckwand. Durch das Loch erblickten viele kurze daraufhin wie Zaknafein\u00b4s letztes St\u00fcndchen geschlagen schien. Er lag am Boden und schien Bewusstlos, w\u00e4hrend 2 M\u00e4nner mit gez\u00fcckten Kurzschwertern auf ihn eindrangen. Doch pl\u00f6tzlich schoss aus einer dunklen Ecke der Werft ein riesiger schwarzer L\u00f6we auf die beide M\u00e4nner zu und streckte sie nieder. Sein Maul umschloss den Leib des einen w\u00e4hrend er mit seinen Pranken und seinem Gewicht den anderen auf den Boden dr\u00fcckte. Vinlay geistesgegenw\u00e4rtig legte seine Armbrust an und schoss, nachdem Camilla ein paar Worte gemurmelt hatte, den Bolzen auf das Tau, welches das Schiff im Trockendock hielt. Der Schuss sa\u00df und das gerissene Seil, durchtrennte einem in der n\u00e4he stehenden Halbelf, den Kopf von seinem K\u00f6rper, der Bolzen blieb in einem weiteren K\u00f6rper, von einem Zwergen\u00a0 stecken, der kurz darauf nachgab und nach vorne \u00fcberkippte.<\/p>\n<p>&#8211; Vinley rennt zu Zak und weicht dabei einen einschlagenden Kometen aus, w\u00e4hrend Dalwick schwer verwundet hinter ihm zusammenbricht<\/p>\n<p>&#8211; die beiden Gnome schiessen irgendwelche brennbaren Fl\u00fcssigkeiten mithilfe eines kleinen Katapultes auf das Dach der Werft<\/p>\n<p>&#8211; der aus der Werft dringende Rauch wird schlimmer<\/p>\n<p>&#8211; Camilla will\u00a0 Dalwick helfen und wird selbst Opfer von dem Assasine<\/p>\n<p>&#8211; ein Gnom der an einem Katapult steht wird Opfer des Assasine<\/p>\n<p>&#8211; Vinlay ereicht Zak und kann sich gerade noch rechtzeitig in Deckung hinter ein paar Kisten begeben, als ein Bolzenhagel in die Kisten einschlagen, abgeschossen von einer Tay mit 2 Handarmbr\u00fcsten<\/p>\n<p>&#8211; Bolzen durchschlagen die Kisten treffen aber Vinlay nicht<\/p>\n<p>&#8211; Vinlay zieht unter Beschuss, Zak zu dem Schwarzstab, der ein Schutzschirm inzwischen aufgebaut hat<\/p>\n<p>&#8211; Vinlay wird getroffen und geht zu Boden<\/p>\n<p>&#8211; Schwarzstab teleportiert die Gruppe in den Tempel des Lathander in Tiefwasser<\/p>\n<p>&#8211; nur Zak landet in der Taverne auf seinem Bett<\/p>\n<p><span style=\"text-decoration: underline;\">Vorwort Ende<\/span><\/p>\n<p>&#8211; Kendrick und Lajana bekommen die M\u00f6glichkeit in Scharzstabsturm zu n\u00e4chtigen, nachdem er sie \u00fcber ihr weiteres Vorgehen aufgekl\u00e4rt hat und ihnen ein gutes Versteck bei den &#8222;Schnitzern&#8220; bei &#8222;Valponia&#8220; angeboten hat<\/p>\n<p>&#8211; Zak und Pery stapfen durch den Schnee, eines dichten Waldes<\/p>\n<p>&#8211; suchen sich eine von Felsen gesch\u00fctze Stelle und bauen ein Zelt auf<\/p>\n<p>&#8211; eine Kr\u00e4he \u00e4rgert Zak indem sie sich auf das Zelt setzt und vor ihm hin und her stolziert, selbst Schneeb\u00e4lle verteiben den Vogel nicht Pery geht als 1. schlafen, ein Wolfsrudel n\u00e4hert sich dem Lager, die Kr\u00e4he\u00a0 wirft von oben Steine auf Zak<\/p>\n<p>&#8211; ein Komet taucht wie aus dem Nichts am Horizont auf der auf den Felsen geschossen kommt<\/p>\n<p>&#8211; Zak stupst Pery wach und sie fangen an zu laufen, gefolgt von den W\u00f6fen die ab und zu mal nach den beiden schnappen<\/p>\n<p>&#8211; die Explosion des Kommeten hallt durch die Umgebung<\/p>\n<p>&#8211; ein Wolf bekommt Pery zu fassen, die auf der Schuler von Zak sitzt<\/p>\n<p>&#8211; selbst mit mehreren Schl\u00e4gen bekommt Zak, Pery nicht frei aus dem Maul des Wolfes<\/p>\n<p>&#8211; letztendlich das von ihm erzeugte Feenfeuer verteibt die Tiere, die sich auf kurzer Distanz halten<\/p>\n<p>&#8211; die beiden laufen wieder los und Pery stellt fest das die Kr\u00e4he wieder da ist<\/p>\n<p>&#8211; die Kr\u00e4he wirft einen Stein auf den laufenden Zak und trifft ihn<\/p>\n<p>&#8211; Pery stellt fest das die Kr\u00e4he im Sturzpfluf auf\u00a0 sie zugeschossen kommt<\/p>\n<p>&#8211; die Kr\u00e4he trifft Zak und l\u00f6st einen riesigen Stromstoss aus, der Pery von den Schultern in einen hohen Bogen in den Schnee schickt<\/p>\n<p>&#8211; beide bleiben zum Gl\u00fcck beim Bewusstsein, wenn auch sehr angekohlt<\/p>\n<p>&#8211; W\u00f6lfe verschwinden<\/p>\n<p>&#8211; Zak und Pery erreichen ein kleines Geh\u00f6ft\u00a0 mit Scheune<\/p>\n<p>&#8211; in dem einen Fenster brennt noch Licht<\/p>\n<p>&#8211; nach kurzem Verhandeln bekommen Zak und Pery ein Schlafplatz in der Scheuen, die gesichert ist mit einem riesigem Bluthund<\/p>\n<p>&#8211; Pery schl\u00e4ft ein w\u00e4hrend Zak Wache h\u00e4lt<\/p>\n<p>&#8211; Kendrick und Lajana werden in den fr\u00fchen Morgenstunden vom Geruch eines Tee\u00b4s und einer kleinen Explosion wach<\/p>\n<p>&#8211; nachdem sie aufgestanden sind und die T\u00fcr \u00f6ffnen, pflitzt ein Gnom von links nach rechts<\/p>\n<p>&#8211; kurz darauf ersch\u00fcttert eine 2te Explosion den Turm und ein Gnom \u00fcberholt sie und landet vor den F\u00fc\u00dfen des Schwarzstabs der auf der Treppe steht und nur meint das dies kein &#8222;Schwarzer Tee&#8220; sei<\/p>\n<p>&#8211; Kendrick und Lajana werden zum reichhaltigen Fr\u00fchst\u00fcck gebeten, an der Tafel<\/p>\n<p>&#8211; Schwarzstab berichtet wo der Rest der Gruppe ist und erkl\u00e4rt Zak und Pery als vermisst<\/p>\n<p>&#8211; er gibt eine Glocke an Lajana weiter mit der Erkl\u00e4rung wie sie funktioniert, kurz daraufhin erscheinen Zak und die schlafende Pery in dem Zimmer<\/p>\n<p>&#8211; der Gnom taucht auf und stolpert \u00fcber die Treppe beim Eingang zum Saal in dem sie verweilen, dabei verliert er den auf den R\u00fccken tragenden Sack und es purzeln Dinge raus<\/p>\n<p>&#8211; Belohnung: 3 B\u00fccher ( Buch der Beweglichkeit, Buch der F\u00e4higkeit, Buch der Treffsicherheit) Glocke der W\u00fcnsche (jetzt nur noch 1. Aufladung), Dolch der Ebenen (Astrale, Schatten und normale Ebene) Glaskugel der Sicht, rot gl\u00fchender Zauberstab, danach noch: Ring des Geistes, immervolle Tabakpfeife<\/p>\n<p>&#8211; wie zu Weihnachten testen sie all ihre Geschenke, dabei verschwindet Zak pl\u00f6tzlich nachdem er sich den Ring aufgesetzt hat<\/p>\n<p>&#8211; Vinlay und Camilla werden im Tempel des Lathanders wach<\/p>\n<p>&#8211; im gleichen Raum liegen weitere 8 Leute, wobei einer die Nacht nicht \u00fcberlebt hat<\/p>\n<p>&#8211; Camilla setzt sich auf und erf\u00e4hrt von einer Elfe wo sie sich befinden und wie ihr Zustand ist<\/p>\n<p>&#8211; Camilla eilt zum Gebetsraum, w\u00e4hrend der in Kr\u00e4utergeh\u00fcllte Vinlay eine kleine Weise spielt<\/p>\n<p>&#8211; Kendrick, Lajana, Pery und Zak treffen im Tempel ein und nehmen Vinlay mit zu den Schnitzern<\/p>\n<p>&#8212;-Zeitvorsprung&#8212;-<\/p>\n<p>Es vergehen mehrer Jahre und jeder Charakter erlebt in der Zwischenzeit einiges, weitere Details sind auf den Seiten der Charaktere zu finden:<\/p>\n<p><a title=\"Camilla\" href=\"https:\/\/rpg-berlin.de\/rpg\/?p=909\">Camilla<\/a><\/p>\n<p><a title=\"Dalwick\" href=\"https:\/\/rpg-berlin.de\/rpg\/?p=843\" target=\"_blank\" rel=\"noopener\">Dalwick<\/a><\/p>\n<p>Kendrick<\/p>\n<p><a title=\"Vinlay\" href=\"https:\/\/rpg-berlin.de\/rpg\/?p=875\" target=\"_blank\" rel=\"noopener\">Vinlay<\/a><\/p>\n<p><a title=\"Zaknafain\u00b4s 7 Jahre\" href=\"https:\/\/rpg-berlin.de\/rpg\/?p=1233\" target=\"_blank\" rel=\"noopener\">Zaknafain<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verfolgt (The Grey Guardians&amp;Cult of the Damned) Vorwort: Vinley, Camilla, Dalwick, der Schwarzstab und 2 weitere Gnome hielten sich versteckt in der N\u00e4he der Werft, der Tays auf, als ein Tumult innerhalb des Geb\u00e4udes ausbrach (Zak\u00b4s Verschwinden aus dem Kerker war bemerkt worden) Ein Einschreiten war unumg\u00e4nglich,\u00a0 in der Werft war anscheinend ein Feuer ausgebrochen, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13,131],"tags":[35],"class_list":["post-1157","post","type-post","status-publish","format-standard","hentry","category-abenteuer","category-gruppe1gruppe2","tag-08-12-1372"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verfolgt (The Grey Guardians&amp;Cult of the Damned) - RPG-Berlin.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verfolgt (The Grey Guardians&amp;Cult of the Damned) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Verfolgt (The Grey Guardians&amp;Cult of the Damned) Vorwort: Vinley, Camilla, Dalwick, der Schwarzstab und 2 weitere Gnome hielten sich versteckt in der N\u00e4he der Werft, der Tays auf, als ein Tumult innerhalb des Geb\u00e4udes ausbrach (Zak\u00b4s Verschwinden aus dem Kerker war bemerkt worden) Ein Einschreiten war unumg\u00e4nglich,\u00a0 in der Werft war anscheinend ein Feuer ausgebrochen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-17T06:39:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-07T11:23:47+00:00\" \/>\n<meta name=\"author\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/\"},\"author\":{\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\"},\"headline\":\"Verfolgt (The Grey Guardians&#038;Cult of the Damned)\",\"datePublished\":\"2012-09-17T06:39:57+00:00\",\"dateModified\":\"2018-02-07T11:23:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/\"},\"wordCount\":1113,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"keywords\":[\"08-12-1372\"],\"articleSection\":[\"Abenteuer\",\"The Grey Guardians&amp;Cult of the Damned (inaktiv)\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/\",\"name\":\"Verfolgt (The Grey Guardians&Cult of the Damned) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"datePublished\":\"2012-09-17T06:39:57+00:00\",\"dateModified\":\"2018-02-07T11:23:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/verfolgt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verfolgt (The Grey Guardians&#038;Cult of the Damned)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\",\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"caption\":\"Thinkleblink\\\/Dalwick (Mirko)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verfolgt (The Grey Guardians&Cult of the Damned) - RPG-Berlin.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/","og_locale":"de_DE","og_type":"article","og_title":"Verfolgt (The Grey Guardians&Cult of the Damned) - RPG-Berlin.de","og_description":"Verfolgt (The Grey Guardians&amp;Cult of the Damned) Vorwort: Vinley, Camilla, Dalwick, der Schwarzstab und 2 weitere Gnome hielten sich versteckt in der N\u00e4he der Werft, der Tays auf, als ein Tumult innerhalb des Geb\u00e4udes ausbrach (Zak\u00b4s Verschwinden aus dem Kerker war bemerkt worden) Ein Einschreiten war unumg\u00e4nglich,\u00a0 in der Werft war anscheinend ein Feuer ausgebrochen, [&hellip;]","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2012-09-17T06:39:57+00:00","article_modified_time":"2018-02-07T11:23:47+00:00","author":"Thinkleblink\/Dalwick (Mirko)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thinkleblink\/Dalwick (Mirko)","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/"},"author":{"name":"Thinkleblink\/Dalwick (Mirko)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec"},"headline":"Verfolgt (The Grey Guardians&#038;Cult of the Damned)","datePublished":"2012-09-17T06:39:57+00:00","dateModified":"2018-02-07T11:23:47+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/"},"wordCount":1113,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"keywords":["08-12-1372"],"articleSection":["Abenteuer","The Grey Guardians&amp;Cult of the Damned (inaktiv)"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/","name":"Verfolgt (The Grey Guardians&Cult of the Damned) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"datePublished":"2012-09-17T06:39:57+00:00","dateModified":"2018-02-07T11:23:47+00:00","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/verfolgt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Verfolgt (The Grey Guardians&#038;Cult of the Damned)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec","name":"Thinkleblink\/Dalwick (Mirko)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","caption":"Thinkleblink\/Dalwick (Mirko)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s4p3r6-verfolgt","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/1157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=1157"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/1157\/revisions"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=1157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=1157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=1157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}