{"id":105746,"date":"2023-04-29T21:00:00","date_gmt":"2023-04-29T19:00:00","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=105746"},"modified":"2023-07-19T22:55:20","modified_gmt":"2023-07-19T20:55:20","slug":"der-kriegsrat-the-resurrected","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/","title":{"rendered":"Der Kriegsrat? (The Resurrected)"},"content":{"rendered":"\n[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.21.0&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<p><!-- divi:paragraph -->&#8222;Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen Kampf gew\u00e4hlt und au\u00dferdem soll die kleine was lernen. Trotzdem war ich mir sicher, dass heute allerdings nichts mehr passiert&#8230;&#8220;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph -->Wir waren gerade beim Schmied, als Ismair auf uns zukam. Sie sagte uns, dass eine wichtige Versammlung ansteht und wir dann die Gelegenheit h\u00e4tten unsere Anliegen anzubringen. Wieder im Tempel angekommen, sahen wir dass die gro\u00dfe Halle vor unseren Zimmern mit einer nicht zu kleinen Gruppe von Leuten gef\u00fcllt war, zu denen sich Ismair dazustellte, w\u00e4hrend wir am anderen Ende warteten. Verstehen konnten wir sie trotzdem, was mich wunderte, da ich ihre Sprache sonst nicht verstand. Egal. Das Gespr\u00e4ch wirkte f\u00fcr mich fast wie ein Kriegsrat oder zumindest eine taktische Besprechung.<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph -->Es war die Rede von anderen &#8222;Orten&#8220; und Personen zu denen der Kontakt abgebrochen war. Von Untoten, um die sich teilweise schon gek\u00fcmmert wird. Und was meine Ohren aufhorchen lies war das Thema eines Drachenskelets. Ob das Bahamuts Einfluss ist?<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph -->Nach einiger schien niemand von den teilweise noch Fremden etwas vorzubringen. Nicht einmal der Mann, der das ganze Gespr\u00e4ch \u00fcber an einer S\u00e4ule lehnte und im gesamten Gespr\u00e4ch nichts sagte und uns w\u00e4hrend unserer Reise an diesen Ort als Tebaun vorgestellt wurde. Er blieb auch weiterhin dort stehen, was Ismair und einer anderen Frau nicht zu gefallen schien. Trotzdem gab uns Ismair das Signal, dass wir herantreten sollten. Angekommen begr\u00fc\u00dfte uns die dritte Frau im Bunde. G&#8217;eldriia ist ihr Name und mir wurde bewusst, dass sie es war an die ich mich f\u00fcr so viele Dinge richten sollte.<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:image {\"align\":\"center\",\"id\":105747,\"sizeSlug\":\"full\",\"linkDestination\":\"media\"} --><\/p>\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?resize=360%2C360&#038;ssl=1\" alt=\"\" class=\"wp-image-105747\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?w=360&amp;ssl=1 360w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?resize=45%2C45&amp;ssl=1 45w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><\/a><\/figure>\n<p><!-- \/divi:image --><\/p>\n<p><!-- divi:paragraph -->Dies tat ich auch und erz\u00e4hlte von Bahamut und meiner Familie. Daraufhin bot sie mir ihre Unterst\u00fctzung an. Uns allen. Denn das erste, was sie tat, war uns einen Segen ihrer G\u00f6ttin zukommen zu lassen, daf\u00fcr dass wir bei der Befreiung der Sklaven geholfen haben. Danach bot sie mir an, dass sie beim n\u00e4chsten Vollmond ein Portal \u00f6ffnen k\u00f6nnen um uns alle nach Hause zu bringen. Und bis dahin haben wir kostenlose Unterkunft bei ihnen. Es klingt alles zu sch\u00f6n um war zu sein&#8230; aber da ist noch ein Gef\u00fchl. Ich kann nicht in mein vorheriges Leben zur\u00fcck. Noch nicht. Nicht w\u00e4hrend Mia gerade leiden muss.<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:paragraph -->Da es trotzdem sch\u00f6n w\u00e4re meine Familie wieder zu sehen, baten sie an eine Magie zu wirken damit ich meine Frau zu erst einmal wieder sehen kann. Aber daf\u00fcr m\u00fcssen wir in&#8217;s innere Heiligtum. Tebaun bat uns an uns durch den ungesehenen Teil des Tempels zu f\u00fchren, aber Vaneara schien sogar noch mehr Begeisterung zu haben und fing an uns durch den Tempel zu f\u00fchren. Weit kamen wir nicht, da wir auf einmal sahen, wie ein Mann dem jungen M\u00e4dchen aus der K\u00fcche einen Schlag versetzte. Es stellte sich zum Gl\u00fcck schnell als Training heraus und so musste ich nicht eingreifen. Da seine Methodik allerdings sehr anders ist, als ich es gew\u00f6hnt war, wollte ich mich einmischen, aber Ricarda kam mir zuvor. Inzwischen sind wir soweit, dass wir jetzt gegen diesen Herrn k\u00e4mpfen werden, damit das M\u00e4dchen daraus lernen kann und nicht selber die Verletzungen ertragen muss. Es wundert mich allerdings, dass Ricarda anscheinend nicht zur\u00fcckschreckt sehr gef\u00e4hrliche und t\u00f6dliche Magie zu verwenden&#8230;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p><!-- divi:image {\"align\":\"center\",\"id\":105748,\"width\":150,\"height\":398,\"sizeSlug\":\"full\",\"linkDestination\":\"media\"} --><\/p>\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Jyslin_Vandree01.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Jyslin_Vandree01.jpg?resize=150%2C398&#038;ssl=1\" alt=\"\" class=\"wp-image-105748\" width=\"150\" height=\"398\" srcset=\"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Jyslin_Vandree01.jpg?w=182&amp;ssl=1 182w, https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Jyslin_Vandree01.jpg?resize=113%2C300&amp;ssl=1 113w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a><\/figure>\n<p><!-- \/divi:image --><\/p>\n<p><!-- divi:paragraph -->Ich werde auf jeden Fall darauf achten ihn nicht zu schwer zu verletzen. Wenn ich das bei seiner Beweglichkeit \u00fcberhaupt schaffe&#8230;<\/p>\n<p><!-- \/divi:paragraph --><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen Kampf gew\u00e4hlt und au\u00dferdem soll die kleine was lernen. Trotzdem war ich mir sicher, dass heute allerdings nichts mehr passiert&#8230;&#8220; Wir waren gerade beim Schmied, als Ismair auf uns zukam. Sie sagte [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":105747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>\"Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen Kampf gew\u00e4hlt und au\u00dferdem soll die kleine was lernen. Trotzdem war ich mir sicher, dass heute allerdings nichts mehr passiert...\"<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Wir waren gerade beim Schmied, als Ismair auf uns zukam. Sie sagte uns, dass eine wichtige Versammlung ansteht und wir dann die Gelegenheit h\u00e4tten unsere Anliegen anzubringen. Wieder im Tempel angekommen, sahen wir dass die gro\u00dfe Halle vor unseren Zimmern mit einer nicht zu kleinen Gruppe von Leuten gef\u00fcllt war, zu denen sich Ismair dazustellte, w\u00e4hrend wir am anderen Ende warteten. Verstehen konnten wir sie trotzdem, was mich wunderte, da ich ihre Sprache sonst nicht verstand. Egal. Das Gespr\u00e4ch wirkte f\u00fcr mich fast wie ein Kriegsrat oder zumindest eine taktische Besprechung.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Es war die Rede von anderen \"Orten\" und Personen zu denen der Kontakt abgebrochen war. Von Untoten, um die sich teilweise schon gek\u00fcmmert wird. Und was meine Ohren aufhorchen lies war das Thema eines Drachenskelets. Ob das Bahamuts Einfluss ist?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Nach einiger schien niemand von den teilweise noch Fremden etwas vorzubringen. Nicht einmal der Mann, der das ganze Gespr\u00e4ch \u00fcber an einer S\u00e4ule lehnte und im gesamten Gespr\u00e4ch nichts sagte und uns w\u00e4hrend unserer Reise an diesen Ort als Tebaun vorgestellt wurde. Er blieb auch weiterhin dort stehen, was Ismair und einer anderen Frau nicht zu gefallen schien. Trotzdem gab uns Ismair das Signal, dass wir herantreten sollten. Angekommen begr\u00fc\u00dfte uns die dritte Frau im Bunde. G'eldriia ist ihr Name und mir wurde bewusst, dass sie es war an die ich mich f\u00fcr so viele Dinge richten sollte.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":105747,\"sizeSlug\":\"full\",\"linkDestination\":\"media\"} -->\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg\"><img src=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg\" alt=\"\" class=\"wp-image-105747\"\/><\/a><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Dies tat ich auch und erz\u00e4hlte von Bahamut und meiner Familie. Daraufhin bot sie mir ihre Unterst\u00fctzung an. Uns allen. Denn das erste, was sie tat, war uns einen Segen ihrer G\u00f6ttin zukommen zu lassen, daf\u00fcr dass wir bei der Befreiung der Sklaven geholfen haben. Danach bot sie mir an, dass sie beim n\u00e4chsten Vollmond ein Portal \u00f6ffnen k\u00f6nnen um uns alle nach Hause zu bringen. Und bis dahin haben wir kostenlose Unterkunft bei ihnen. Es klingt alles zu sch\u00f6n um war zu sein... aber da ist noch ein Gef\u00fchl. Ich kann nicht in mein vorheriges Leben zur\u00fcck. Noch nicht. Nicht w\u00e4hrend Mia gerade leiden muss.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Da es trotzdem sch\u00f6n w\u00e4re meine Familie wieder zu sehen, baten sie an eine Magie zu wirken damit ich meine Frau zu erst einmal wieder sehen kann. Aber daf\u00fcr m\u00fcssen wir in's innere Heiligtum. Tebaun bat uns an uns durch den ungesehenen Teil des Tempels zu f\u00fchren, aber Vaneara schien sogar noch mehr Begeisterung zu haben und fing an uns durch den Tempel zu f\u00fchren. Weit kamen wir nicht, da wir auf einmal sahen, wie ein Mann dem jungen M\u00e4dchen aus der K\u00fcche einen Schlag versetzte. Es stellte sich zum Gl\u00fcck schnell als Training heraus und so musste ich nicht eingreifen. Da seine Methodik allerdings sehr anders ist, als ich es gew\u00f6hnt war, wollte ich mich einmischen, aber Ricarda kam mir zuvor. Inzwischen sind wir soweit, dass wir jetzt gegen diesen Herrn k\u00e4mpfen werden, damit das M\u00e4dchen daraus lernen kann und nicht selber die Verletzungen ertragen muss. Es wundert mich allerdings, dass Ricarda anscheinend nicht zur\u00fcckschreckt sehr gef\u00e4hrliche und t\u00f6dliche Magie zu verwenden...<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"align\":\"center\",\"id\":105748,\"width\":150,\"height\":398,\"sizeSlug\":\"full\",\"linkDestination\":\"media\"} -->\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Jyslin_Vandree01.jpg\"><img src=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Jyslin_Vandree01.jpg\" alt=\"\" class=\"wp-image-105748\" width=\"150\" height=\"398\"\/><\/a><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:paragraph -->\n<p>Ich werde auf jeden Fall darauf achten ihn nicht zu schwer zu verletzen. Wenn ich das bei seiner Beweglichkeit \u00fcberhaupt schaffe...<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[834],"tags":[],"class_list":["post-105746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-the-resurrected"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Kriegsrat? (The Resurrected) - RPG-Berlin.de<\/title>\n<meta name=\"description\" content=\"&quot;Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Kriegsrat? (The Resurrected) - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"&quot;Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T19:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-19T20:55:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bran (Michael)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bran (Michael)\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/\"},\"author\":{\"name\":\"Bran (Michael)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/b527e2485a49fc031996c87eedd61faa\"},\"headline\":\"Der Kriegsrat? (The Resurrected)\",\"datePublished\":\"2023-04-29T19:00:00+00:00\",\"dateModified\":\"2023-07-19T20:55:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/\"},\"wordCount\":695,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Geldriia.jpg?fit=360%2C360&ssl=1\",\"articleSection\":[\"The Resurrected\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/\",\"name\":\"Der Kriegsrat? (The Resurrected) - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Geldriia.jpg?fit=360%2C360&ssl=1\",\"datePublished\":\"2023-04-29T19:00:00+00:00\",\"dateModified\":\"2023-07-19T20:55:20+00:00\",\"description\":\"\\\"Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Geldriia.jpg?fit=360%2C360&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Geldriia.jpg?fit=360%2C360&ssl=1\",\"width\":360,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/abenteuer\\\/the-resurrected\\\/der-kriegsrat-the-resurrected\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Kriegsrat? (The Resurrected)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/b527e2485a49fc031996c87eedd61faa\",\"name\":\"Bran (Michael)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15b3eab6bbc6fc95f3413400370ac2d7e4751789d8fe29b72f50a940bc0901d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15b3eab6bbc6fc95f3413400370ac2d7e4751789d8fe29b72f50a940bc0901d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15b3eab6bbc6fc95f3413400370ac2d7e4751789d8fe29b72f50a940bc0901d6?s=96&d=mm&r=g\",\"caption\":\"Bran (Michael)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/michael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Kriegsrat? (The Resurrected) - RPG-Berlin.de","description":"\"Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/","og_locale":"de_DE","og_type":"article","og_title":"Der Kriegsrat? (The Resurrected) - RPG-Berlin.de","og_description":"\"Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen..","og_url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2023-04-29T19:00:00+00:00","article_modified_time":"2023-07-19T20:55:20+00:00","og_image":[{"width":360,"height":360,"url":"https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg","type":"image\/jpeg"}],"author":"Bran (Michael)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Bran (Michael)","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/"},"author":{"name":"Bran (Michael)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/b527e2485a49fc031996c87eedd61faa"},"headline":"Der Kriegsrat? (The Resurrected)","datePublished":"2023-04-29T19:00:00+00:00","dateModified":"2023-07-19T20:55:20+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/"},"wordCount":695,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?fit=360%2C360&ssl=1","articleSection":["The Resurrected"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/","url":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/","name":"Der Kriegsrat? (The Resurrected) - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#primaryimage"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?fit=360%2C360&ssl=1","datePublished":"2023-04-29T19:00:00+00:00","dateModified":"2023-07-19T20:55:20+00:00","description":"\"Ich bin erstaunt, dass ich so ruhig bleiben kann w\u00e4hrend dieser Typ Ricarda schl\u00e4gt. Einmischen werde ich mich aber nicht. Sie hat diesen..","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#primaryimage","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?fit=360%2C360&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?fit=360%2C360&ssl=1","width":360,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/abenteuer\/the-resurrected\/der-kriegsrat-the-resurrected\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Der Kriegsrat? (The Resurrected)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/b527e2485a49fc031996c87eedd61faa","name":"Bran (Michael)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/15b3eab6bbc6fc95f3413400370ac2d7e4751789d8fe29b72f50a940bc0901d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15b3eab6bbc6fc95f3413400370ac2d7e4751789d8fe29b72f50a940bc0901d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15b3eab6bbc6fc95f3413400370ac2d7e4751789d8fe29b72f50a940bc0901d6?s=96&d=mm&r=g","caption":"Bran (Michael)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/michael\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2023\/05\/Geldriia.jpg?fit=360%2C360&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-rvA","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/105746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=105746"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/105746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media\/105747"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=105746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=105746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=105746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}