{"id":105169,"date":"2022-03-29T15:45:25","date_gmt":"2022-03-29T13:45:25","guid":{"rendered":"https:\/\/rpg-berlin.de\/rpg\/?p=105169"},"modified":"2022-03-30T12:12:20","modified_gmt":"2022-03-30T10:12:20","slug":"die-9-gesinnungen","status":"publish","type":"post","link":"https:\/\/rpg-berlin.de\/rpg\/tipps\/die-9-gesinnungen\/","title":{"rendered":"Die 9 Gesinnungen"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.15&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;2_5,3_5&#8243; _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/06\/Cherlia-Brightbringer.jpg&#8220; alt=&#8220;K\u00e4mpfer haben mehr M\u00f6glichkeiten, Talente einzubringen als jede andere Klasse in %22Dungeons and Dragons%22, und es gibt einige wirklich herausragende Optionen. F\u00fcr viele Spieler, die neu bei Dungeons &#038; Dragons sind, ist die K\u00e4mpferklasse ziemlich einfach zu erlernen und kann einen einfachen Spielstil bieten. Standard-K\u00e4mpfer-Builds k\u00f6nnen es dem Spieler erm\u00f6glichen, sich ausschlie\u00dflich auf Nahkampfwaffenangriffe zu konzentrieren, ohne sich um eine entmutigend gro\u00dfe Liste von Zauberspr\u00fcchen k\u00fcmmern zu m\u00fcssen. K\u00e4mpfer sind jedoch alles andere als fad. Wie jede Klasse in D&#038;D k\u00f6nnen K\u00e4mpfer so komplex sein wie der Spieler, der sie spielt. K\u00e4mpfer k\u00f6nnen Angreifer an vorderster Front, Unterst\u00fctzungspanzer oder sogar Zauberer sein. Dein Spielstil wird weitgehend von deiner Unterklasse bestimmt, aber auch von den Kunstst\u00fccken, die du machst. K\u00e4mpfer erhalten mehr Ability Score Improvements (ASI) oder Feats als jede andere Klasse, was sie zu einer der m\u00e4chtigsten und vielseitigsten Klassen im Spiel macht.&#8220; title_text=&#8220;Cherlia Brightbringer&#8220; _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h5>Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und Vorlieben. Seit 1974 verwendet Dungeons and Dragons ein Moralsystem, das als Alignment bekannt ist, um das Verhalten von Spieler- und Nichtspielercharakteren gleicherma\u00dfen abzubilden. In der urspr\u00fcnglichen Version existierte die Ausrichtung entlang einer einzigen Achse, von rechtm\u00e4\u00dfig bis chaotisch, mit Neutral in der Mitte. Advanced Dungeons and Dragons, das 1979 ver\u00f6ffentlicht wurde, f\u00fchrte eine zweite Achse ein, von gut \u00fcber neutral bis b\u00f6se. Dieses Neunersystem ist weitgehend unver\u00e4ndert geblieben, mit einer kurzen \u00c4nderung in der 4. D&amp;D-Ausgabe von 2008, obwohl die tats\u00e4chlichen Beschreibungen jedes einzelnen stark variiert haben. Diese Ausrichtungen haben sich vom D&amp;D-Fandom in eine breitere Popkultur verlagert, die oft als Abk\u00fcrzung verwendet wird, um das Verhalten und die Lebenseinstellung einer fiktiven Figur oder einer realen Person zu beschreiben.<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.15&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.15.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h3>&#8222;Lawful Good&#8220; verwendet Gesetze oder Kodizes, um Menschen zu sch\u00fctzen<\/h3>\n<p>In einem Livestream auf seinem YouTube-Kanal sagte der ehemalige D&amp; D-Designer Tim Kask, dass die rechtm\u00e4\u00dfige Ausrichtung urspr\u00fcnglich konzipiert wurde, um Kreaturen zu beschreiben, deren Verhalten vorhergesagt werden konnte. &#8222;Du warst ein Gewohnheitstier, nicht, dass du ein Abzeichen getragen hast&#8220;, so Kask. Dies wich buchst\u00e4blichen Gesetzen bei der Einf\u00fchrung der Gut\/B\u00f6se-Achse in AD &amp; D, die rechtm\u00e4\u00dfige gute Charaktere als starke Anh\u00e4nger von Recht und Ordnung beschreibt, die bereit sind, bestimmte pers\u00f6nliche Freiheiten zu opfern, um das vermeintliche Gemeinwohl zu verfolgen. Das rechtm\u00e4\u00dfige Gut war eine der f\u00fcnf Alignments in 4e, wo seine Definition leicht erweitert wurde, um Menschen einzubeziehen, die alle Verhaltenskodizes respektieren, sei es auf pers\u00f6nlicher oder einer breiteren gesellschaftlichen Ebene. Das rechtm\u00e4\u00dfige Gut von 5e ist so etwas wie eine R\u00fcckkehr zur Form. &#8222;Auf rechtm\u00e4\u00dfige gute Gesch\u00f6pfe kann man sich verlassen, dass sie das Richtige tun, wie es von der Gesellschaft erwartet wird.&#8220;<\/p>\n<h3>&#8222;Neutral Good&#8220; ist die catch-all gute Ausrichtung<\/h3>\n<p>Vielleicht die generischste Ausrichtung f\u00fcr heroische Charaktere, neutral good hat sich im Laufe der Jahre in seiner Pr\u00e4sentation um einiges ver\u00e4ndert. AD&amp; D beschreibt neutrale gute Kreaturen in ziemlich politischen Begriffen und erkl\u00e4rt, dass sie &#8222;glauben, dass es eine gewisse Regulierung in Kombination mit Freiheiten geben muss, wenn das Beste in die Welt gebracht werden soll&#8220;. Neutrales Gut gleicht sich in 3.5, 4e (wo es einfach &#8222;gut&#8220; genannt wurde) und 5e aus und umfasst im Allgemeinen Kreaturen, die tun, was sie k\u00f6nnen, um anderen zu helfen und im Allgemeinen das Wohlbefinden zu f\u00f6rdern.\u00a0<\/p>\n<h3>&#8222;Chaotic Good&#8220; priorisiert Freiheit<\/h3>\n<p>Chaos war eine der beiden metaphysischen Fraktionen in der urspr\u00fcnglichen Version von Dungeons and Dragons und wurde im Allgemeinen als Analogon f\u00fcr das B\u00f6se verwendet. AD &amp; D erschwerte dies, indem es chaotisches Gutes hinzuf\u00fcgte, eine Ausrichtung, die die pers\u00f6nliche Freiheit und den Wert jedes Lebens aufrechterh\u00e4lt. 3.5 beschreibt den chaotischen guten Charakter als den &#8222;Rebellen&#8220;, der vor allem seinem Gewissen folgt, unabh\u00e4ngig von den Strukturen um ihn herum. Chaotisches Gutes fehlte in 4e und wurde stattdessen meist mit der guten Ausrichtung abgeschlossen. 5es Beschreibung des chaotischen Guten spiegelt weitgehend auch die 3.5-Iteration wieder.<\/p>\n<h3>&#8222;Lawful Neutral&#8220; befasst sich mit Ordnungen aller Art<\/h3>\n<p>Die urspr\u00fcngliche Beschreibung von legal neutral in AD &amp; D beschreibt Kreaturen, die &#8222;Regulierung als alles Wichtige betrachten&#8220;. Das ultimative Ziel dieser Version der rechtm\u00e4\u00dfigen Neutralit\u00e4t ist etwas erhaben, da sie Gut und B\u00f6se als irrelevant im Streben nach einer Welt betrachten, die rein und perfekt geordnet ist. Die rechtm\u00e4\u00dfige Neutralit\u00e4t von 3.5 ist etwas menschlicher und beschreibt Charaktere, die &#8222;Gesetz, Tradition oder einem pers\u00f6nlichen Kodex&#8220; folgen. Dies markiert eine Abkehr von der eher kosmischen Geschichte der Ausrichtung und eine Bewegung hin zu einem System, das besser auf reale, individualisierte Charaktere anwendbar ist. Rechtm\u00e4\u00dfig neutral fehlte in 4e, und 5es rechtm\u00e4\u00dfiger Neutraler ist im Grunde das gleiche wie 3,5.\u00a0<\/p>\n<h3>&#8222;Neutral&#8220; hat sich am meisten ver\u00e4ndert<\/h3>\n<p>Die neutrale Ausrichtung hat zweifellos die meisten \u00c4nderungen von Edition zu Edition durchlaufen. In AD &amp; D wurde es als &#8222;wahr neutral&#8220; bezeichnet. Wahrhaft neutrale Charaktere besch\u00e4ftigen sich letztendlich mit dem Gleichgewicht, sehen Gut und B\u00f6se, Gesetz und Chaos als alle Arme einer kosmischen Skala. Wahr neutral beg\u00fcnstigte die Kraft der Natur, und AD &amp; D Druiden waren immer wahr neutral. 3.5 stattdessen neutral als &#8222;die Unentschlossenen&#8220; darstellen, die Ausrichtung f\u00fcr Charaktere, die ihren Instinkten folgen, denen eine starke \u00dcberzeugung fehlt, anstatt sich an neutralit\u00e4t zu halten. Die alte Version von neutral war vorhanden, aber implizierte, die weniger verbreitete Version zu sein. 4e schaffte neutral ab und ersetzte es durch unaligned, eine \u00e4hnliche Ausrichtung f\u00fcr Leute, die keine besondere Neigung hatten. 5e ist weitgehend dasselbe und beschreibt neutrale Charaktere als diejenigen, die &#8222;das tun, was zu der Zeit am besten erscheint&#8220;.\u00a0<\/p>\n<h3>&#8222;Chaotic Neutral&#8220; schm\u00e4ht Autorit\u00e4t<\/h3>\n<p>Chaotisch neutral in AD &amp;D kann der chaotischen Ausrichtung des urspr\u00fcnglichen D &amp; D am n\u00e4chsten kommen. Chaotische neutrale Kreaturen sch\u00e4tzen Zuf\u00e4lligkeit und Unordnung \u00fcber alles andere. Einem Trend folgend, macht 3.5 dies ein wenig umsetzbarer, indem chaotische neutrale Charaktere als &#8222;Freigeister&#8220; bezeichnet werden, reine Individualisten, die Autorit\u00e4t untergraben und Traditionen in Frage stellen. Chaotisch neutral in AD &amp;D kann der chaotischen Ausrichtung des urspr\u00fcnglichen D &amp; D am n\u00e4chsten kommen. Chaotische neutrale Kreaturen sch\u00e4tzen Zuf\u00e4lligkeit und Unordnung \u00fcber alles andere. Einem Trend folgend, macht 3.5 dies ein wenig umsetzbarer, indem chaotische neutrale Charaktere als &#8222;Freigeister&#8220; bezeichnet werden, reine Individualisten, die Autorit\u00e4t untergraben und Traditionen in Frage stellen.\u00a0<\/p>\n<h3>&#8222;Lawful Evil&#8220;\u00a0 versucht zu unterwerfen<\/h3>\n<p>So wie Chaos im urspr\u00fcnglichen D&amp;D manchmal als Ersatz f\u00fcr das B\u00f6se verwendet wurde, war das Gesetz so etwas wie ein Stellvertreter f\u00fcr das Gute. Mit der Einf\u00fchrung der sekund\u00e4ren Achse in AD&amp;D wurde das gesetzm\u00e4\u00dfige B\u00f6se geboren. Das urspr\u00fcngliche gesetzm\u00e4\u00dfige B\u00f6se beschreibt Kreaturen, die Recht und Ordnung respektieren, ohne wert auf Leben, Sch\u00f6nheit oder Freiheit zu legen. Diese Ausrichtung ist im Laufe der Jahre weitgehend unver\u00e4ndert geblieben, selbst in 4e, die nur eine b\u00f6se und chaotische b\u00f6se Ausrichtung hatte. Die b\u00f6se Ausrichtung von 4e besagt, dass &#8222;b\u00f6se Charaktere Regeln und Ordnung verwenden, um den pers\u00f6nlichen Gewinn zu maximieren&#8220;, was darauf hindeutet, dass diese Ausrichtung tats\u00e4chlich mehr mit dem rechtm\u00e4\u00dfigen B\u00f6sen als mit dem neutralen B\u00f6sen zu tun hat. 5e tritt, wie erwartet, in die Fu\u00dfstapfen der vorherigen Ausgabe und beschreibt rechtm\u00e4\u00dfige b\u00f6se Kreaturen, die andere innerhalb bestimmter Hierarchien und Systeme dominieren.\u00a0<\/p>\n<h3>&#8222;Neutral Evil&#8220; ist schlicht und einfach schlecht<\/h3>\n<p>So wie neutrales Gut ein nettes Sammelbecken f\u00fcr gute Menschen ist, ist neutrales B\u00f6ses eine Art generische b\u00f6se Ausrichtung. AD&amp; D sagt, dass b\u00f6se Kreaturen Gesetz und Chaos als \u00fcberfl\u00fcssig betrachten und stattdessen ihre Ziele ohne Bedenken verfolgen. 3.5 Das neutrale B\u00f6se ist in \u00e4hnlicher Weise Charakteren vorbehalten, die tun, was sie wollen, ohne einen Moralkodex oder eine bestimmte Neigung zur Zerst\u00f6rung. 4es b\u00f6se Ausrichtung ist wie neutrales und rechtm\u00e4\u00dfiges B\u00f6ses zusammengerollt, w\u00e4hrend 5e es als Catch-All-Evil-Ausrichtung verwendet, \u00e4hnlich wie fr\u00fchere Ausgaben.<\/p>\n<h3>&#8222;Chaotic Evil&#8220; wird alles f\u00fcr die Macht tun<\/h3>\n<p>Das chaotische B\u00f6se hat sich, wie die anderen chaotischen Ausrichtungen, im Laufe der Jahre etwas ver\u00e4ndert. Das chaotische B\u00f6se von AD &amp;D war unglaublich nihilistisch und erkl\u00e4rte, dass &#8222;das Leben keinen Wert hat&#8220;. 3.5 beseitigte diese eher philosophische Neigung und spielte stattdessen den Aspekt der Unabh\u00e4ngigkeit und Grausamkeit hoch. Das chaotische B\u00f6se wurde in 4e als fast eine noch schlimmere Version des B\u00f6sen dargestellt und zitierte die Tatsache, dass diese Philosophie die Weltanschauung einer Person so verzerrt, dass sie v\u00f6llig unvorhersehbar ist. 5e folgt der eher einfachen chaotischen b\u00f6sen Formel und beschreibt Kreaturen, die &#8222;mit willk\u00fcrlicher Gewalt handeln, angespornt von anderer Gier, Hass oder Blutrausch&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und Vorlieben. Seit 1974 verwendet Dungeons and Dragons ein Moralsystem, das als Alignment bekannt ist, um das Verhalten von Spieler- und Nichtspielercharakteren gleicherma\u00dfen abzubilden. In der urspr\u00fcnglichen Version existierte die Ausrichtung entlang einer einzigen Achse, von rechtm\u00e4\u00dfig [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[871],"tags":[],"class_list":["post-105169","post","type-post","status-publish","format-standard","hentry","category-tipps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die 9 Gesinnungen - RPG-Berlin.de<\/title>\n<meta name=\"description\" content=\"Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die 9 Gesinnungen - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rpg.berlin\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-29T13:45:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-30T10:12:20+00:00\" \/>\n<meta name=\"author\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thinkleblink\/Dalwick (Mirko)\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/\"},\"author\":{\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\"},\"headline\":\"Die 9 Gesinnungen\",\"datePublished\":\"2022-03-29T13:45:25+00:00\",\"dateModified\":\"2022-03-30T10:12:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/\"},\"wordCount\":1658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"articleSection\":[\"Tipps\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/\",\"name\":\"Die 9 Gesinnungen - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"datePublished\":\"2022-03-29T13:45:25+00:00\",\"dateModified\":\"2022-03-30T10:12:20+00:00\",\"description\":\"Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/tips\\\/die-9-gesinnungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die 9 Gesinnungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/person\\\/045b9a7c066eec7e24a84e4c6ec275ec\",\"name\":\"Thinkleblink\\\/Dalwick (Mirko)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g\",\"caption\":\"Thinkleblink\\\/Dalwick (Mirko)\"},\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die 9 Gesinnungen - RPG-Berlin.de","description":"Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/","og_locale":"de_DE","og_type":"article","og_title":"Die 9 Gesinnungen - RPG-Berlin.de","og_description":"Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und..","og_url":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/","og_site_name":"RPG-Berlin.de","article_publisher":"https:\/\/www.facebook.com\/rpg.berlin\/","article_published_time":"2022-03-29T13:45:25+00:00","article_modified_time":"2022-03-30T10:12:20+00:00","author":"Thinkleblink\/Dalwick (Mirko)","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thinkleblink\/Dalwick (Mirko)"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/#article","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/"},"author":{"name":"Thinkleblink\/Dalwick (Mirko)","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec"},"headline":"Die 9 Gesinnungen","datePublished":"2022-03-29T13:45:25+00:00","dateModified":"2022-03-30T10:12:20+00:00","mainEntityOfPage":{"@id":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/"},"wordCount":1658,"commentCount":0,"publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"articleSection":["Tipps"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/","url":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/","name":"Die 9 Gesinnungen - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"datePublished":"2022-03-29T13:45:25+00:00","dateModified":"2022-03-30T10:12:20+00:00","description":"Dungeons and Dragons verwendet seit langem neun Gesinnungen, um die Charakterphilosophie zu beschreiben, jede mit ihren eigenen Werten und..","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/tips\/die-9-gesinnungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Die 9 Gesinnungen"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]},{"@type":"Person","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/person\/045b9a7c066eec7e24a84e4c6ec275ec","name":"Thinkleblink\/Dalwick (Mirko)","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/78efc02aad7bd1be5de2324a736b341a96b84618f825d5700740f3ff04daa22f?s=96&d=mm&r=g","caption":"Thinkleblink\/Dalwick (Mirko)"},"url":"https:\/\/rpg-berlin.de\/rpg\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4p3r6-rmh","_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/105169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/comments?post=105169"}],"version-history":[{"count":0,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts\/105169\/revisions"}],"wp:attachment":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/media?parent=105169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories?post=105169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/tags?post=105169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}