{"id":222,"count":13,"description":"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen nicht mehr existent.","link":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/","name":"The Ragtag Bunch (inaktiv)","slug":"gruppe5","taxonomy":"category","parent":13,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Ragtag Bunch (inaktiv) Archive - RPG-Berlin.de<\/title>\n<meta name=\"description\" content=\"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen existiert die Gruppe nicht mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Ragtag Bunch (inaktiv) Archive - RPG-Berlin.de\" \/>\n<meta property=\"og:description\" content=\"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen existiert die Gruppe nicht mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rpg-berlin.de\/rpg\/D&amp;D5e\/abenteuer\/gruppe5\/\" \/>\n<meta property=\"og:site_name\" content=\"RPG-Berlin.de\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/D&D5e\\\/abenteuer\\\/gruppe5\\\/\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/D&D5e\\\/abenteuer\\\/gruppe5\\\/\",\"name\":\"The Ragtag Bunch (inaktiv) Archive - RPG-Berlin.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\"},\"description\":\"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen existiert die Gruppe nicht mehr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/D&D5e\\\/abenteuer\\\/gruppe5\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/D&D5e\\\/abenteuer\\\/gruppe5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abenteuer\",\"item\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/D&D5e\\\/abenteuer\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"The Ragtag Bunch (inaktiv)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#website\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"name\":\"RPG-Berlin.de\",\"description\":\"Blog mehrerer D&amp;D 5e Rollenspielergruppen\",\"publisher\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#organization\",\"name\":\"RPG-Berlin.de\",\"url\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/rpg-berlin.de\\\/rpg\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/cropped-Ogma4.png?fit=95%2C95&ssl=1\",\"width\":95,\"height\":95,\"caption\":\"RPG-Berlin.de\"},\"image\":{\"@id\":\"https:\\\/\\\/rpg-berlin.de\\\/rpg\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rpg.berlin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Ragtag Bunch (inaktiv) Archive - RPG-Berlin.de","description":"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen existiert die Gruppe nicht mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/","og_locale":"de_DE","og_type":"article","og_title":"The Ragtag Bunch (inaktiv) Archive - RPG-Berlin.de","og_description":"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen existiert die Gruppe nicht mehr.","og_url":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/","og_site_name":"RPG-Berlin.de","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/","url":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/","name":"The Ragtag Bunch (inaktiv) Archive - RPG-Berlin.de","isPartOf":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#website"},"description":"Hier sind alle Zusammenfassungen von der Gruppe: The Ragtag Bunch. Seit dem 13.10.2014. Inzwischen existiert die Gruppe nicht mehr.","breadcrumb":{"@id":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/gruppe5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rpg-berlin.de\/rpg\/"},{"@type":"ListItem","position":2,"name":"Abenteuer","item":"https:\/\/rpg-berlin.de\/rpg\/D&D5e\/abenteuer\/"},{"@type":"ListItem","position":3,"name":"The Ragtag Bunch (inaktiv)"}]},{"@type":"WebSite","@id":"https:\/\/rpg-berlin.de\/rpg\/#website","url":"https:\/\/rpg-berlin.de\/rpg\/","name":"RPG-Berlin.de","description":"Blog mehrerer D&amp;D 5e Rollenspielergruppen","publisher":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rpg-berlin.de\/rpg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rpg-berlin.de\/rpg\/#organization","name":"RPG-Berlin.de","url":"https:\/\/rpg-berlin.de\/rpg\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rpg-berlin.de\/rpg\/wp-content\/uploads\/2019\/05\/cropped-Ogma4.png?fit=95%2C95&ssl=1","width":95,"height":95,"caption":"RPG-Berlin.de"},"image":{"@id":"https:\/\/rpg-berlin.de\/rpg\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rpg.berlin\/"]}]}},"_links":{"self":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories\/222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/categories\/13"}],"wp:post_type":[{"href":"https:\/\/rpg-berlin.de\/rpg\/wp-json\/wp\/v2\/posts?categories=222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}